{"id":53752,"date":"2023-07-07T11:24:12","date_gmt":"2023-07-07T09:24:12","guid":{"rendered":"https:\/\/www.moas.eu\/?p=53752"},"modified":"2023-07-07T11:27:01","modified_gmt":"2023-07-07T09:27:01","slug":"i-nuovi-strumenti-digitali-e-le-opportunita-per-supportare-le-cause-nelle-quali-credi","status":"publish","type":"post","link":"https:\/\/www.moas.eu\/it\/i-nuovi-strumenti-digitali-e-le-opportunita-per-supportare-le-cause-nelle-quali-credi\/","title":{"rendered":"I nuovi strumenti digitali e le opportunit\u00e0 per supportare le cause nelle quali credi"},"content":{"rendered":"<p><span data-contrast=\"auto\">Ciascuno di noi crede fortemente in determinate cause politiche, umanitarie o ambientali e nella necessit\u00e0 di sostenere e implementare i diritti che dovrebbero essere garantiti a qualsiasi persona nel mondo. Attivisti e donatori, con il loro tempo e con le loro risorse economiche, permettono alle organizzazioni no profit e alle onlus, di portare avanti il proprio lavoro e di fornire un piccolo tassello per l\u2019avanzamento di queste cause.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">I nuovi strumenti digitali, per\u00f2, offrono la possibilit\u00e0 di fare molto di pi\u00f9. Per coloro i quali non hanno le risorse necessarie in termini di tempo e di denaro o vogliono incrementare il loro sostegno all\u2019organizzazione che si impegna per una causa che hanno a cuore, oggi ci sono numerose opportunit\u00e0.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">CSR &#8211; Corporate Social Responsability<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">La responsabilit\u00e0 sociale d\u2019impresa \u00e8 il principio secondo cui proprietari di impresa e amministratori, dipendenti e clienti, insieme possono creare un valore condiviso. L\u2019attenzione e la consapevolezza verso le questioni sociali e ambientali possono trasformarsi in un impegno a restituire alla societ\u00e0 il valore che si ricava dal business. Se sei a capo di un\u2019impresa puoi far parte di una piattaforma di CSR (Corporate Social Responsability) attraverso la quale coinvolgere i dipendenti a sostegno di una causa sociale, trasformando i tuoi buoni propositi in un\u2019azione proattiva di welfare aziendale.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Buoni per i servizi welfare<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">La tua impresa pu\u00f2 inoltrare scegliere di corrispondere ai dipendenti dei buoni per i servizi welfare. Tra i servizi welfare \u00e8 possibile far aggiungere l\u2019organizzazione umanitaria che pi\u00f9 ti sta a cuore. In questo modo il dipendente pu\u00f2 decidere di devolvere la somma indicata all\u2019organizzazione.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Charity Cashback<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Facendo acquisti online tramite Paypal o su alcuni e-commerce potrai attivare automaticamente la donazione per l\u2019organizzazione che vuoi sostenere. Potrai donare 1 euro o potrai far s\u00ec che il fornitore doni una percentuale del tuo acquisto all\u2019organizzazione senza alcun addebito aggiuntivo. Attraverso i social potrai condividere il tuo gesto diffondendo il link della campagna, diventando un fundraiser e aiutandoci ad arrivare a sempre pi\u00f9 persone.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">E-commerce solidale<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">In cambio di una piccola donazione potrai avere gadgets e merchandising online o potrai richiedere i nostri prodotti da inserire sul tuo e-commerce. Puoi trovare il merchandise MOAS su <a href=\"https:\/\/worthwearing.org\/store\/moas-migrant-offshore-aid-station\">https:\/\/worthwearing.org\/store\/moas-migrant-offshore-aid-station<\/a>.<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Raccolte fondi\u00a0<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Puoi attivare una campagna di raccolta fondi in occasione del tuo compleanno, della tua laurea, del tuo matrimonio o in qualsiasi periodo dell\u2019anno su <a href=\"https:\/\/www.moasfundraising.com\/\">https:\/\/www.moasfundraising.com\/<\/a> e sulla nostra pagina Facebook. Puoi organizzare anche una raccolta fondi fisica, crea un evento, una cena di beneficenza o in occasione di un evento gi\u00e0 in programma, coinvolgi i tuoi amici e colleghi e insieme, ciascuno con un piccolo gesto, potrete raccogliete denaro per l\u2019organizzazione scelta dando un valore aggiunto al momento che avete condiviso insieme. Trovare sponsorizzazioni in occasione di eventi sportivi, tra le aziende che conosci o nel tuo business \u00e8 un altro buon sistema per raccogliere fondi senza spendere nulla.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Tasse<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Molti Paesi offrono la possibilit\u00e0 di devolver parte delle tasse a organizzazioni registrate a livello locale o di partecipare a programmi che permettono di sostenere alle organizzazioni no profit tramite finanziamenti pubblici.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">MOAS partecipa in Italia al programma Cinque per Mille , inoltre ha regime fiscale negli Stati Uniti, Regno Unito, Germania e Malta. Per maggiori informazioni: <a href=\"https:\/\/www.moas.eu\/it\/5x1000\/\">https:\/\/www.moas.eu\/it\/5&#215;1000\/<\/a>.<\/span><\/p>\n<p><b><span data-contrast=\"auto\">App\/Browser<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Molti giochi, app e browser devolvono parte dei ricavi pubblicitari ad organizzazioni benefiche. Alcune di queste hanno creato i loro giochi o app nei quali \u00e8 sufficiente giocare per generare fondi. Tutti questi meccanismi funzionano in maniera simile: pi\u00f9 si utilizza l\u2019app\/sito pi\u00f9 ricavi vengono generati e trasformati in donazioni per la causa. Chiedi all\u2019organizzazione che sostieni di essere inserita nell\u2019elenco delle organizzazioni benefiche che possono usufruirne.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Promozione\/Advocacy<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Non sottovalutare il potere della community online. Ogni organizzazione cerca di allargare il proprio raggio di azione e trovare nuovi sostenitori tramite i social media. Seguire pagine di organizzazioni come MOAS e condividere le loro petizioni di fundraising, il blog o gli aggiornamenti sulle operazioni pu\u00f2 aumentare enormemente il loro impatto, e farli conoscere a possibili nuovi donatori. Un semplice gesto come quello di condividere un articolo diventa un vero atto di solidariet\u00e0. Puoi anche candidare l\u2019organizzazione che hai scelto a premi e programmi che possano assicurarle un riconoscimento, un finanziamento o maggiore visibilit\u00e0.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Lasciti testamentari<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Se in questo momento non sei in grado di fare una donazione, ma pensi di voler lasciare qualcosa alla tua organizzazione preferita in tua memoria, allora il lascito testamentario potrebbe fare per te. Per maggiori informazioni contattaci a <a href=\"mailto:info@moas.eu\">info@moas.eu<\/a>.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Per seguire i contenuti di MOAS visita le nostre pagine <a href=\"https:\/\/www.facebook.com\/migrantoffshoreaidstation\/\">Facebook<\/a>, <a href=\"https:\/\/twitter.com\/i\/flow\/login?redirect_after_login=%2Fmoas_it\">Twitter<\/a>, <a href=\"https:\/\/www.instagram.com\/moas_eu\/\">Instagram<\/a>, <a href=\"https:\/\/www.linkedin.com\/company\/migrant-offshore-aid-station?originalSubdomain=mt\">LinkedIn<\/a> e iscriviti alla nostra <a href=\"https:\/\/moas.us11.list-manage.com\/subscribe\/post?u=d6bc6708edc59f5d737ddac41&amp;id=ecfda43cc0\">newsletter<\/a>.\u00a0<\/strong><strong>Per fare una donazione ti basta cliccare su <a href=\"https:\/\/www.moas.eu\/it\/dona\/\">https:\/\/www.moas.eu\/it\/dona\/<\/a>.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ciascuno di noi crede fortemente in determinate cause politiche, umanitarie o ambientali e nella necessit\u00e0 di sostenere e implementare i diritti che dovrebbero essere garantiti &#8230; <a title=\"I nuovi strumenti digitali e le opportunit\u00e0 per supportare le cause nelle quali credi\" class=\"read-more\" href=\"https:\/\/www.moas.eu\/it\/i-nuovi-strumenti-digitali-e-le-opportunita-per-supportare-le-cause-nelle-quali-credi\/\" aria-label=\"Per saperne di pi\u00f9 su I nuovi strumenti digitali e le opportunit\u00e0 per supportare le cause nelle quali credi\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":53740,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"nf_dc_page":"","footnotes":""},"categories":[19],"tags":[],"class_list":["post-53752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-it","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","resize-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I nuovi strumenti digitali e le opportunit\u00e0 per supportare le cause nelle quali credi - MOAS<\/title>\n<meta name=\"description\" content=\"Il finanziamento delle organizzazioni no profit e alle onlus si basa principalmente sul contributo di donatori e attivisti, in molti modi diversi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.moas.eu\/it\/i-nuovi-strumenti-digitali-e-le-opportunita-per-supportare-le-cause-nelle-quali-credi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I nuovi strumenti digitali e le opportunit\u00e0 per supportare le cause nelle quali credi - MOAS\" \/>\n<meta property=\"og:description\" content=\"Il finanziamento delle organizzazioni no profit e alle onlus si basa principalmente sul contributo di donatori e attivisti, in molti modi diversi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.moas.eu\/it\/i-nuovi-strumenti-digitali-e-le-opportunita-per-supportare-le-cause-nelle-quali-credi\/\" \/>\n<meta property=\"og:site_name\" content=\"MOAS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/migrantoffshoreaidstation\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-07T09:24:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-07T09:27:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.moas.eu\/wp-content\/uploads\/blog10_image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christina Lejman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@moas_eu\" \/>\n<meta name=\"twitter:site\" content=\"@moas_eu\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christina Lejman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/i-nuovi-strumenti-digitali-e-le-opportunita-per-supportare-le-cause-nelle-quali-credi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/i-nuovi-strumenti-digitali-e-le-opportunita-per-supportare-le-cause-nelle-quali-credi\\\/\"},\"author\":{\"name\":\"Christina Lejman\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/person\\\/be1af883120febb082823c3c74304c69\"},\"headline\":\"I nuovi strumenti digitali e le opportunit\u00e0 per supportare le cause nelle quali credi\",\"datePublished\":\"2023-07-07T09:24:12+00:00\",\"dateModified\":\"2023-07-07T09:27:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/i-nuovi-strumenti-digitali-e-le-opportunita-per-supportare-le-cause-nelle-quali-credi\\\/\"},\"wordCount\":811,\"publisher\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/i-nuovi-strumenti-digitali-e-le-opportunita-per-supportare-le-cause-nelle-quali-credi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/blog10_image.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/i-nuovi-strumenti-digitali-e-le-opportunita-per-supportare-le-cause-nelle-quali-credi\\\/\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/i-nuovi-strumenti-digitali-e-le-opportunita-per-supportare-le-cause-nelle-quali-credi\\\/\",\"name\":\"I nuovi strumenti digitali e le opportunit\u00e0 per supportare le cause nelle quali credi - MOAS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/i-nuovi-strumenti-digitali-e-le-opportunita-per-supportare-le-cause-nelle-quali-credi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/i-nuovi-strumenti-digitali-e-le-opportunita-per-supportare-le-cause-nelle-quali-credi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/blog10_image.jpg\",\"datePublished\":\"2023-07-07T09:24:12+00:00\",\"dateModified\":\"2023-07-07T09:27:01+00:00\",\"description\":\"Il finanziamento delle organizzazioni no profit e alle onlus si basa principalmente sul contributo di donatori e attivisti, in molti modi diversi.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/i-nuovi-strumenti-digitali-e-le-opportunita-per-supportare-le-cause-nelle-quali-credi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.moas.eu\\\/it\\\/i-nuovi-strumenti-digitali-e-le-opportunita-per-supportare-le-cause-nelle-quali-credi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/i-nuovi-strumenti-digitali-e-le-opportunita-per-supportare-le-cause-nelle-quali-credi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/blog10_image.jpg\",\"contentUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/blog10_image.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/i-nuovi-strumenti-digitali-e-le-opportunita-per-supportare-le-cause-nelle-quali-credi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I nuovi strumenti digitali e le opportunit\u00e0 per supportare le cause nelle quali credi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/\",\"name\":\"MOAS\",\"description\":\"MOAS\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.moas.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\",\"name\":\"MOAS\",\"alternateName\":\"Migrant Offshore Aid Station\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/moas-logo-oval.png\",\"contentUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/moas-logo-oval.png\",\"width\":793,\"height\":354,\"caption\":\"MOAS\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/migrantoffshoreaidstation\",\"https:\\\/\\\/x.com\\\/moas_eu\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/migrant-offshore-aid-station\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZHcDS7ePIBW66d3KvX2K0Q\",\"https:\\\/\\\/www.instagram.com\\\/moas_eu\\\/?hl=en\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/person\\\/be1af883120febb082823c3c74304c69\",\"name\":\"Christina Lejman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"caption\":\"Christina Lejman\"},\"url\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/author\\\/clejman\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I nuovi strumenti digitali e le opportunit\u00e0 per supportare le cause nelle quali credi - MOAS","description":"Il finanziamento delle organizzazioni no profit e alle onlus si basa principalmente sul contributo di donatori e attivisti, in molti modi diversi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.moas.eu\/it\/i-nuovi-strumenti-digitali-e-le-opportunita-per-supportare-le-cause-nelle-quali-credi\/","og_locale":"it_IT","og_type":"article","og_title":"I nuovi strumenti digitali e le opportunit\u00e0 per supportare le cause nelle quali credi - MOAS","og_description":"Il finanziamento delle organizzazioni no profit e alle onlus si basa principalmente sul contributo di donatori e attivisti, in molti modi diversi.","og_url":"https:\/\/www.moas.eu\/it\/i-nuovi-strumenti-digitali-e-le-opportunita-per-supportare-le-cause-nelle-quali-credi\/","og_site_name":"MOAS","article_publisher":"https:\/\/www.facebook.com\/migrantoffshoreaidstation","article_published_time":"2023-07-07T09:24:12+00:00","article_modified_time":"2023-07-07T09:27:01+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.moas.eu\/wp-content\/uploads\/blog10_image.jpg","type":"image\/jpeg"}],"author":"Christina Lejman","twitter_card":"summary_large_image","twitter_creator":"@moas_eu","twitter_site":"@moas_eu","twitter_misc":{"Scritto da":"Christina Lejman","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.moas.eu\/it\/i-nuovi-strumenti-digitali-e-le-opportunita-per-supportare-le-cause-nelle-quali-credi\/#article","isPartOf":{"@id":"https:\/\/www.moas.eu\/it\/i-nuovi-strumenti-digitali-e-le-opportunita-per-supportare-le-cause-nelle-quali-credi\/"},"author":{"name":"Christina Lejman","@id":"https:\/\/www.moas.eu\/#\/schema\/person\/be1af883120febb082823c3c74304c69"},"headline":"I nuovi strumenti digitali e le opportunit\u00e0 per supportare le cause nelle quali credi","datePublished":"2023-07-07T09:24:12+00:00","dateModified":"2023-07-07T09:27:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.moas.eu\/it\/i-nuovi-strumenti-digitali-e-le-opportunita-per-supportare-le-cause-nelle-quali-credi\/"},"wordCount":811,"publisher":{"@id":"https:\/\/www.moas.eu\/#organization"},"image":{"@id":"https:\/\/www.moas.eu\/it\/i-nuovi-strumenti-digitali-e-le-opportunita-per-supportare-le-cause-nelle-quali-credi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/blog10_image.jpg","articleSection":["Blog"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.moas.eu\/it\/i-nuovi-strumenti-digitali-e-le-opportunita-per-supportare-le-cause-nelle-quali-credi\/","url":"https:\/\/www.moas.eu\/it\/i-nuovi-strumenti-digitali-e-le-opportunita-per-supportare-le-cause-nelle-quali-credi\/","name":"I nuovi strumenti digitali e le opportunit\u00e0 per supportare le cause nelle quali credi - MOAS","isPartOf":{"@id":"https:\/\/www.moas.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.moas.eu\/it\/i-nuovi-strumenti-digitali-e-le-opportunita-per-supportare-le-cause-nelle-quali-credi\/#primaryimage"},"image":{"@id":"https:\/\/www.moas.eu\/it\/i-nuovi-strumenti-digitali-e-le-opportunita-per-supportare-le-cause-nelle-quali-credi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/blog10_image.jpg","datePublished":"2023-07-07T09:24:12+00:00","dateModified":"2023-07-07T09:27:01+00:00","description":"Il finanziamento delle organizzazioni no profit e alle onlus si basa principalmente sul contributo di donatori e attivisti, in molti modi diversi.","breadcrumb":{"@id":"https:\/\/www.moas.eu\/it\/i-nuovi-strumenti-digitali-e-le-opportunita-per-supportare-le-cause-nelle-quali-credi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.moas.eu\/it\/i-nuovi-strumenti-digitali-e-le-opportunita-per-supportare-le-cause-nelle-quali-credi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.moas.eu\/it\/i-nuovi-strumenti-digitali-e-le-opportunita-per-supportare-le-cause-nelle-quali-credi\/#primaryimage","url":"https:\/\/www.moas.eu\/wp-content\/uploads\/blog10_image.jpg","contentUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/blog10_image.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/www.moas.eu\/it\/i-nuovi-strumenti-digitali-e-le-opportunita-per-supportare-le-cause-nelle-quali-credi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.moas.eu\/it\/"},{"@type":"ListItem","position":2,"name":"I nuovi strumenti digitali e le opportunit\u00e0 per supportare le cause nelle quali credi"}]},{"@type":"WebSite","@id":"https:\/\/www.moas.eu\/#website","url":"https:\/\/www.moas.eu\/","name":"MOAS","description":"MOAS","publisher":{"@id":"https:\/\/www.moas.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.moas.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.moas.eu\/#organization","name":"MOAS","alternateName":"Migrant Offshore Aid Station","url":"https:\/\/www.moas.eu\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.moas.eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/moas-logo-oval.png","contentUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/moas-logo-oval.png","width":793,"height":354,"caption":"MOAS"},"image":{"@id":"https:\/\/www.moas.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/migrantoffshoreaidstation","https:\/\/x.com\/moas_eu","https:\/\/www.linkedin.com\/company\/migrant-offshore-aid-station","https:\/\/www.youtube.com\/channel\/UCZHcDS7ePIBW66d3KvX2K0Q","https:\/\/www.instagram.com\/moas_eu\/?hl=en"]},{"@type":"Person","@id":"https:\/\/www.moas.eu\/#\/schema\/person\/be1af883120febb082823c3c74304c69","name":"Christina Lejman","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","caption":"Christina Lejman"},"url":"https:\/\/www.moas.eu\/it\/author\/clejman\/"}]}},"_links":{"self":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/53752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/comments?post=53752"}],"version-history":[{"count":5,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/53752\/revisions"}],"predecessor-version":[{"id":53792,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/53752\/revisions\/53792"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/media\/53740"}],"wp:attachment":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/media?parent=53752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/categories?post=53752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/tags?post=53752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}