{"id":52313,"date":"2022-12-27T09:00:34","date_gmt":"2022-12-27T09:00:34","guid":{"rendered":"https:\/\/www.moas.eu\/?p=52313"},"modified":"2022-12-28T11:43:06","modified_gmt":"2022-12-28T11:43:06","slug":"2022-che-anno-e-stato","status":"publish","type":"post","link":"https:\/\/www.moas.eu\/it\/2022-che-anno-e-stato\/","title":{"rendered":"2022&#8230; Che anno \u00e8 stato!"},"content":{"rendered":"<p>Il 2022 \u00e8 trascorso ed \u00e8 tempo di riflettere sulle attivit\u00e0 e sui progetti realizzati da MOAS in tutto il mondo. \u00c8 stato un periodo impegnativo ma produttivo e ricco di successi. Le nostre operazioni hanno raggiunto alcune delle comunit\u00e0 pi\u00f9 vulnerabili in aree diverse e contiamo di continuare su questa strada anche nel 2023! Di seguito troverete una panoramica dei progetti realizzati l&#8217;anno scorso e del loro impatto.<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>App MOAS<\/strong><\/span><\/p>\n<p>All&#8217;inizio del 2022 MOAS ha rilasciato la sua nuova App, disponibile per il download su <a href=\"https:\/\/apps.apple.com\/dk\/app\/moas-eu\/id1591027788\">App Store<\/a> e <a href=\"https:\/\/play.google.com\/store\/apps\/details?id=eu.moas.app\">Google Play<\/a>. Attraverso un&#8217;interfaccia molto semplice e facile da navigare, l&#8217;app \u00e8 il modo migliore per scoprire le missioni e le iniziative di MOAS in tutto il mondo e fare una donazione per sostenere le comunit\u00e0 pi\u00f9 vulnerabili nelle aree di crisi. Utilizzando l&#8217;app l&#8217;utente pu\u00f2:<\/p>\n<ul>\n<li>Scoprire i progetti di MOAS e trovare informazioni su ciascuno di essi<\/li>\n<li>Accedere ai blog e agli articoli su migrazioni, tendenze umanitarie e iniziative di sviluppo.<\/li>\n<li>Accedere alla sezione fotografica e condividere le proprie esperienze nella sezione Comunit\u00e0<\/li>\n<li>Effettuare una donazione per sostenere un progetto. L&#8217;applicazione mobile consente ai donatori di scegliere il progetto che pi\u00f9 li appassiona.<\/li>\n<li>Accedere ed esplorare i nostri canali di social media e diventare un follower<\/li>\n<li>Leggere e firmare l&#8217;appello per l&#8217;implementazione di #VieSicureELegali di migrazione.<\/li>\n<\/ul>\n<p>Con l&#8217;app MOAS, donare \u00e8 molto semplice. Ad esempio, con 10 euro si pu\u00f2 acquistare una borsa da lancio salvavita, un&#8217;attrezzatura fondamentale per la formazione sulla sicurezza in acqua. 37 euro permettono di curare la malnutrizione di un bambino denutrito in Yemen o in Somalia. Ogni donazione \u00e8 importante, piccola o grande che sia.<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>MOAS in Ucraina<\/strong><\/span><\/p>\n<p>L\u2019obiettivo di MOAS \u00e8 quello di rispondere in modo rapido ed efficiente alle crisi emergenti nel mondo. Per questo motivo, nel febbraio 2022 MOAS ha avviato una missione medica in Ucraina per portare aiuti medici d&#8217;emergenza e medicinali alle popolazioni colpite dal conflitto. Si stima che tra gli 8 e i 12 milioni di persone siano state sfollate e tagliate fuori dai normali servizi sanitari del Paese. Inoltre, il danneggiamento diretto o la chiusura di circa 1.000 strutture sanitarie e di diverse migliaia di personale medico ha lasciato le\u00a0infrastrutture mediche a pezzi e ha reso l&#8217;accesso alle cure di base quasi impossibile.<\/p>\n<p>Grazie a una flotta di 27 veicoli di pronto intervento completamente attrezzati, il nostro team di paramedici, medici e infermieri ha curato migliaia di pazienti attraverso il nostro lavoro di assistenza in caso di traumi e di distribuzione degli aiuti.<\/p>\n<p><span style=\"text-decoration: underline;\">In cosa consiste la missione:\u00a0<\/span><\/p>\n<ul>\n<li>MOAS opera nel Paese con una flotta di veicoli di pronto intervento con capacit\u00e0 diverse, tra cui unit\u00e0 di base per squadre mediche mobili, veicoli per il trasporto di pazienti in condizioni critiche, veicoli per il rifornimento e la logistica, veicoli per la distribuzione di personale e cos\u00ec via.<\/li>\n<li>Questi veicoli sono equipaggiati con forniture mediche portatili, scorte di farmaci e attrezzature all&#8217;avanguardia che consentono alle nostre squadre di fornire supporto vitale di base e avanzato, interventi clinici, trasporto e triage, nonch\u00e9 interventi di assistenza a pazienti in condizioni critiche pi\u00f9 estesi, se e quando necessario.<\/li>\n<li>Ogni veicolo \u00e8 presidiato da due medici abilitati e da un autista\/mediatore culturale locale.<\/li>\n<li>Il maggior numero possibile di pazienti viene controllato, trattato e dimesso sul campo, ma i casi pi\u00f9 gravi e ad alto rischio vengono trasferiti dai team MOAS in veicoli per il trasporto di pazienti che necessitano\u00a0 livelli pi\u00f9 alti di assistenza, fuori dalla linea del fronte, per interventi chirurgici e ulteriori cure.<\/li>\n<\/ul>\n<p>Utilizzando questo modello, il nostro team ha gi\u00e0 curato e dimesso migliaia di pazienti sul campo e ha trasportato quelli in condizioni pi\u00f9 critiche in centri specializzati. I pazienti trasferiti con i traumi pi\u00f9 gravi includono bambini a partire da 11 anni, donne e uomini di tutte le et\u00e0, compresi gli anziani e gli infermi. MOAS lavora con medici tattici esperti in medicina sul campo per garantire che ogni paziente sia trattato con interventi completi, rapidi e mirati, progettati per ridurre al minimo l&#8217;impatto del danno e salvare il maggior numero possibile di vite.<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>Formazione e riduzione del rischio di catastrofi &#8211; DRR<\/strong><\/span><\/p>\n<p><span style=\"text-decoration: underline;\">Sicurezza contro le inondazioni e l&#8217;acqua <\/span><\/p>\n<p>Dall&#8217;inizio del 2019 MOAS affianca i partner locali nella realizzazione di corsi di formazione unici e innovativi sulla sicurezza in acqua. Il team di MOAS mette a disposizione la propria esperienza per la formazione e la fornitura di attrezzature ai volontari della comunit\u00e0 di rifugiati e dalla comunit\u00e0 locale ospitante. Tali corsi di formazione creano resilienza contro i rischi legati all&#8217;acqua &#8211; come le inondazioni e i monsoni &#8211; ma supporta anche l&#8217;autosviluppo, non solo fornendo ai volontari competenze e attrezzature, ma anche migliorando le capacit\u00e0 di leadership e il lavoro di squadra. Questi programmi, inoltre, forniscono mezzi di sostentamento ai sarti locali che producono i nostri equipaggiamenti di sicurezza e che ricevono una formazione nell&#8217;ambito del progetto. Quest&#8217;anno, grazie ai nostri incredibili partner globali, MOAS ha facilitato e sostenuto la formazione di oltre 1375 rifugiati e 28 rappresentanti della comunit\u00e0 ospitante; ogni volontario ha ricevuto una borsa da lancio progettata e realizzata localmente da MOAS.<\/p>\n<p><span style=\"text-decoration: underline;\">Sicurezza antincendio <\/span><\/p>\n<p>Per rispondere all&#8217;aumento della frequenza e della gravit\u00e0 dei focolai di incendio nei campi profughi affollati, il nostro team ha sostenuto lo sviluppo di un progetto di riduzione del rischio di disastri (DRR) unico nel suo genere per la sicurezza e la risposta agli incendi. L\u2019iniziativa si concentra su tre elementi: la mappatura del rischio, la formazione per la prima risposta e la prototipazione e produzione di attrezzature antincendio.<\/p>\n<p>Il modello di mappatura dei rischi consente ai nostri esperti tecnici di dare consigli sulla gestione del campo e sulle aree di particolare rischio e di sviluppare strategie di risposta in base a ciascun contesto, mentre la formazione fornisce competenze e tecniche di attuazione delle strategie di intervento ai volontari della comunit\u00e0. Infine, il team ha prototipato diverse attrezzature specifiche per l&#8217;uso nel contesto del campo, tra cui tuk-tuk antincendio e zaini. Con il sostegno di donatori internazionali e partner INGO, il nostro team ha formato 2662 volontari e ha contribuito a produrre 45 unit\u00e0 antincendio tuk-tuk e a procurare e distribuire 341 pompe d\u2019acqua, mentre 533 serbatoi d&#8217;acqua sono stati collocati nei campi profughi. Questo programma di sicurezza antincendio continuer\u00e0 nel 2023, con sviluppi ancora pi\u00f9 interessanti.<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>Yemen e Somalia<\/strong><\/span><\/p>\n<p>Dall&#8217;inizio del 2019 MOAS fornisce assistenza farmaceutica e cure specialistiche contro la malnutrizione ai bambini vulnerabili dello Yemen e della Somalia. In questi Paesi, paralizzati da crisi politiche esacerbate da catastrofi ambientali, l&#8217;insicurezza alimentare \u00e8 ai massimi storici, con carestie, siccit\u00e0 e malnutrizione che mettono a rischio milioni di vite. Quest&#8217;anno non \u00e8 stato diverso e, grazie al continuo sostegno dei partner Edesia, Action Medeor, ADRA Yemen e IMC, siamo riusciti a distribuire oltre 80 tonnellate di alimenti terapeutici pronti all&#8217;uso a bambini affetti da malnutrizione.<\/p>\n<p>Con il vostro aiuto, continueremo a far arrivare questi aiuti salvavita a chi ne ha pi\u00f9 bisogno.<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>Malta<\/strong><\/span><\/p>\n<p>A Malta, MOAS \u00e8 impegnato a sostenere le comunit\u00e0 di persone migranti e rifugiati presenti sull&#8217;isola, fornendo assistenza per le sfide che si trovano ad affrontare nella loro vita quotidiana, piccole o grandi che siano. Nel fare ci\u00f2, gestiamo diversi progetti che vanno dalle iniziative educative all&#8217;integrazione e all&#8217;assistenza ospedaliera.<\/p>\n<p>Nel 2022 MOAS ha lanciato il progetto &#8220;Integrazione attraverso l&#8217;educazione e l&#8217;informazione&#8221;, per stimolare la collaborazione tra le organizzazioni di volontariato e coordinare sessioni ed eventi rivolti alla comunit\u00e0 di richiedenti asilo sull&#8217;isola, per favorire l&#8217;integrazione e l&#8217;indipendenza. Il nostro team leader, supportato da uno staff di straordinari volontari, ha organizzato corsi d&#8217;arte, visite guidate, passeggiate nella natura e altre interessanti iniziative, coinvolgendo la comunit\u00e0 di rifugiati e le parti interessate per favorire l&#8217;impegno della comunit\u00e0 e implementare l&#8217;integrazione.<\/p>\n<p>Un altro progetto importante \u00e8 la creazione di centri di informazione e apprendimento nei campi profughi di Hal Far. MOAS intende creare spazi multifunzionali presso i Centri di accoglienza: tali spazi sono in fase finale di ristrutturazione e saranno dotati di risorse didattiche come computer, libri e altri strumenti di apprendimento e saranno utilizzati dai residenti dei centri per l&#8217;istruzione formale, le attivit\u00e0 di formazione come i corsi di lingua, lo studio in autonomia e svolgere attivit\u00e0 essenziali come la scrittura del CV, la ricerca di lavoro e la registrazione ai servizi online.<\/p>\n<p>\u00c8 in corso anche un&#8217;iniziativa di apprendimento a distanza, un progetto attraverso il quale MOAS fornisce tablet e modem con connessione a Internet a rifugiati e richiedenti asilo che sono studenti adulti a tempo pieno per sostenerli negli studi.<\/p>\n<p>Con il progetto Family Hosting &amp; Sponsorship di MOAS, le persone migranti vengono messe in contatto con famiglie residenti a Malta che desiderano sostenerle nel proseguimento degli studi. Attraverso questi progetti, miriamo a facilitare l&#8217;integrazione e l&#8217;inclusione a lungo termine e a sostenere lo sviluppo e l&#8217;indipendenza dei partecipanti, offrendo sostegno sociale, orientamento e interazioni familiari.<\/p>\n<p>Dopo la sospensione causata dalla pandemia di Covid-19, nel 2022 MOAS ha ripreso le visite in ospedale alle persone migranti evacuate medicalmente dalle navi SAR e sottoposte a cure, per garantire che si sentissero supportate e avessero accesso ai servizi. Abbiamo anche fornito loro articoli per l&#8217;assistenza di base (igiene, biancheria) per facilitare il recupero. Inoltre, MOAS ha contribuito a coordinare l&#8217;assistenza a domicilio per le persone che necessitano di ulteriore supporto una volta tornate a casa dopo il ricovero.<\/p>\n<p>Sull&#8217;isola MOAS offre anche il corso &#8220;Inglese per principianti&#8221; ai residenti di alcuni centri di accoglienza transitoria: il corso \u00e8 adattato alle esigenze dei richiedenti asilo beneficiari e l&#8217;obiettivo \u00e8 quello di aumentare la fiducia nell&#8217;ascolto e nella conversazione in inglese in un contesto informale. Le lezioni, che si concentrano principalmente sulla conversazione in inglese, aumentano la capacit\u00e0 dei partecipanti di integrarsi nella comunit\u00e0 locale e di accedere alle risorse comunitarie. L&#8217;acquisizione della lingua inglese pu\u00f2 essere fondamentale per i partecipanti per accedere a un impiego migliore e creare legami nella comunit\u00e0.<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>Il film The Path<\/strong><\/span><\/p>\n<p>La fine dell&#8217;anno \u00e8 stata segnata dall&#8217;uscita del cortometraggio animato <em>The Path<\/em>, ideato e diretto per MOAS dall&#8217;animatore britannico Duncan Rudd. Il film \u00e8 stato concepito durante un progetto artistico dedicato al lavoro di MOAS in occasione della Settimana dei Rifugiati, grazie alla collaborazione con Studio Treble, un&#8217;agenzia digitale con sede a Manchester. Il film racconta la storia di una giovane ragazza costretta a lasciarsi tutto alle spalle e a fuggire in cerca di salvezza; il film si ispira al lavoro di MOAS &#8211; che nel 2014 \u00e8 stata la prima organizzazione umanitaria ad avviare missioni SAR private nel Mediterraneo e che in tre anni ha salvato ben 40.000 vite &#8211; e alla campagna di advocacy per #VieSicureELegali. Il film pu\u00f2 essere visto <a href=\"https:\/\/www.youtube.com\/watch?v=fVEs8ZTPfts\">qui<\/a>.<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>Campagna sui cambiamenti climatici<\/strong><\/span><\/p>\n<p>Nel 2022 MOAS ha lanciato una campagna educativa e di advocacy incentrata sulle questioni chiave che i migranti climatici devono affrontare, tra cui la mancanza di un meccanismo di protezione internazionale e di un piano di collaborazione a lungo termine per garantire la fornitura dei mezzi di sussistenza delle persone colpite dall\u2019impatto del cambiamento climatico. La campagna globale \u00e8 stata promossa attraverso le piattaforme social di MOAS per informare il pubblico sulla realt\u00e0 vissuta dei rifugiati climatici e sottolineare la necessit\u00e0 di cambiamenti politici. Mentre la Convenzione sui rifugiati \u00e8 sancita da accordi internazionali e non sono state apportate modifiche dalla sua creazione, c&#8217;\u00e8 la possibilit\u00e0 di attuare dei miglioramenti per garantire la messa in atto di meccanismi di protezione.<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>Advocacy<\/strong><\/span><\/p>\n<p>MOAS continua a sostenere l&#8217;implementazione di #VieSicureELegali di migrazione.<\/p>\n<p>Nel corso del 2022 il team di MOAS \u00e8 stato impegnato nel fornire informazioni e sensibilizzare la nostra comunit\u00e0. Il team ha decostruito la terminologia della migrazione, ha spiegato le definizioni legali e ha esplorato le narrazioni dell&#8217;asilo e gli ostacoli che queste persone devono affrontare. Abbiamo inoltre analizzato i principali fattori che guidano la migrazione: economici, politici, sociali e ambientali, in modo che il nostro pubblico possa capire meglio perch\u00e9 le persone decidono di lasciare i loro Paesi e rischiare la vita per raggiungere la salvezza.<\/p>\n<p>Sono stati anche considerati i sistemi giuridici esistenti attraverso i quali le persone migranti possono chiedere protezione umanitaria; questi includono i visti umanitari, i programmi di reinsediamento, il ricongiungimento familiare e la sponsorizzazione comunitaria.<\/p>\n<p>Negli ultimi mesi dell&#8217;anno, l&#8217;\u00e9quipe di MOAS si \u00e8 concentrato sulla fornitura di informazioni sulle procedure di migrazione nel Regno Unito e in Italia, approfondendo i percorsi legali gi\u00e0 esistenti, che devono essere implementati.<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>Guardando al 2023<\/strong><\/span><\/p>\n<p>MOAS sta facendo passi da gigante nel campo della DRR e continuer\u00e0 a sostenere i nostri partner e le infrastrutture di gestione dei campi nella mappatura dei rischi, nella formazione e nella distribuzione di attrezzature per combattere i possibili effetti di inondazioni e cicloni, nonch\u00e9 degli incendi nei campi profughi e nelle comunit\u00e0 ospitanti circostanti.<\/p>\n<p>La nostra raccolta fondi per i progetti di consegna degli aiuti nutrizionali \u00e8 ben avviata, in quanto ci sforziamo di fornire gli stessi livelli di supporto allo Yemen e alla Somalia come abbiamo fatto nel 2022, ampliando nel contempo il progetto per includere nuove consegne che potrebbero essere necessarie.<\/p>\n<p>A Malta, puntiamo ad aprire il primo Centro di apprendimento e informazione presso l&#8217;Hangar Open Center (HOC) all&#8217;inizio del 2023, che sar\u00e0 seguito da un&#8217;apertura simile presso l&#8217;Hal Far Tent Village (HTC). Il programma di apprendimento a distanza continuer\u00e0 ad espandersi e MOAS continuer\u00e0 a sostenere i richiedenti asilo e i beneficiari di protezione (BoP) nella comunit\u00e0 attraverso visite in ospedale, distribuzioni, attivit\u00e0 e opportunit\u00e0 educative, ecc.<\/p>\n<p>Abbiamo inoltre in programma di continuare i progetti di integrazione attraverso una serie di iniziative in collaborazione con altre ONG e parti interessate, per implementare le connessioni e l&#8217;indipendenza dei rifugiati e dei richiedenti asilo a Malta.<\/p>\n<p>In Ucraina, il nostro personale medico e il nostro team dedicato continueranno ad assistere il maggior numero possibile di pazienti, fornendo cure di emergenza e salvando le vite dei civili vulnerabili colpiti dall&#8217;impatto devastante del conflitto armato in corso.<\/p>\n<p>Riteniamo che i nostri maggiori successi risiedano nella profondit\u00e0 e nell&#8217;ampiezza del sostegno che abbiamo fornito ai nostri beneficiari. Continuiamo a impegnarci per un mondo in cui tutte le persone siano trattate con dignit\u00e0 e rispetto; grazie alla nostra esperienza nella logistica siamo in grado di rispondere rapidamente alle crisi emergenti e di fornire assistenza umanitaria a lungo termine per alleviare le sofferenze delle persone costrette a rischiare la vita in cerca di salvezza.<\/p>\n<p>In vista del 2023, continueremo a fornire le nostre competenze logistiche e a rispondere rapidamente alle crisi emergenti.<\/p>\n<p><b><span data-contrast=\"auto\">Se siete interessati al lavoro di MOAS e dei nostri partner, vi preghiamo di seguirci sui social media, iscrivervi alla nostra newsletter e condividere i nostri contenuti. Potete anche contattarci in qualsiasi momento tramite\u00a0<\/span><\/b><a href=\"mailto:info@moas.eu\"><b><span data-contrast=\"none\">info@moas.eu<\/span><\/b><\/a><b><span data-contrast=\"auto\">. Se volete sostener le nostre operazioni, per favore donatei quello che potete su\u00a0<\/span><\/b><b><span data-contrast=\"none\"><a href=\"https:\/\/www.moas.eu\/it\/dona\/\">www.moas.eu\/donate<\/a>.<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il 2022 \u00e8 trascorso ed \u00e8 tempo di riflettere sulle attivit\u00e0 e sui progetti realizzati da MOAS in tutto il mondo. \u00c8 stato un periodo &#8230; <a title=\"2022&#8230; Che anno \u00e8 stato!\" class=\"read-more\" href=\"https:\/\/www.moas.eu\/it\/2022-che-anno-e-stato\/\" aria-label=\"Per saperne di pi\u00f9 su 2022&#8230; Che anno \u00e8 stato!\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":52307,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"nf_dc_page":"","footnotes":""},"categories":[19],"tags":[218,219,217],"class_list":["post-52313","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-it","tag-advocacy","tag-crisi-emergenti","tag-missione","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","resize-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2022... Che anno \u00e8 stato! - MOAS<\/title>\n<meta name=\"description\" content=\"Il 2022 \u00e8 alle spalle ed \u00e8 tempo di riflettere sulle attivit\u00e0 e sui progetti di MOAS in tutto il mondo. \u00c8 stato un periodo impegnativo ma produttivo e ricco di successi!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.moas.eu\/it\/2022-che-anno-e-stato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2022... Che anno \u00e8 stato! - MOAS\" \/>\n<meta property=\"og:description\" content=\"Il 2022 \u00e8 alle spalle ed \u00e8 tempo di riflettere sulle attivit\u00e0 e sui progetti di MOAS in tutto il mondo. \u00c8 stato un periodo impegnativo ma produttivo e ricco di successi!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.moas.eu\/it\/2022-che-anno-e-stato\/\" \/>\n<meta property=\"og:site_name\" content=\"MOAS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/migrantoffshoreaidstation\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-27T09:00:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-28T11:43:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.moas.eu\/wp-content\/uploads\/21-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1775\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christina Lejman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@moas_eu\" \/>\n<meta name=\"twitter:site\" content=\"@moas_eu\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christina Lejman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/2022-che-anno-e-stato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/2022-che-anno-e-stato\\\/\"},\"author\":{\"name\":\"Christina Lejman\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/person\\\/be1af883120febb082823c3c74304c69\"},\"headline\":\"2022&#8230; Che anno \u00e8 stato!\",\"datePublished\":\"2022-12-27T09:00:34+00:00\",\"dateModified\":\"2022-12-28T11:43:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/2022-che-anno-e-stato\\\/\"},\"wordCount\":2475,\"publisher\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/2022-che-anno-e-stato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/21-scaled.jpg\",\"keywords\":[\"advocacy\",\"crisi emergenti\",\"missione\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/2022-che-anno-e-stato\\\/\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/2022-che-anno-e-stato\\\/\",\"name\":\"2022... Che anno \u00e8 stato! - MOAS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/2022-che-anno-e-stato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/2022-che-anno-e-stato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/21-scaled.jpg\",\"datePublished\":\"2022-12-27T09:00:34+00:00\",\"dateModified\":\"2022-12-28T11:43:06+00:00\",\"description\":\"Il 2022 \u00e8 alle spalle ed \u00e8 tempo di riflettere sulle attivit\u00e0 e sui progetti di MOAS in tutto il mondo. \u00c8 stato un periodo impegnativo ma produttivo e ricco di successi!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/2022-che-anno-e-stato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.moas.eu\\\/it\\\/2022-che-anno-e-stato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/2022-che-anno-e-stato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/21-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/21-scaled.jpg\",\"width\":2560,\"height\":1775},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/2022-che-anno-e-stato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2022&#8230; Che anno \u00e8 stato!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/\",\"name\":\"MOAS\",\"description\":\"MOAS\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.moas.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\",\"name\":\"MOAS\",\"alternateName\":\"Migrant Offshore Aid Station\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/moas-logo-oval.png\",\"contentUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/moas-logo-oval.png\",\"width\":793,\"height\":354,\"caption\":\"MOAS\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/migrantoffshoreaidstation\",\"https:\\\/\\\/x.com\\\/moas_eu\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/migrant-offshore-aid-station\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZHcDS7ePIBW66d3KvX2K0Q\",\"https:\\\/\\\/www.instagram.com\\\/moas_eu\\\/?hl=en\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/person\\\/be1af883120febb082823c3c74304c69\",\"name\":\"Christina Lejman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"caption\":\"Christina Lejman\"},\"url\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/author\\\/clejman\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2022... Che anno \u00e8 stato! - MOAS","description":"Il 2022 \u00e8 alle spalle ed \u00e8 tempo di riflettere sulle attivit\u00e0 e sui progetti di MOAS in tutto il mondo. \u00c8 stato un periodo impegnativo ma produttivo e ricco di successi!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.moas.eu\/it\/2022-che-anno-e-stato\/","og_locale":"it_IT","og_type":"article","og_title":"2022... Che anno \u00e8 stato! - MOAS","og_description":"Il 2022 \u00e8 alle spalle ed \u00e8 tempo di riflettere sulle attivit\u00e0 e sui progetti di MOAS in tutto il mondo. \u00c8 stato un periodo impegnativo ma produttivo e ricco di successi!","og_url":"https:\/\/www.moas.eu\/it\/2022-che-anno-e-stato\/","og_site_name":"MOAS","article_publisher":"https:\/\/www.facebook.com\/migrantoffshoreaidstation","article_published_time":"2022-12-27T09:00:34+00:00","article_modified_time":"2022-12-28T11:43:06+00:00","og_image":[{"width":2560,"height":1775,"url":"https:\/\/www.moas.eu\/wp-content\/uploads\/21-scaled.jpg","type":"image\/jpeg"}],"author":"Christina Lejman","twitter_card":"summary_large_image","twitter_creator":"@moas_eu","twitter_site":"@moas_eu","twitter_misc":{"Scritto da":"Christina Lejman","Tempo di lettura stimato":"11 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.moas.eu\/it\/2022-che-anno-e-stato\/#article","isPartOf":{"@id":"https:\/\/www.moas.eu\/it\/2022-che-anno-e-stato\/"},"author":{"name":"Christina Lejman","@id":"https:\/\/www.moas.eu\/#\/schema\/person\/be1af883120febb082823c3c74304c69"},"headline":"2022&#8230; Che anno \u00e8 stato!","datePublished":"2022-12-27T09:00:34+00:00","dateModified":"2022-12-28T11:43:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.moas.eu\/it\/2022-che-anno-e-stato\/"},"wordCount":2475,"publisher":{"@id":"https:\/\/www.moas.eu\/#organization"},"image":{"@id":"https:\/\/www.moas.eu\/it\/2022-che-anno-e-stato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/21-scaled.jpg","keywords":["advocacy","crisi emergenti","missione"],"articleSection":["Blog"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.moas.eu\/it\/2022-che-anno-e-stato\/","url":"https:\/\/www.moas.eu\/it\/2022-che-anno-e-stato\/","name":"2022... Che anno \u00e8 stato! - MOAS","isPartOf":{"@id":"https:\/\/www.moas.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.moas.eu\/it\/2022-che-anno-e-stato\/#primaryimage"},"image":{"@id":"https:\/\/www.moas.eu\/it\/2022-che-anno-e-stato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/21-scaled.jpg","datePublished":"2022-12-27T09:00:34+00:00","dateModified":"2022-12-28T11:43:06+00:00","description":"Il 2022 \u00e8 alle spalle ed \u00e8 tempo di riflettere sulle attivit\u00e0 e sui progetti di MOAS in tutto il mondo. \u00c8 stato un periodo impegnativo ma produttivo e ricco di successi!","breadcrumb":{"@id":"https:\/\/www.moas.eu\/it\/2022-che-anno-e-stato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.moas.eu\/it\/2022-che-anno-e-stato\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.moas.eu\/it\/2022-che-anno-e-stato\/#primaryimage","url":"https:\/\/www.moas.eu\/wp-content\/uploads\/21-scaled.jpg","contentUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/21-scaled.jpg","width":2560,"height":1775},{"@type":"BreadcrumbList","@id":"https:\/\/www.moas.eu\/it\/2022-che-anno-e-stato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.moas.eu\/it\/"},{"@type":"ListItem","position":2,"name":"2022&#8230; Che anno \u00e8 stato!"}]},{"@type":"WebSite","@id":"https:\/\/www.moas.eu\/#website","url":"https:\/\/www.moas.eu\/","name":"MOAS","description":"MOAS","publisher":{"@id":"https:\/\/www.moas.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.moas.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.moas.eu\/#organization","name":"MOAS","alternateName":"Migrant Offshore Aid Station","url":"https:\/\/www.moas.eu\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.moas.eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/moas-logo-oval.png","contentUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/moas-logo-oval.png","width":793,"height":354,"caption":"MOAS"},"image":{"@id":"https:\/\/www.moas.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/migrantoffshoreaidstation","https:\/\/x.com\/moas_eu","https:\/\/www.linkedin.com\/company\/migrant-offshore-aid-station","https:\/\/www.youtube.com\/channel\/UCZHcDS7ePIBW66d3KvX2K0Q","https:\/\/www.instagram.com\/moas_eu\/?hl=en"]},{"@type":"Person","@id":"https:\/\/www.moas.eu\/#\/schema\/person\/be1af883120febb082823c3c74304c69","name":"Christina Lejman","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","caption":"Christina Lejman"},"url":"https:\/\/www.moas.eu\/it\/author\/clejman\/"}]}},"_links":{"self":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/52313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/comments?post=52313"}],"version-history":[{"count":5,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/52313\/revisions"}],"predecessor-version":[{"id":52383,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/52313\/revisions\/52383"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/media\/52307"}],"wp:attachment":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/media?parent=52313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/categories?post=52313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/tags?post=52313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}