{"id":49456,"date":"2022-05-09T07:18:45","date_gmt":"2022-05-09T07:18:45","guid":{"rendered":"http:\/\/just2093.temp.domains\/~tqmoaseu\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\/"},"modified":"2022-10-20T09:09:26","modified_gmt":"2022-10-20T09:09:26","slug":"limpatto-del-conflitto-in-ucraina-sul-settore-umanitario","status":"publish","type":"post","link":"https:\/\/www.moas.eu\/it\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\/","title":{"rendered":"L\u2019IMPATTO DEL CONFLITTO IN UCRAINA SUL SETTORE UMANITARIO"},"content":{"rendered":"<p>L&#8217;escalation della violenza in Ucraina causa gravi ripercussioni su scala globale. Il conflitto ha avuto terribili conseguenze per i civili ed ha scatenato una crisi umanitaria e un movimento massiccio di rifugiati. Oltre a ci\u00f2, i paesi di tutto il mondo hanno risentito di un aumento vertiginoso dei prezzi degli alimenti e dell&#8217;energia, causando un peggioramento dei livelli di povert\u00e0. In modi diversi, l&#8217;intero settore umanitario \u00e8 stato gravemente colpito dall\u2019impatto del conflitto ucraino.<\/p>\n<p><strong>Crisi globale alimentare e aumento del costo della vita<\/strong><\/p>\n<p>La fame \u00e8 in aumento a livello globale e, secondo stime ufficiali, gi\u00e0 nel 2020 tra <a href=\"https:\/\/www.un.org\/en\/global-issues\/food#:~:text=Hunger%20and%20nutrition%20in%20numbers&amp;text=It%20is%20estimated%20that%20between,pandemic%20on%20global%20food%20security.\">720 e 811 milioni di persone<\/a> nel mondo non avevano accesso al cibo e hanno sofferto la fame. Si tratta di un record, causato da un insieme di eventi climatici estremi, crisi economica e finanziaria e conflitti di lunga durata. Oltre a questa situazione gi\u00e0 preoccupante, a seguito della crisi in Ucraina i prezzi degli alimenti sono saliti ai livelli pi\u00f9 alti mai raggiunti. Secondo <a href=\"https:\/\/www.fao.org\/worldfoodsituation\/foodpricesindex\/en\/\">l&#8217;indice mensile dei prezzi alimentari della FAO<\/a>, olio da cucina, cereali e carni ora costano un terzo in pi\u00f9 rispetto allo stesso periodo dell&#8217;anno scorso. A causa del conflitto, i porti del Paese sono stati chiusi, il sistema di esportazione del Mar Nero \u00e8 stato interrotto e anche le esportazioni russe sono state rallentate a seguito di problemi finanziari e marittimi in Russia.<\/p>\n<p>Come notato dagli esperti della FAO, \u00e8 probabile che il rapido aumento dei prezzi alimentari a livello mondiale persista. Di conseguenza, l&#8217;impatto a lungo termine si far\u00e0 sentire pesantemente in tutti i continenti. L&#8217;interruzione delle importazioni, della produzione e il relativo aumento dei costi possono potenzialmente peggiorare l\u2019accesso al cibo a livello globale. L&#8217;aumento vertiginoso dei prezzi alimentari sar\u00e0 particolarmente dannoso in aree gi\u00e0 colpite da altre crisi quali conflitti, disastri naturali e condizioni economiche e finanziarie difficili: ad esempio, Kenya, Etiopia, Somalia e Sud Sudan, stanno attraversando un periodo di grave siccit\u00e0 e sono afflitti da turbolenze interne. Inoltre, l&#8217;Ucraina e la Russia sono due dei principali produttori mondiali di grano, fertilizzanti ed energia, per cui l&#8217;interruzione dei flussi di esportazione, unita all&#8217;imposizione di severe sanzioni economiche contro la Russia, hanno suscitato i timori di una <a href=\"https:\/\/www.wfp.org\/stories\/war-ukraine-fears-impact-global-hunger-after-agricultural-fields-turned-battlefields#:~:text=There%20are%20food%20shortages%20in,prices%20are%20reaching%20record%20highs.\">crisi alimentare globale<\/a>.<\/p>\n<p><strong>Riduzione dei finanziamenti <\/strong><\/p>\n<p>Dato che la crisi in Ucraina sta ricevendo grande attenzione mediatica, si teme che gli aiuti e le risorse umanitarie vengano dirottati da altre aree di intervento e reindirizzate in Ucraina. Sebbene Siria, Somalia, Yemen, Afghanistan e Yemen siano state riconosciute a livello internazionale come aree di crisi, sembra che ora corrano il rischio di essere trascurate dalle organizzazioni umanitarie internazionali poich\u00e9 le risorse dei principali donatori vengono convogliate verso l&#8217;Ucraina e le esigenze umanitarie del Paese. Di conseguenza, alla conferenza per lo Yemen tenutasi il 16 marzo 2022, i donatori hanno raccolto <a href=\"https:\/\/www.unocha.org\/sites\/unocha\/files\/2022%20Yemen%20HLE%202022%20Announcements%20Results%20final%2016%20March.pdf\">meno di un terzo<\/a> dei 4,3 miliardi di dollari richiesti dalle Nazioni Unite per rispondere a una delle emergenze umanitarie pi\u00f9 vaste e complesse del mondo. Questo risultato riflette un cambiamento nella risposta umanitaria alle crisi globali: non \u00e8 solo lo Yemen a ricevere una frazione di ci\u00f2 di cui ha bisogno. Il numero di crisi nel mondo sta aumentando, le popolazioni stanno soffrendo e hanno bisogno di costante aiuto e sostegno umanitario.<\/p>\n<p><strong>MOAS in Yemen e in Somalia<\/strong><\/p>\n<p>Grazie alla nostra competenza logistica, MOAS \u00e8 in grado di rispondere rapidamente alle crisi umanitarie emergenti. Mentre forniamo assistenza medica di emergenza in Ucraina, stiamo anche continuando le nostre operazioni in Yemen, Siria e Somalia per assistere le comunit\u00e0 pi\u00f9 vulnerabili colpite dagli effetti devastanti di guerra, violenza, cambiamenti climatici e shock ambientali. Attraverso la #MissionofHope, MOAS fornisce supplementi nutrizionali specificamente studiati per aiutare a curare la malnutrizione nei bambini e salvare vite umane. Ci\u00f2 avviene in stretta collaborazione con il nostro partner Edesia. Inoltre, MOAS spedisce forniture mediche in Yemen, dove \u00e8 in corso una delle peggior crisi umanitaria al mondo. La nostra pi\u00f9 recente consegna di forniture mediche, donate dal nostro partner Medeor, ha recentemente raggiunto il porto di Aden e sar\u00e0 distribuita tramite la nostra controparte locale, ADRA Yemen. La prima spedizione di alimenti terapeutici pronti all&#8217;uso \u00e8 recentemente arrivata in Turchia e presto raggiunger\u00e0 la destinazione finale in Siria per supportare il nostro partner Action For Humanity.<\/p>\n<p><strong>Considerazioni finali<\/strong><\/p>\n<p>La pandemia e le crisi emergenti ci hanno costretto a riconsiderare le nostre priorit\u00e0 e hanno evidenziato l&#8217;importanza di creare societ\u00e0 pi\u00f9 sostenibili e resilienti. Eppure, sembra che ci stiamo spostando da una crisi all&#8217;altra. La comunit\u00e0 internazionale e i governi nazionali devono tenere presente che sono sempre i civili e le comunit\u00e0 pi\u00f9 vulnerabili a subire le conseguenze pi\u00f9 dure di un conflitto. Poich\u00e9 la situazione si evolve e le conseguenze umanitarie sono difficili da stimare, \u00e8 necessario garantire che le comunit\u00e0 colpite abbiano accesso continuo al sostegno umanitario di cui potrebbero aver bisogno e che la loro sicurezza, in aggiunta alla sicurezza degli operatori umanitari in loco, sia garantita.<\/p>\n<p><strong>Se sei interessato al lavoro di MOAS e dei nostri partner, seguici sui social media, iscriviti alla nostra newsletter e condividi i nostri contenuti. Puoi anche contattarci in qualsiasi momento tramite info@moas.eu. Se vuoi sostenere le nostre operazioni, ti preghiamo di donare ci\u00f2 che puoi su\u00a0<\/strong><a href=\"https:\/\/www.moas.eu\/donate\/\"><strong>www.moas.eu\/donate\/<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/eupa-logo-1-1.png\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-38077\" src=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/eupa-logo-1-1.png\" alt=\"eupa logo\" width=\"177\" height=\"156\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;escalation della violenza in Ucraina causa gravi ripercussioni su scala globale. Il conflitto ha avuto terribili conseguenze per i civili ed ha scatenato una crisi &#8230; <a title=\"L\u2019IMPATTO DEL CONFLITTO IN UCRAINA SUL SETTORE UMANITARIO\" class=\"read-more\" href=\"https:\/\/www.moas.eu\/it\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\/\" aria-label=\"Per saperne di pi\u00f9 su L\u2019IMPATTO DEL CONFLITTO IN UCRAINA SUL SETTORE UMANITARIO\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":48794,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"nf_dc_page":"","footnotes":""},"categories":[14,19],"tags":[],"class_list":["post-49456","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-blog-it","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","resize-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019IMPATTO DEL CONFLITTO IN UCRAINA SUL SETTORE UMANITARIO - MOAS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.moas.eu\/it\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019IMPATTO DEL CONFLITTO IN UCRAINA SUL SETTORE UMANITARIO - MOAS\" \/>\n<meta property=\"og:description\" content=\"L&#8217;escalation della violenza in Ucraina causa gravi ripercussioni su scala globale. Il conflitto ha avuto terribili conseguenze per i civili ed ha scatenato una crisi ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.moas.eu\/it\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\/\" \/>\n<meta property=\"og:site_name\" content=\"MOAS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/migrantoffshoreaidstation\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-09T07:18:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-20T09:09:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Blog-Post-Ceci-Beth-21.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Christina Lejman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@moas_eu\" \/>\n<meta name=\"twitter:site\" content=\"@moas_eu\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christina Lejman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\\\/\"},\"author\":{\"name\":\"Christina Lejman\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/person\\\/be1af883120febb082823c3c74304c69\"},\"headline\":\"L\u2019IMPATTO DEL CONFLITTO IN UCRAINA SUL SETTORE UMANITARIO\",\"datePublished\":\"2022-05-09T07:18:45+00:00\",\"dateModified\":\"2022-10-20T09:09:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\\\/\"},\"wordCount\":880,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Blog-Post-Ceci-Beth-21.png\",\"articleSection\":[\"Blog\",\"Blog\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.moas.eu\\\/it\\\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\\\/\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\\\/\",\"name\":\"L\u2019IMPATTO DEL CONFLITTO IN UCRAINA SUL SETTORE UMANITARIO - MOAS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Blog-Post-Ceci-Beth-21.png\",\"datePublished\":\"2022-05-09T07:18:45+00:00\",\"dateModified\":\"2022-10-20T09:09:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.moas.eu\\\/it\\\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Blog-Post-Ceci-Beth-21.png\",\"contentUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Blog-Post-Ceci-Beth-21.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019IMPATTO DEL CONFLITTO IN UCRAINA SUL SETTORE UMANITARIO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/\",\"name\":\"MOAS\",\"description\":\"MOAS\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.moas.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\",\"name\":\"MOAS\",\"alternateName\":\"Migrant Offshore Aid Station\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/moas-logo-oval.png\",\"contentUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/moas-logo-oval.png\",\"width\":793,\"height\":354,\"caption\":\"MOAS\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/migrantoffshoreaidstation\",\"https:\\\/\\\/x.com\\\/moas_eu\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/migrant-offshore-aid-station\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZHcDS7ePIBW66d3KvX2K0Q\",\"https:\\\/\\\/www.instagram.com\\\/moas_eu\\\/?hl=en\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/person\\\/be1af883120febb082823c3c74304c69\",\"name\":\"Christina Lejman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"caption\":\"Christina Lejman\"},\"url\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/author\\\/clejman\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019IMPATTO DEL CONFLITTO IN UCRAINA SUL SETTORE UMANITARIO - MOAS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.moas.eu\/it\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\/","og_locale":"it_IT","og_type":"article","og_title":"L\u2019IMPATTO DEL CONFLITTO IN UCRAINA SUL SETTORE UMANITARIO - MOAS","og_description":"L&#8217;escalation della violenza in Ucraina causa gravi ripercussioni su scala globale. Il conflitto ha avuto terribili conseguenze per i civili ed ha scatenato una crisi ... Read more","og_url":"https:\/\/www.moas.eu\/it\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\/","og_site_name":"MOAS","article_publisher":"https:\/\/www.facebook.com\/migrantoffshoreaidstation","article_published_time":"2022-05-09T07:18:45+00:00","article_modified_time":"2022-10-20T09:09:26+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Blog-Post-Ceci-Beth-21.png","type":"image\/png"}],"author":"Christina Lejman","twitter_card":"summary_large_image","twitter_creator":"@moas_eu","twitter_site":"@moas_eu","twitter_misc":{"Scritto da":"Christina Lejman","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.moas.eu\/it\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\/#article","isPartOf":{"@id":"https:\/\/www.moas.eu\/it\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\/"},"author":{"name":"Christina Lejman","@id":"https:\/\/www.moas.eu\/#\/schema\/person\/be1af883120febb082823c3c74304c69"},"headline":"L\u2019IMPATTO DEL CONFLITTO IN UCRAINA SUL SETTORE UMANITARIO","datePublished":"2022-05-09T07:18:45+00:00","dateModified":"2022-10-20T09:09:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.moas.eu\/it\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\/"},"wordCount":880,"commentCount":0,"publisher":{"@id":"https:\/\/www.moas.eu\/#organization"},"image":{"@id":"https:\/\/www.moas.eu\/it\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\/#primaryimage"},"thumbnailUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Blog-Post-Ceci-Beth-21.png","articleSection":["Blog","Blog"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.moas.eu\/it\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.moas.eu\/it\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\/","url":"https:\/\/www.moas.eu\/it\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\/","name":"L\u2019IMPATTO DEL CONFLITTO IN UCRAINA SUL SETTORE UMANITARIO - MOAS","isPartOf":{"@id":"https:\/\/www.moas.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.moas.eu\/it\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\/#primaryimage"},"image":{"@id":"https:\/\/www.moas.eu\/it\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\/#primaryimage"},"thumbnailUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Blog-Post-Ceci-Beth-21.png","datePublished":"2022-05-09T07:18:45+00:00","dateModified":"2022-10-20T09:09:26+00:00","breadcrumb":{"@id":"https:\/\/www.moas.eu\/it\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.moas.eu\/it\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.moas.eu\/it\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\/#primaryimage","url":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Blog-Post-Ceci-Beth-21.png","contentUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Blog-Post-Ceci-Beth-21.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.moas.eu\/it\/limpatto-del-conflitto-in-ucraina-sul-settore-umanitario\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.moas.eu\/it\/"},{"@type":"ListItem","position":2,"name":"L\u2019IMPATTO DEL CONFLITTO IN UCRAINA SUL SETTORE UMANITARIO"}]},{"@type":"WebSite","@id":"https:\/\/www.moas.eu\/#website","url":"https:\/\/www.moas.eu\/","name":"MOAS","description":"MOAS","publisher":{"@id":"https:\/\/www.moas.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.moas.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.moas.eu\/#organization","name":"MOAS","alternateName":"Migrant Offshore Aid Station","url":"https:\/\/www.moas.eu\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.moas.eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/moas-logo-oval.png","contentUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/moas-logo-oval.png","width":793,"height":354,"caption":"MOAS"},"image":{"@id":"https:\/\/www.moas.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/migrantoffshoreaidstation","https:\/\/x.com\/moas_eu","https:\/\/www.linkedin.com\/company\/migrant-offshore-aid-station","https:\/\/www.youtube.com\/channel\/UCZHcDS7ePIBW66d3KvX2K0Q","https:\/\/www.instagram.com\/moas_eu\/?hl=en"]},{"@type":"Person","@id":"https:\/\/www.moas.eu\/#\/schema\/person\/be1af883120febb082823c3c74304c69","name":"Christina Lejman","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","caption":"Christina Lejman"},"url":"https:\/\/www.moas.eu\/it\/author\/clejman\/"}]}},"_links":{"self":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/49456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/comments?post=49456"}],"version-history":[{"count":1,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/49456\/revisions"}],"predecessor-version":[{"id":49457,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/49456\/revisions\/49457"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/media\/48794"}],"wp:attachment":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/media?parent=49456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/categories?post=49456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/tags?post=49456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}