{"id":49426,"date":"2022-02-03T09:23:01","date_gmt":"2022-02-03T09:23:01","guid":{"rendered":"http:\/\/just2093.temp.domains\/~tqmoaseu\/i-trend-umanitari-del-2022\/"},"modified":"2022-10-20T09:09:32","modified_gmt":"2022-10-20T09:09:32","slug":"i-trend-umanitari-del-2022","status":"publish","type":"post","link":"https:\/\/www.moas.eu\/it\/i-trend-umanitari-del-2022\/","title":{"rendered":"I TREND UMANITARI DEL 2022"},"content":{"rendered":"<p>Nel 2022 si prevede che <a href=\"https:\/\/reliefweb.int\/report\/world\/global-humanitarian-overview-2022\">274 milioni<\/a> di persone avranno bisogno di assistenza e protezione umanitaria. Questo dato \u00e8 aumentato in modo significativo rispetto al 2021 e per questo motivo l&#8217;ONU ha richiesto <a href=\"https:\/\/reliefweb.int\/report\/world\/global-humanitarian-overview-2022\">41 miliardi di dollari<\/a> per aiutare circa 183 milioni di persone in 63 Paesi. I Paesi attualmente spendono circa 25 miliardi di dollari per fornire aiuti salvavita e assistenza a coloro che sono colpiti da disastri e conflitti. Anche se sembra un importo enorme, tali livelli di finanziamento sono fondamentali poich\u00e9 i bisogni umanitari continuano ad aumentare a livello globale. Senza una maggiore sinergia tra la pianificazione e gli investimenti in materia di sviluppo, aiuti umanitari e riduzione del rischio di catastrofi (DRR), tali finanziamenti continueranno a non essere sufficienti per poter affrontare in modo efficace le crisi che si verificheranno nei prossimi anni.<\/p>\n<p><strong>Insicurezza alimentare<\/strong><\/p>\n<p>La fame nel mondo non sar\u00e0 <a href=\"https:\/\/docs.wfp.org\/api\/documents\/WFP-0000130141\/download\/?_ga=2.114406215.171976761.1626375021-1366495049.1625167788\">sradicata<\/a> entro il 2030 a meno che i Paesi non apportino cambiamenti sostanziali per affrontare efficacemente la disuguaglianza nell&#8217;accesso al cibo. Quasi <a href=\"https:\/\/docs.wfp.org\/api\/documents\/WFP-0000130141\/download\/?_ga=2.114406215.171976761.1626375021-1366495049.1625167788\">660 milioni<\/a> di persone probabilmente dovranno affrontare la fame entro il 2030, 30 milioni in pi\u00f9 del previsto a causa degli impatti a lungo termine della pandemia. L&#8217;anno scorso, in 80 Paesi, circa 283 milioni di persone erano gravemente insicure dal punto di vista alimentare o ad alto rischio di malnutrizione. Questo record \u00e8 stato determinato da livelli variabili di insicurezza alimentare nelle regioni afflitte da conflitti militari, come Afghanistan, Myanmar, Etiopia, Yemen e Somalia. Quest&#8217;anno, molti di questi Paesi stanno affrontando la carestia e la Nigeria \u00e8 attualmente sull&#8217;orlo del baratro mentre la violenza continua a devastare il Paese.<\/p>\n<p>Nel 2021, secondo il Global Humanitarian Overview, &#8220;gli impatti climatici si sono uniti ai conflitti come causa principale della carestia&#8221;. Una maggiore frequenza di fenomeni quali siccit\u00e0, piogge e scarsi raccolti agricoli in molte aree del mondo, hanno costretto i cittadini a ricorrere al razionamento delle scorte di cibo solitamente riservato al bestiame pur di poter sopravvivere.<\/p>\n<p><strong>Clima e migrazione<\/strong><\/p>\n<p>La temperatura del globo continuer\u00e0 ad aumentare almeno fino al 2050 secondo quanto stabilito in tutti gli scenari di emissioni calcolati nel <a href=\"https:\/\/www.ipcc.ch\/report\/ar6\/wg1\/\">rapporto IPCC 2021<\/a>. Un riscaldamento globale di 1,5\u00b0C e 2\u00b0C sar\u00e0 probabilmente superato in questo secolo, a meno che non vengano effettuate riduzioni radicali del biossido di carbonio (CO2) e di altri gas serra. Mentre la COP21 ha visto i governi riunirsi per impegnarsi a modificare i consumi, la produzione e le fonti di energia rinnovabile, molte comunit\u00e0 indigene sono state escluse dalla conversazione e sono state fatte promesse a sostegno dell\u2019ambiente dai principali attori inquinatori che, da allora, non sono state seguite da alcun cambiamento politico significativo. Mentre 200 organizzazioni ambientaliste hanno firmato una <a href=\"https:\/\/www.thenewhumanitarian.org\/analysis\/2021\/11\/23\/New-climate-charter-greener-future-for-the-aid-sector\">nuova Carta sul Clima<\/a>, ci sono stati pochi cambiamenti tangibili per compensare i disastri legati al clima nei Paesi pi\u00f9 vulnerabili. \u00c8 probabile che aumenti il numero delle persone costrette a migrare a causa del cambiamento climatico che non solo causa disastri, ma \u00e8 un fattore di intensificazione dei conflitti e dell&#8217;instabilit\u00e0 economica. Alcuni Paesi sono sempre pi\u00f9 sfacciati nello sfruttare la migrazione per esercitare pressioni politiche e molti sono sempre pi\u00f9 desiderosi di impedire alle persone di entrare nei loro confini. Ci sono state poche indicazioni che i Paesi occidentali siano pronti a cambiare drasticamente le politiche di confine di fronte alle previsioni sulla migrazione, ma bisogna lavorare insieme per dare la priorit\u00e0 alla vita umana rispetto alle politiche di esclusione.<\/p>\n<p><strong>Questioni di Genere<\/strong><\/p>\n<p>Il divario tra povert\u00e0 e genere si sta <a href=\"https:\/\/reliefweb.int\/report\/world\/global-humanitarian-overview-2022\">ingrandendo<\/a>, con 247 milioni di donne che attualmente vivono con meno di 1,90 dollari al giorno. Questa statistica sbalorditiva riflette un passo indietro verso la parit\u00e0 di genere: la pandemia, le ripercussioni economiche e il tumulto politico in molte regioni hanno inferto un duro colpo al progresso di parit\u00e0 di genere. A livello globale, in particolare, \u00a0la prevalenza dell&#8217;insicurezza alimentare tra le donne \u00e8 aumentata drammaticamente negli ultimi 2 anni: era del <a href=\"https:\/\/docs.wfp.org\/api\/documents\/WFP-0000130141\/download\/?_ga=2.114406215.171976761.1626375021-1366495049.1625167788\">6% pi\u00f9 alta tra le donne<\/a> rispetto agli uomini nel 2019, e del 10% in pi\u00f9 nel 2020. Poich\u00e9 questa tendenza continua a causa della pandemia di COVID-19 ed intacca duramente altri contesti sociali, ci troviamo di fronte a gravi battute d&#8217;arresto negli anni a venire. Queste sono sfide pervasive e in via di sviluppo, ma ci sono <a href=\"https:\/\/unfoundation.org\/blog\/post\/5-global-issues-to-watch-in-2022\/\">sempre pi\u00f9 attori<\/a> dedicati e gruppi della societ\u00e0 civile che lavorano per accelerare l&#8217;uguaglianza di genere attraverso iniziative e movimenti per la giustizia. Nel 2021, il Generation Equality Forum (GEF) si \u00e8 tenuto in Messico e Francia, mobilitando 40 miliardi di dollari di finanziamenti promessi da governi e attori chiave. Nel 2022, questi impegni dovrebbero iniziare a tradursi in cambiamenti politici e programmazione creativa.<\/p>\n<p><strong>Tendenze politiche<\/strong><\/p>\n<p>Gli operatori umanitari hanno iniziato a sfruttare lo sviluppo e il finanziamento degli aiuti con modelli di finanziamento nuovi e innovativi che si discostano dalle forme tradizionali. Abbiamo visto la Banca Mondiale assumere un ruolo sempre pi\u00f9 attivo in contesti di crisi e le ONG hanno informato in modo pi\u00f9 dettagliato i governi circa le politiche di riduzione del rischio climatico, in particolare sulla COP21. La maggior parte della programmazione umanitaria \u00e8 ora sostenuta da considerazioni sul clima e la sfera dello sviluppo si sta spostando verso una pianificazione dell&#8217;azione pi\u00f9 localizzata. Lo sviluppo delle microimprese sar\u00e0 probabilmente un&#8217;area prioritaria in crescita in termini di strategie di sviluppo. Tali imprese si ripercuotono positivamente sullo sviluppo dell&#8217;indipendenza economica tra le comunit\u00e0 svantaggiate e sull&#8217;integrazione economica a lungo termine. Il Refugee Impact Bond \u00e8 una nuova iniziativa che segue questi principi, sviluppando l&#8217;indipendenza a lungo termine dei rifugiati incoraggiando pratiche di integrazione dinamica.<\/p>\n<p><strong>Considerazioni finali<\/strong><\/p>\n<p>\u00c8 necessaria una visione a lungo termine quando si considera il futuro degli aiuti e dello sviluppo. Si stima che la met\u00e0 di tutte le crisi odierne sia in qualche modo prevedibile e il 20% di queste sia altamente prevedibile. Tuttavia, meno dell&#8217;1% del finanziamento di queste crisi \u00e8 prestabilito. Pertanto, l\u2019approccio globale deve essere pi\u00f9 anticipatore per mitigare i disastri futuri. Ci\u00f2 include lo sfruttamento delle proiezioni del rischio climatico per avviare la pianificazione umanitaria in modo da poter comprendere meglio e prepararsi alla vulnerabilit\u00e0 sociale.<\/p>\n<p>Negli ultimi anni ci sono state raccomandazioni di alto livello che hanno chiesto una migliore sinergia tra sviluppo, DRR e pianificazione umanitaria poich\u00e9 gli interventi umanitari pi\u00f9 efficaci si hanno nell\u2019attenuare i disastri piuttosto che nel rispondere ad essi. Dobbiamo continuare a lavorare su questa sinergia in modo che la comunit\u00e0 globale sia meglio preparata ad affrontare i cambiamenti climatici, le crisi e le sfide in corso. Non dobbiamo utilizzare un approccio coloniale dall&#8217;alto verso il basso verso tali aiuti, ma dobbiamo sostenere la programmazione e le iniziative localizzate per prepararci al meglio per il futuro.<\/p>\n<p><b><span data-contrast=\"auto\">Se sei interessato al lavoro di MOAS e dei nostri partner, seguici sui social media, iscriviti alla nostra newsletter e condividi i nostri contenuti. Puoi anche contattarci in qualsiasi momento tramite\u00a0<\/span><\/b><a href=\"mailto:info@moas.eu\"><b><span data-contrast=\"none\">info@moas.eu<\/span><\/b><\/a><b><span data-contrast=\"auto\">. Se vuoi supportare le nostre operazioni, ti preghiamo di dare ci\u00f2 che puoi su\u00a0<\/span><\/b><a href=\"https:\/\/www.moas.eu\/donate\"><b><span data-contrast=\"none\">www.moas.eu\/donate<\/span><\/b><\/a><b><span data-contrast=\"auto\">.<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel 2022 si prevede che 274 milioni di persone avranno bisogno di assistenza e protezione umanitaria. Questo dato \u00e8 aumentato in modo significativo rispetto al &#8230; <a title=\"I TREND UMANITARI DEL 2022\" class=\"read-more\" href=\"https:\/\/www.moas.eu\/it\/i-trend-umanitari-del-2022\/\" aria-label=\"Per saperne di pi\u00f9 su I TREND UMANITARI DEL 2022\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":48734,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"nf_dc_page":"","footnotes":""},"categories":[14,19],"tags":[],"class_list":["post-49426","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-blog-it","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","resize-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I TREND UMANITARI DEL 2022 - MOAS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.moas.eu\/it\/i-trend-umanitari-del-2022\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I TREND UMANITARI DEL 2022 - MOAS\" \/>\n<meta property=\"og:description\" content=\"Nel 2022 si prevede che 274 milioni di persone avranno bisogno di assistenza e protezione umanitaria. Questo dato \u00e8 aumentato in modo significativo rispetto al ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.moas.eu\/it\/i-trend-umanitari-del-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"MOAS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/migrantoffshoreaidstation\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-03T09:23:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-20T09:09:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Blog-Post-Ceci-Beth-34.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christina Lejman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@moas_eu\" \/>\n<meta name=\"twitter:site\" content=\"@moas_eu\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christina Lejman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/i-trend-umanitari-del-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/i-trend-umanitari-del-2022\\\/\"},\"author\":{\"name\":\"Christina Lejman\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/person\\\/be1af883120febb082823c3c74304c69\"},\"headline\":\"I TREND UMANITARI DEL 2022\",\"datePublished\":\"2022-02-03T09:23:01+00:00\",\"dateModified\":\"2022-10-20T09:09:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/i-trend-umanitari-del-2022\\\/\"},\"wordCount\":1144,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/i-trend-umanitari-del-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Blog-Post-Ceci-Beth-34.jpg\",\"articleSection\":[\"Blog\",\"Blog\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.moas.eu\\\/it\\\/i-trend-umanitari-del-2022\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/i-trend-umanitari-del-2022\\\/\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/i-trend-umanitari-del-2022\\\/\",\"name\":\"I TREND UMANITARI DEL 2022 - MOAS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/i-trend-umanitari-del-2022\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/i-trend-umanitari-del-2022\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Blog-Post-Ceci-Beth-34.jpg\",\"datePublished\":\"2022-02-03T09:23:01+00:00\",\"dateModified\":\"2022-10-20T09:09:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/i-trend-umanitari-del-2022\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.moas.eu\\\/it\\\/i-trend-umanitari-del-2022\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/i-trend-umanitari-del-2022\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Blog-Post-Ceci-Beth-34.jpg\",\"contentUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Blog-Post-Ceci-Beth-34.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/i-trend-umanitari-del-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I TREND UMANITARI DEL 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/\",\"name\":\"MOAS\",\"description\":\"MOAS\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.moas.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\",\"name\":\"MOAS\",\"alternateName\":\"Migrant Offshore Aid Station\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/moas-logo-oval.png\",\"contentUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/moas-logo-oval.png\",\"width\":793,\"height\":354,\"caption\":\"MOAS\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/migrantoffshoreaidstation\",\"https:\\\/\\\/x.com\\\/moas_eu\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/migrant-offshore-aid-station\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZHcDS7ePIBW66d3KvX2K0Q\",\"https:\\\/\\\/www.instagram.com\\\/moas_eu\\\/?hl=en\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/person\\\/be1af883120febb082823c3c74304c69\",\"name\":\"Christina Lejman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"caption\":\"Christina Lejman\"},\"url\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/author\\\/clejman\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I TREND UMANITARI DEL 2022 - MOAS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.moas.eu\/it\/i-trend-umanitari-del-2022\/","og_locale":"it_IT","og_type":"article","og_title":"I TREND UMANITARI DEL 2022 - MOAS","og_description":"Nel 2022 si prevede che 274 milioni di persone avranno bisogno di assistenza e protezione umanitaria. Questo dato \u00e8 aumentato in modo significativo rispetto al ... Read more","og_url":"https:\/\/www.moas.eu\/it\/i-trend-umanitari-del-2022\/","og_site_name":"MOAS","article_publisher":"https:\/\/www.facebook.com\/migrantoffshoreaidstation","article_published_time":"2022-02-03T09:23:01+00:00","article_modified_time":"2022-10-20T09:09:32+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Blog-Post-Ceci-Beth-34.jpg","type":"image\/jpeg"}],"author":"Christina Lejman","twitter_card":"summary_large_image","twitter_creator":"@moas_eu","twitter_site":"@moas_eu","twitter_misc":{"Scritto da":"Christina Lejman","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.moas.eu\/it\/i-trend-umanitari-del-2022\/#article","isPartOf":{"@id":"https:\/\/www.moas.eu\/it\/i-trend-umanitari-del-2022\/"},"author":{"name":"Christina Lejman","@id":"https:\/\/www.moas.eu\/#\/schema\/person\/be1af883120febb082823c3c74304c69"},"headline":"I TREND UMANITARI DEL 2022","datePublished":"2022-02-03T09:23:01+00:00","dateModified":"2022-10-20T09:09:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.moas.eu\/it\/i-trend-umanitari-del-2022\/"},"wordCount":1144,"commentCount":0,"publisher":{"@id":"https:\/\/www.moas.eu\/#organization"},"image":{"@id":"https:\/\/www.moas.eu\/it\/i-trend-umanitari-del-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Blog-Post-Ceci-Beth-34.jpg","articleSection":["Blog","Blog"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.moas.eu\/it\/i-trend-umanitari-del-2022\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.moas.eu\/it\/i-trend-umanitari-del-2022\/","url":"https:\/\/www.moas.eu\/it\/i-trend-umanitari-del-2022\/","name":"I TREND UMANITARI DEL 2022 - MOAS","isPartOf":{"@id":"https:\/\/www.moas.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.moas.eu\/it\/i-trend-umanitari-del-2022\/#primaryimage"},"image":{"@id":"https:\/\/www.moas.eu\/it\/i-trend-umanitari-del-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Blog-Post-Ceci-Beth-34.jpg","datePublished":"2022-02-03T09:23:01+00:00","dateModified":"2022-10-20T09:09:32+00:00","breadcrumb":{"@id":"https:\/\/www.moas.eu\/it\/i-trend-umanitari-del-2022\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.moas.eu\/it\/i-trend-umanitari-del-2022\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.moas.eu\/it\/i-trend-umanitari-del-2022\/#primaryimage","url":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Blog-Post-Ceci-Beth-34.jpg","contentUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Blog-Post-Ceci-Beth-34.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.moas.eu\/it\/i-trend-umanitari-del-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.moas.eu\/it\/"},{"@type":"ListItem","position":2,"name":"I TREND UMANITARI DEL 2022"}]},{"@type":"WebSite","@id":"https:\/\/www.moas.eu\/#website","url":"https:\/\/www.moas.eu\/","name":"MOAS","description":"MOAS","publisher":{"@id":"https:\/\/www.moas.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.moas.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.moas.eu\/#organization","name":"MOAS","alternateName":"Migrant Offshore Aid Station","url":"https:\/\/www.moas.eu\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.moas.eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/moas-logo-oval.png","contentUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/moas-logo-oval.png","width":793,"height":354,"caption":"MOAS"},"image":{"@id":"https:\/\/www.moas.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/migrantoffshoreaidstation","https:\/\/x.com\/moas_eu","https:\/\/www.linkedin.com\/company\/migrant-offshore-aid-station","https:\/\/www.youtube.com\/channel\/UCZHcDS7ePIBW66d3KvX2K0Q","https:\/\/www.instagram.com\/moas_eu\/?hl=en"]},{"@type":"Person","@id":"https:\/\/www.moas.eu\/#\/schema\/person\/be1af883120febb082823c3c74304c69","name":"Christina Lejman","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","caption":"Christina Lejman"},"url":"https:\/\/www.moas.eu\/it\/author\/clejman\/"}]}},"_links":{"self":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/49426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/comments?post=49426"}],"version-history":[{"count":1,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/49426\/revisions"}],"predecessor-version":[{"id":51752,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/49426\/revisions\/51752"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/media\/48734"}],"wp:attachment":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/media?parent=49426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/categories?post=49426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/tags?post=49426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}