{"id":49375,"date":"2021-09-29T02:00:11","date_gmt":"2021-09-29T02:00:11","guid":{"rendered":"http:\/\/just2093.temp.domains\/~tqmoaseu\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\/"},"modified":"2022-10-20T09:09:38","modified_gmt":"2022-10-20T09:09:38","slug":"protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio","status":"publish","type":"post","link":"https:\/\/www.moas.eu\/it\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\/","title":{"rendered":"Protezione dei rifugiati: cosa \u00e8 andato storto e cosa si pu\u00f2 fare meglio."},"content":{"rendered":"<p><strong>Segni dei tempi<\/strong><\/p>\n<p>La scorsa settimana non \u00e8 stata facile per i rifugiati.<\/p>\n<p>Luned\u00ec 20 settembre le autorit\u00e0 greche hanno iniziato a spostare i richiedenti asilo sull\u2019isola di Samos da un vecchio e squallido campo a una nuova struttura finanziata dalla UE, denominata \u201cclosed controlled access centre\u2019\u201d. Mentre la Grecia insiste nell\u2019affermare che le condizioni nel nuovo centro siano migliori rispetto al vecchio campo, i gruppi in difesa dei diritti umani hanno sollevato molte preoccupazioni sulla natura detentiva della nuova struttura e l\u2019impatto negativo che avr\u00e0 sulla salute mentale dei suoi residenti.<\/p>\n<p><a href=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/alessio-lin-9PPvnEd92xE-unsplash-scaled.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\" wp-image-39506 alignleft\" src=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/alessio-lin-9PPvnEd92xE-unsplash-scaled.jpg\" alt=\"\" width=\"327\" height=\"218\"><\/a><\/p>\n<p>Marted\u00ec 21 settembre i media hanno riportato che quattro rifugiati, probabilmente Iracheni, sono morti dopo essere rimasti bloccati al confine tra Bielorussia e Polonia, con entrambi i Paesi che rifiutavano di accettarli o di fornire loro assistenza. Nella stessa giornata, sono state diffuse immagini di rifugiati frustati da guardie di frontiera a cavallo nella frontiera meridionale degli Stati Uniti, , mentre l&#8217;amministrazione Biden ha lanciato un\u2019operazione di espulsione di massa per i richiedenti asilo provenienti da Haiti.<\/p>\n<p>Mercoled\u00ec 22 settembre abbiamo appreso che un certo numero di rifugiati eritrei in Egitto era stato arrestato, picchiato e incarcerato per anni senza accesso ai servizi di protezione garantiti dall\u2019UNHCR, rischiando di essere forzatamente riportato nel proprio paese di origine, dove avrebbe rischiato di subire ulteriori abusi &nbsp;da parte del governo autoritario.<\/p>\n<p>Nel corso della settimana sono emerse con chiarezza le strategie adottate dagli Stati per ostacolare l&#8217;arrivo di Afgani in fuga dai Talebani: chiusura delle frontiere in Pakistan, minacce di deportazione in Iran, costruzione di un nuovo muro come frontiera orientale in Turchia e la militarizzazione della frontiera greca, che include la costruzione di torrette di guardia e centri di detenzione, insieme al dispiegamento di telecamere termiche, agenti di polizia, forze militari, droni e un dirigibile di sorveglianza.<\/p>\n<p><strong>Un attimo di speranza <\/strong><\/p>\n<p>Non sarebbe dovuta andare cos\u00ec. Cinque anni fa, in seguito in Europa di rifugiati dal Medio Oriente, dall&#8217;Africa e dall&#8217;Asia, la comunit\u00e0 internazionale decise di affrontare il fenomeno migratorio in modo pi\u00f9 efficace ed equo. &nbsp;Si tenne un incontro al vertice che si concluse con una dichiarazione presso l&#8217;Assemblea Generale delle Nazioni Unite a New York.<\/p>\n<p>Fu istituito un \u201cquadro di risposta globale ai rifugiati\u201d o CRRF (Comprehensive Refugee Response Framework \u2013 ndt ) per rendere operativi tali principi, mentre due anni dopo la maggioranza degli stati membri delle Nazioni Unite approv\u00f2 sia <em>il Global Compact on Refugees<\/em> (Patto Globale sui Rifugiati) sia <em>il &nbsp;Global Compact on Migration <\/em>(Patto Globale sulla Migrazione), entrambi intesi a migliorare la protezione e il benessere delle persone migranti e consentire agli Stati di affrontare la questione dei movimenti transfrontalieri in maniera coerente.<\/p>\n<p>Alla fine del 2019 pi\u00f9 di 2.000 rappresentanti di Stati, agenzie delle Nazioni Unite, ONG e organizzazioni della societ\u00e0 civile, si riunirono a Ginevra per assumere impegni specifici in relazione all\u2019azione che avrebbero intrapreso per realizzare gli obiettivi del <em>Global Compact<\/em> sui Rifugiati.<\/p>\n<p>L\u2019UNHCR, che aveva giocato un ruolo centrale in questo susseguirsi di eventi tra il 2015 e il 2019, espresse un grande ottimismo rispetto agli obiettivi. Il <em>Global Compact<\/em> &nbsp;e il CRRF costituivano \u201cuna svolta\u201d, \u201cun cambiamento di paradigma\u201d, \u201cuna pietra miliare per la solidariet\u00e0 globale e per la protezione dei rifugiati\u201d e addirittura \u201cun piccolo miracolo\u201d. E in merito al <em>Global Refugee Forum<\/em> si disse che era \u201cun\u2019opportunit\u00e0 unica per definire gli elementi necessari ad accelerare la nostra trasformazione di risposta globale ai flussi di rifugiati\u201d.<\/p>\n<p>Ma, come hanno dimostrato gli eventi della scorsa settimana, tutte queste speranze e aspettative non si sono realizzate. Ben lungi dal testimoniare un rafforzamento della solidariet\u00e0 globale, l\u2019evidenza suggerisce che la risposta della comunit\u00e0 internazionale la questione relativa ai rifugiati si \u00e8 in realt\u00e0 mossa in direzione opposta.<\/p>\n<p><strong>Tendenze negative <\/strong><\/p>\n<p>Per spiegare questo dilemma bisogna prendere in considerazione diversi fattori.<\/p>\n<p>Per prima cosa, negli ultimi cinque anni, la <em>governance<\/em> globale e la cooperazione internazionale si sono indebolite: una tendenza dimostrata assai chiaramente dall\u2019incapacit\u00e0 del Consiglio delle Nazioni Unite di prevenire e far cessare conflitti armati, evitando che le persone siano costrette a lasciare la loro patria o permettendo loro di rientrare nei loro paesi d&#8217;origine.<\/p>\n<p>In secondo luogo, la nozione stessa di \u201ccomunit\u00e0 internazionale\u201d e di \u201cNazioni Unite\u201d \u00e8 stata messa in discussione dalla crescente influenza di Stati che rivelano ideologie nazionalistiche e politiche unilaterali, inclusi, tra gli altri, la Cina, l&#8217;Ungheria, l&#8217;India, la Russia, la Turchia e gli Stati Uniti sotto il presidente Trump. Non serve dire che tali governi hanno dimostrato scarso rispetto nei confronti delle leggi internazionali, dei principi umanitari e delle norme sulle quali si basa il regime internazionale di protezione dei rifugiati.<\/p>\n<p>In terzo luogo, i Paesi del Nord del mondo hanno dato un pessimo esempio, esternalizzando le loro politiche in materia di immigrazione e asilo e adottando misure al di l\u00e0 dei propri confini per garantire che i rifugiati fossero confinati nei paesi meno sviluppati.<\/p>\n<p>In quarto luogo, da quando \u00e8 stato istituito il <em>Global Compact<\/em> dei Rifugiati, la comunit\u00e0 internazionale ha affrontato nuove sfide quali il cambiamento climatico, e la pandemia di COVID-19. A fronte di un incremento del numero di rifugiati a causa dei cambiamenti climatici, il COVID-19 ha, invece, spinto molti Stati a chiudere le frontiere ai rifugiati e ad altri cittadini stranieri, aggravando la situazione gi\u00e0 precaria.<\/p>\n<p>Infine, sebbene l\u2019UNHCR abbia una speciale responsabilit\u00e0 nella protezione dei rifugiati a livello mondiale, non \u00e8 riuscita a far fronte a queste profonde tendenze negative. L&#8217;organizzazione \u00e8 fortemente dipendente dal sostegno finanziario e diplomatico degli Stati. \u00c8 stata intimidita e cooptata da governi per i quali il benessere dei rifugiati non \u00e8 una priorit\u00e0. E ha posto un grado irrealistico di fiducia nel branding, nel marketing e nelle celebrit\u00e0 come mezzi per mantenere la sua influenza sulla comunit\u00e0 internazionale.<\/p>\n<p><strong>La strada da percorrere <\/strong><\/p>\n<p>Che cosa si pu\u00f2 fare dunque di fronte a questa situazione cos\u00ec precaria? Non esistono risposte facili a questa domanda e non dovremmo essere affatto sorpresi se la situazione dei rifugiati nel mondo continuer\u00e0 a deteriorarsi nei mesi e negli anni a venire.<\/p>\n<p>Per evitare un esito cos\u00ec nefasto, chi opera in questo settore deve far si che quei politici che mantengono un impegno nei confronti dei principi umanitari e del diritto svolgano un ruolo di guida nel campo della protezione dei rifugiati.<\/p>\n<p>Dobbiamo inoltre diffondere e valorizzare l\u2019impegno di quei paesi che hanno dato un buon esempio al resto del mondo, sia che si tratti della politica di \u201cporte aperte\u201d perseguita dall&#8217;Uganda, del ruolo pionieristico del Canada in relazione al reinsediamento dei rifugiati sponsorizzato dalla comunit\u00e0, o della recente decisione della Colombia di concedere il diritto di residenza ai rifugiati venezuelani.<\/p>\n<p>Dobbiamo, inoltre, ricordare agli Stati gli obblighi che hanno liberamente assunto nei confronti dei rifugiati con l\u2019obiettivo di affrontare i movimenti transfrontalieri delle persone in modo coerente, cooperativo ed equo.<\/p>\n<p>Dobbiamo impegnarci e mobilitare il sostegno della pi\u00f9 ampia rete possibile di persone che sono in grado di influenzare positivamente la vita dei rifugiati: membri della magistratura e assemblee legislative; organizzazioni religiose e membri della comunit\u00e0 imprenditoriale; accademici e artisti, nonch\u00e9 societ\u00e0 civile e associazioni di volontariato.<\/p>\n<p>Dopo la fine dell&#8217;amministrazione Trump, l&#8217;UNHCR ha assunto una posizione pi\u00f9 assertiva in relazione alle politiche di asilo restrittive ed esternalizzate del \u201cNord Globale\u201d, muovendo delle critiche al modo in cui paesi come l&#8217;Australia, il Regno Unito e gli Stati Uniti trattano i rifugiati. Dobbiamo applaudire questi interventi e incoraggiare l&#8217;organizzazione a continuare su questa strada.<\/p>\n<p>Infine, e per concludere questa prognosi un po&#8217; cupa con una nota positiva, dobbiamo garantire che le voci degli stessi rifugiati e il numero crescente di organizzazioni da essi istituite, siano in grado di svolgere un ruolo centrale nel discorso sull&#8217;asilo e la protezione. Per parafrasare ci\u00f2 che hanno detto i rifugiati con crescente forza e chiarezza, non ci dovrebbero essere discussioni su di loro, senza di loro.<\/p>\n<p><strong>Jeff Crisp&nbsp;<\/strong><\/p>\n<p><strong>Se sei interessato al lavoro di MOAS e dei nostri partner, seguici sui social media, iscriviti alla nostra newsletter e condividi i nostri contenuti. Puoi anche contattarci in qualsiasi momento tramite info@moas.eu. Se vuoi sostenere le nostre operazioni, ti preghiamo di donare ci\u00f2 che puoi su&nbsp;<\/strong><a href=\"https:\/\/www.moas.eu\/donate\/\"><strong>www.moas.eu\/donate\/<\/strong><\/a><\/p>\n\n\n<p class=\"wp-block-paragraph\"><em>Traduzione di Alessandra Sisti<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Segni dei tempi La scorsa settimana non \u00e8 stata facile per i rifugiati. Luned\u00ec 20 settembre le autorit\u00e0 greche hanno iniziato a spostare i richiedenti &#8230; <a title=\"Protezione dei rifugiati: cosa \u00e8 andato storto e cosa si pu\u00f2 fare meglio.\" class=\"read-more\" href=\"https:\/\/www.moas.eu\/it\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\/\" aria-label=\"Per saperne di pi\u00f9 su Protezione dei rifugiati: cosa \u00e8 andato storto e cosa si pu\u00f2 fare meglio.\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"nf_dc_page":"","footnotes":""},"categories":[19],"tags":[],"class_list":["post-49375","post","type-post","status-publish","format-standard","hentry","category-blog-it","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Protezione dei rifugiati: cosa \u00e8 andato storto e cosa si pu\u00f2 fare meglio. - MOAS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.moas.eu\/it\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Protezione dei rifugiati: cosa \u00e8 andato storto e cosa si pu\u00f2 fare meglio. - MOAS\" \/>\n<meta property=\"og:description\" content=\"Segni dei tempi La scorsa settimana non \u00e8 stata facile per i rifugiati. Luned\u00ec 20 settembre le autorit\u00e0 greche hanno iniziato a spostare i richiedenti ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.moas.eu\/it\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\/\" \/>\n<meta property=\"og:site_name\" content=\"MOAS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/migrantoffshoreaidstation\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-29T02:00:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-20T09:09:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/alessio-lin-9PPvnEd92xE-unsplash-scaled.jpg\" \/>\n<meta name=\"author\" content=\"Christina Lejman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@moas_eu\" \/>\n<meta name=\"twitter:site\" content=\"@moas_eu\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christina Lejman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\\\/\"},\"author\":{\"name\":\"Christina Lejman\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/person\\\/be1af883120febb082823c3c74304c69\"},\"headline\":\"Protezione dei rifugiati: cosa \u00e8 andato storto e cosa si pu\u00f2 fare meglio.\",\"datePublished\":\"2021-09-29T02:00:11+00:00\",\"dateModified\":\"2022-10-20T09:09:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\\\/\"},\"wordCount\":1388,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/alessio-lin-9PPvnEd92xE-unsplash-scaled.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.moas.eu\\\/it\\\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\\\/\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\\\/\",\"name\":\"Protezione dei rifugiati: cosa \u00e8 andato storto e cosa si pu\u00f2 fare meglio. - MOAS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/alessio-lin-9PPvnEd92xE-unsplash-scaled.jpg\",\"datePublished\":\"2021-09-29T02:00:11+00:00\",\"dateModified\":\"2022-10-20T09:09:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.moas.eu\\\/it\\\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/alessio-lin-9PPvnEd92xE-unsplash-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/alessio-lin-9PPvnEd92xE-unsplash-scaled.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Protezione dei rifugiati: cosa \u00e8 andato storto e cosa si pu\u00f2 fare meglio.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/\",\"name\":\"MOAS\",\"description\":\"MOAS\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.moas.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\",\"name\":\"MOAS\",\"alternateName\":\"Migrant Offshore Aid Station\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/moas-logo-oval.png\",\"contentUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/moas-logo-oval.png\",\"width\":793,\"height\":354,\"caption\":\"MOAS\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/migrantoffshoreaidstation\",\"https:\\\/\\\/x.com\\\/moas_eu\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/migrant-offshore-aid-station\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZHcDS7ePIBW66d3KvX2K0Q\",\"https:\\\/\\\/www.instagram.com\\\/moas_eu\\\/?hl=en\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/person\\\/be1af883120febb082823c3c74304c69\",\"name\":\"Christina Lejman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"caption\":\"Christina Lejman\"},\"url\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/author\\\/clejman\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Protezione dei rifugiati: cosa \u00e8 andato storto e cosa si pu\u00f2 fare meglio. - MOAS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.moas.eu\/it\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\/","og_locale":"it_IT","og_type":"article","og_title":"Protezione dei rifugiati: cosa \u00e8 andato storto e cosa si pu\u00f2 fare meglio. - MOAS","og_description":"Segni dei tempi La scorsa settimana non \u00e8 stata facile per i rifugiati. Luned\u00ec 20 settembre le autorit\u00e0 greche hanno iniziato a spostare i richiedenti ... Read more","og_url":"https:\/\/www.moas.eu\/it\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\/","og_site_name":"MOAS","article_publisher":"https:\/\/www.facebook.com\/migrantoffshoreaidstation","article_published_time":"2021-09-29T02:00:11+00:00","article_modified_time":"2022-10-20T09:09:38+00:00","og_image":[{"url":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/alessio-lin-9PPvnEd92xE-unsplash-scaled.jpg","type":"","width":"","height":""}],"author":"Christina Lejman","twitter_card":"summary_large_image","twitter_creator":"@moas_eu","twitter_site":"@moas_eu","twitter_misc":{"Scritto da":"Christina Lejman","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.moas.eu\/it\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\/#article","isPartOf":{"@id":"https:\/\/www.moas.eu\/it\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\/"},"author":{"name":"Christina Lejman","@id":"https:\/\/www.moas.eu\/#\/schema\/person\/be1af883120febb082823c3c74304c69"},"headline":"Protezione dei rifugiati: cosa \u00e8 andato storto e cosa si pu\u00f2 fare meglio.","datePublished":"2021-09-29T02:00:11+00:00","dateModified":"2022-10-20T09:09:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.moas.eu\/it\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\/"},"wordCount":1388,"commentCount":0,"publisher":{"@id":"https:\/\/www.moas.eu\/#organization"},"image":{"@id":"https:\/\/www.moas.eu\/it\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/alessio-lin-9PPvnEd92xE-unsplash-scaled.jpg","articleSection":["Blog"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.moas.eu\/it\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.moas.eu\/it\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\/","url":"https:\/\/www.moas.eu\/it\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\/","name":"Protezione dei rifugiati: cosa \u00e8 andato storto e cosa si pu\u00f2 fare meglio. - MOAS","isPartOf":{"@id":"https:\/\/www.moas.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.moas.eu\/it\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\/#primaryimage"},"image":{"@id":"https:\/\/www.moas.eu\/it\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/alessio-lin-9PPvnEd92xE-unsplash-scaled.jpg","datePublished":"2021-09-29T02:00:11+00:00","dateModified":"2022-10-20T09:09:38+00:00","breadcrumb":{"@id":"https:\/\/www.moas.eu\/it\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.moas.eu\/it\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.moas.eu\/it\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\/#primaryimage","url":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/alessio-lin-9PPvnEd92xE-unsplash-scaled.jpg","contentUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/alessio-lin-9PPvnEd92xE-unsplash-scaled.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.moas.eu\/it\/protezione-dei-rifugiati-cosa-e-andato-storto-e-cosa-si-puo-fare-meglio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.moas.eu\/it\/"},{"@type":"ListItem","position":2,"name":"Protezione dei rifugiati: cosa \u00e8 andato storto e cosa si pu\u00f2 fare meglio."}]},{"@type":"WebSite","@id":"https:\/\/www.moas.eu\/#website","url":"https:\/\/www.moas.eu\/","name":"MOAS","description":"MOAS","publisher":{"@id":"https:\/\/www.moas.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.moas.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.moas.eu\/#organization","name":"MOAS","alternateName":"Migrant Offshore Aid Station","url":"https:\/\/www.moas.eu\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.moas.eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/moas-logo-oval.png","contentUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/moas-logo-oval.png","width":793,"height":354,"caption":"MOAS"},"image":{"@id":"https:\/\/www.moas.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/migrantoffshoreaidstation","https:\/\/x.com\/moas_eu","https:\/\/www.linkedin.com\/company\/migrant-offshore-aid-station","https:\/\/www.youtube.com\/channel\/UCZHcDS7ePIBW66d3KvX2K0Q","https:\/\/www.instagram.com\/moas_eu\/?hl=en"]},{"@type":"Person","@id":"https:\/\/www.moas.eu\/#\/schema\/person\/be1af883120febb082823c3c74304c69","name":"Christina Lejman","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","caption":"Christina Lejman"},"url":"https:\/\/www.moas.eu\/it\/author\/clejman\/"}]}},"_links":{"self":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/49375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/comments?post=49375"}],"version-history":[{"count":1,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/49375\/revisions"}],"predecessor-version":[{"id":49376,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/49375\/revisions\/49376"}],"wp:attachment":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/media?parent=49375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/categories?post=49375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/tags?post=49375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}