{"id":49351,"date":"2021-08-05T08:52:02","date_gmt":"2021-08-05T08:52:02","guid":{"rendered":"http:\/\/just2093.temp.domains\/~tqmoaseu\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\/"},"modified":"2022-10-20T09:09:42","modified_gmt":"2022-10-20T09:09:42","slug":"podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs","status":"publish","type":"post","link":"https:\/\/www.moas.eu\/it\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\/","title":{"rendered":"Podcast &#8211; L\u2019importanza di Vie Sicure e legali. Intervista a Lord Dubs"},"content":{"rendered":"<p><a href=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Twitter-12.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-large wp-image-39258\" src=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Twitter-12-1024x576.jpg\" alt=\"Twitter (12)\" width=\"1024\" height=\"576\" \/><\/a><\/p>\n<p><strong><em>Benvenuti nel podcast di MOAS. Oggi parliamo di #VieSicureeLegali con Lord Alf Dubs, uno dei bambini Cechi salvati dal regime nazista attraverso i Kindertransport e da allora attivista per i diritti dei rifugiati e dei richiedenti asilo. Nel corso della sua lunga carriera nel settore pubblico e nell&#8217;advocacy nel Regno Unito, la sua dedizione verso i temi della migrazione e la promozione di vie sicure e legali ha avuto eco nelle politiche governative e nelle campagne di advocacy del Paese. Lord Dubs continua a galvanizzare il sostegno ai richiedenti asilo, ai rifugiati e ai minori non accompagnati che sono attualmente trascurati dalla politica del governo. MOAS \u00e8 assolutamente onorata di parlare con Lord Dubs di vie sicure e legali.<\/em><\/strong><\/p>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" title=\"Audioboom player\" width=\"100%\" height=\"300\" src=\"https:\/\/embeds.audioboom.com\/posts\/7918720\/embed\/v4#?secret=5JSzmKCUQ6\" data-secret=\"5JSzmKCUQ6\" frameborder=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<p><strong>MOAS: <\/strong>Sono onorata di poter parlare con lei della sua esperienza e competenza in materia di migrazione e vie sicure e legali. \u00a0Lei \u00e8 stato determinante nella campagna per il sostegno ai rifugiati e, naturalmente, nello sponsorizzare un emendamento alla legge sull\u2019immigrazione del governo nel 2016 che ha permesso a 3000 bambini rifugiati non accompagnati di accedere al sostegno nel Regno Unito. Poich\u00e9 il pendolo dell\u2019opinione pubblica in termini di migrazione sembra spostarsi sempre di pi\u00f9 verso destra, sar\u00e0 un piacere poter parlare con lei riguardo a ci\u00f2 che \u00e8 necessario fare per difendere i diritti dei rifugiati e promuovere rotte migratorie sicure.<\/p>\n<p>Potrebbe dare a MOAS e agli ascoltatori una breve panoramica della sua storia personale e, in particolare, della sua esperienza nel campo della migrazione?<\/p>\n<blockquote><p><strong>Lord Dubs: <\/strong>Potrebbe volerci addirittura un\u2019ora, ma la racconter\u00f2 brevemente. Sono arrivato in Gran Bretagna con il Kindertransport da Praga nel luglio 1939, ci\u00f2 significa che sono arrivato come bambino rifugiato non accompagnato. Mio padre era ebreo e mia madre no, quindi lui se ne and\u00f2 quando i tedeschi occuparono Praga nel marzo 1939 mentre a mia madre fu negato il permesso di partire, ecco perch\u00e9 mi fece salire sul Kindertranport.<br \/>\nPrima di allora, l\u2019occupazione tedesca implicava il mettere la fotografia di Hitler nei nostri libri di scuola e cosi via. Mia madre mi ha salutato alla stazione di Praga in cui c\u2019erano soldati con la svastica e genitori in ansia perch\u00e9 non sapevano se avrebbero rivisto i loro figli; nel treno eravamo 150.<br \/>\nCi sono voluti due giorni per arrivare nel Regno Unito e quando siamo giunti al confine olandese dopo 24 ore, i pi\u00f9 grandi hanno applaudito perch\u00e9 eravamo fuori dalla portata dei nazisti e, per quanto mi riguarda, sapevo che era qualcosa di significativo, ma io non ho applaudito. Non capisco il perch\u00e9, ero alla ricerca di mulini a vento e zoccoli di legno, esattamente tutto ci\u00f2 che sapevo dell\u2019Olanda. Ad ogni modo, siamo arrivati dall\u2019Olanda a Liverpool Street. Io ero forse il pi\u00f9 giovane sul treno, come ho detto avevo circa 6 anni, ma sono stato anche fortunato perch\u00e9 pi\u00f9 della met\u00e0 dei ragazzi sul treno non aveva una famiglia ad aspettarli in stazione, mentre mio padre era l\u00e0, alla stazione di Liverpool Street. Questo \u00e8 stato il mio viaggio verso il Regno Unito.<\/p><\/blockquote>\n<p><strong>MOAS: <\/strong>Per quanto riguarda la sua esperienza effettiva nel campo della migrazione, come precedente amministratore delegato del Refugee Council, alla sua organizzazione \u00e8 stato chiesto di facilitare il reinsediamento dei bosniaci perseguitati nei campi di concentramento serbi: questi progetti hanno provocato lo stesso tipo di tossicit\u00e0 e narrazioni xenofobe palpabili oggi? In caso contrario, quali pensa che siano i fattori che contribuiscono ad un tale cambiamento negli atteggiamenti dell\u2019opinione pubblica odierna?<\/p>\n<blockquote><p><strong>Lord Dubs<\/strong>: Penso che questa sia una domanda davvero molto interessante. Quando ero al Refugee Council, a noi e alla Croce Rossa \u00e8 stato chiesto, con un preavviso ragionevolmente breve, di organizzare le strutture di accoglienza per diverse migliaia di bosniaci che erano stati nei campi di concentramento serbi. \u00c8 stato un grande giorno quando sono arrivati all\u2019aeroporto di Stanstead e met\u00e0 dei media di tutto il mondo erano l\u00e0 ed io ho dovuto impedire loro di avere accesso facile ai bosniaci appena arrivati, ad accezione di coloro che era disponibili a parlare con i media: queste persone avevano vissuto esperienze terribili, alcuni di loro volevano parlarne per superare l\u2019accaduto, mentre altri non avevano intenzione di farlo, non allora e forse mai. Comunque, non c\u2019\u00e8 stata nessuna opposizione a questo, nonostante fosse un programma governativo e ci dovessimo muovere molto in fretta: allora, nessuno poteva accusarmi di essere antigovernativo (io ero d\u2019accordo col programma). C\u2019\u00e8 stata una certa resistenza locale perch\u00e9 alcune persone non pensavano che avrebbe funzionato nelle loro aree, dato che avevamo allestito strutture di accoglienza in varie parti del Paese, tuttavia credo che nel complesso abbia funzionato piuttosto bene. Una delle cose che abbiamo fatto a Newcastle, \u00e8 stata un\u2019idea del Refugee Council mentre ero l\u00ec, \u00e8 stato organizzare un open day dove abbiamo accolto consiglieri locali, assistenti sociali, medici, insegnanti, polizia e tutta la comunit\u00e0 per incontrare i rifugiati: penso che sia stato utile perch\u00e9 significava includere tutti loro nel programma governativo.<br \/>\nComplessivamente, la posizione nazionale non era cos\u00ec ostile come lo divenne in seguito nei confronti di altri rifugiati. Credo, ma questa \u00e8 la mia spiegazione, che sia dovuto ad alcune fotografie che mostravano le terribili condizioni dei campi di concentramento serbi raffiguranti persone emaciate, e penso che la gente abbia considerato ci\u00f2 che questi rifugiati avevano affrontato e per questo abbia deciso di accoglierli. Ritengo che un secondo motivo sia stata la decisione del governo di stabilire un numero ben definito di persone da accogliere, ci\u00f2 significava non trovarsi di fronte ad un impegno a tempo indeterminato.<\/p><\/blockquote>\n<p><strong>MOAS: <\/strong>cosa pensa che si possa fare per combattere le narrazioni presenti nei media e, talvolta, nella politica del governo, che criminalizzano apertamente i richiedenti asilo e i rifugiati? In senso pratico, cosa possiamo fare noi, come ONG e come persone, per cercare di combattere queste narrazioni?<\/p>\n<blockquote><p><strong>Lord Dubs<\/strong>: Bene, rispondo prendendo spunto da ci\u00f2 che abbiamo fatto noi. Prima di tutto, ripeto sempre che, quando diciamo o facciamo qualcosa, dobbiamo tenere a mente che l\u2019opinione pubblica \u00e8 ci\u00f2 che dobbiamo persuadere. Il motivo principale per cui la legislazione, l\u2019emendamento, \u00e8 stato approvato, \u00e8 perch\u00e9 l\u2019opinione pubblica ha iniziato a prestare attenzione. Una delle cose che ha aiutato, simile a ci\u00f2 che ha aiutato con i bosniaci, sono state le immagini scioccanti di persone che annegavano nel Mediterraneo, \u00e8 stata l\u2019immagine del corpo di Alan Kurdi annegato riverso su una spiaggia. Un\u2019altra cosa che penso dobbiamo sempre spiegare \u00e8 da dove sono fuggite queste persone. Loro sono fuggiti dalla guerra, dalla persecuzione. Voglio dire, parlo sempre di un ragazzo siriano che ha detto di aver visto suo padre saltare in aria davanti a lui a causa di una bomba ad Aleppo, a Damasco. Penso che si debba raccontare da cosa stanno scappando e perch\u00e9 dovremmo essere umani nell\u2019accoglierli. Non c\u2019\u00e8 niente di sbagliato nel dire di essere alla ricerca di una vita migliore, mai, ma se le persone dicono semplicemente che stanno cercando una vita migliore questo non li rende rifugiati ai sensi della Convenzione di Ginevra. Quello che dobbiamo spiegare al nostro pubblico \u00e8 ci\u00f2 che queste persone hanno passato, le loro esperienze e sofferenze, e come noi possiamo dar loro sicurezza, conforto, un senso di famiglia e cosi via. L\u2019altra cosa a cui penso \u00e8 quella di cercare a livello locale di organizzare eventi, che si tratti di sport o altro, \u00a0che li coinvolgano insieme alla gente e con i bambini del posto.<br \/>\nIn conclusione, odio questa parola ormai normalizzata, ma penso che il problema principale sia che, a volte, le persone vedono i rifugiati quasi come un museo, invece si tratta di esseri umani che desiderano condurre una vita normale, come la maggior parte delle persone. Dobbiamo normalizzare la loro integrazione attraverso lo sport ed altre attivit\u00e0. Localmente, c\u2019\u00e8 un\u2019organizzazione che allestisce una volta a settimana una giornata per i rifugiati in cui molti di loro distribuiscono cibo alla comunit\u00e0, sono state organizzate lezioni di inglese ed altre attivit\u00e0. Questi sono eventi creati per aiutarli. Ma la cosa davvero fondamentale \u00e8 normalizzare l\u2019integrazione e fare in modo che le comunit\u00e0 locali siano accoglienti, specialmente a scuola. Quindi ci sono una serie di azioni che possono essere intraprese, soprattutto da parte delle comunit\u00e0 locali.<\/p><\/blockquote>\n<p><strong>MOAS: <\/strong>Si, sicuramente. In questo momento stiamo cercando di concentrare la campagna #VieSicureELegali sull\u2019educazione per far capire alle persone la differenza tra richiedente asilo e rifugiato. Penso che nei media e nella politica governativa si senta molto parlare di asilo, ed \u00e8 importante tornare alla radice del motivo per cui le persone lasciano il loro paese di origine ed educare il pubblico a riguardo perch\u00e9, come ha detto lei, \u00e8 proprio ci\u00f2 che ha bisogno di sapere.<\/p>\n<blockquote><p><strong>Lord Dubs: <\/strong>D\u2019altra parte, se posso collegarmi alla sua domanda precedente, quando sono arrivati i bosniaci, il governo voleva che venissero. Il governo aveva detto che lo avrebbe fatto succedere. Hanno chiesto aiuto a due organizzazioni e noi possiamo affermare di aver sempre ricevuto pieno sostegno da parte del governo. Oggi invece abbiamo l\u2019opposizione del governo. E credo che questo sia vero per molti paesi europei: i ministri lanciano segnali negativi. E se ministri, leader di comunit\u00e0, chiedono restrizioni e affermano che non vogliono rifugiati, questo manda un segnale di ostilit\u00e0 alle comunit\u00e0 locali nei loro confronti. Penso che il minimo che possiamo aspettarci sia che il governo, le persone importanti nei nostri paesi, diano effettivamente messaggi pi\u00f9 positivi e non messaggi ostili.<\/p><\/blockquote>\n<p><strong>MOAS: <\/strong>si, esattamente. E questo porta alla mia prossima domanda. L\u2019emendamento Dubs, implementato nel 2016, \u00e8 stata una componente estremamente vitale nel disegno di legge sull\u2019integrazione. Mi chiedevo come l\u2019emendamento sia stato implementato e il tipo di risposta ricevuta dal governo e dal pubblico, e come pensa che possa essere d\u2019esempio per vie sicure e legali di migrazione da implementare nel futuro?<\/p>\n<blockquote><p><strong>Lord Dubs: <\/strong>Questa \u00e8 una domanda piuttosto complicata; senza entrare troppo nel dettaglio, ci\u00f2 che \u00e8 successo \u00e8 stato apprendere che nel 2016, come dicevi tu, secondo Save the Children, in Europa c\u2019erano 95.000 bambini rifugiati non accompagnati. Numero scioccante. Secondo l\u2019Interpol, 10,000 di loro erano effettivamente scomparsi. Quando un bambino scompare in altri paesi, tutti lo cercano disperatamente. Qui abbiamo fatto sparire pi\u00f9 di 10.000 persone. Quindi ho presentato questo emendamento e al governo non \u00e8 piaciuto. Theresa May, che allora era il ministro degli interni, mi ha invitato per un incontro e ha detto che avrebbe voluto che ritirassi l\u2019emendamento. Al che io ho risposto \u201cperch\u00e9?\u201d, e lei ha detto \u201cbeh, se prendiamo questi bambini, altri seguiranno.\u201d E io ho replicato \u201cnon possiamo voltare le spalle ai giovani che dormono nella giungla di Calais, nelle isole greche o altrove nel Mediterraneo. Non possiamo voltare loro le spalle. Sono vulnerabili alla tratta, alla criminalit\u00e0, alla prostituzione, alla droga, a ogni genere di cosa.\u201d. Quindi ci siamo lasciati.<br \/>\nComunque, per farla breve, l\u2019emendamento \u00e8 stato approvato a larga maggioranza dai Lord, \u00e8 stato leggermente sconfitto dai Commons, ma \u00e8 stato rimandato ai Lord. E mentre questo accadeva i media si sono improvvisamente svegliati. E come ho detto prima, c\u2019erano queste terribili fotografie di persone che annegavano nel Mediterraneo, di Alan Kurdi. L\u2019opinione pubblica ha iniziato a svegliarsi e si sono formati gruppi locali che dicevano di accogliere i rifugiati nelle aree locali. E credo che questo abbia dato un po\u2019 di tono ed \u00e8 cos\u00ec che Theresa May ha proposto di accettare l\u2019emendamento. Ora, penso che questo sia stato il peso dell\u2019opinione pubblica esercitato nei collegi elettorali locali sui governi che sostengono i parlamentari. Ho sempre detto che non dobbiamo farne una cosa politica. Questa causa dei bambini rifugiati, dovrebbe attraversare lo spettro. Ma ovviamente avevamo meno conservatori di quanti altri partiti ci sostenessero. E penso che sia stata esercitata molta pressione sui parlamentari e il governo ha successivamente ritenuto che avrebbero potuto perdere gli emendamenti, quindi hanno ceduto. Inizialmente il governo aveva un numero di 3000, una cifra molto piccola in realt\u00e0, ma in ogni caso dovevamo discutere cosa fare e cosa avremmo potuto ottenere. Per varie ragioni tecnico-parlamentari siamo dovuti restare sui 3000 e lasciare il numero indeterminato. E poi il governo ha proposto di limitare il numero a 480. Al che io ho chiesto la motivazione e la riposta \u00e8 stata che non c\u2019erano sufficienti autorit\u00e0 locali che potessero fornire famiglie affidatarie disposte ad accogliere i bambini.<\/p>\n<p>Il modello funziona in questo modo: se i ragazzi hanno fino a 16 anni, possono essere ospitati da famiglie affidatarie \u2013 il modello del Regno Unito. Noi abbiamo iniziato a contestare questo modello dicendo che avremmo potuto trovare altre autorit\u00e0 locali molto pi\u00f9 rapidamente. Abbiamo fatto un sondaggio e abbiamo trovato 15\/16 altri posti. Ma il governo ha insistito per mantenere basso quel numero. C\u2019era un ulteriore emendamento che aveva a che fare con il trattato di Dublino in base al quale un bambino rifugiato in un paese dell\u2019Unione Europea poteva chiedere di ricongiungersi ad un altro rifugiato: in questo modo un ragazzo siriano in Francia avrebbe potuto chiedere di ricongiungersi ad uno zio o ad un fratello nel Regno Unito.<\/p>\n<p>Il problema \u00e8 stato quando la Gran Bretagna ha preso la decisione disastrosa di lasciare l&#8217;UE. L&#8217;emendamento a un altro disegno di legge, che ho approvato, prevede che la Gran Bretagna dovrebbe continuare a negoziare i termini dell&#8217;accordo di Dublino anche dopo aver lasciato l&#8217;UE &#8211; vale a dire termini di ricongiungimento familiare. Questo \u00e8 un disastro perch\u00e9 ora non c\u2019\u00e8 nemmeno un ricorso legale adeguato per le famiglia. C\u2019\u00e8 un altro disegno di legge in parlamento chiamato Borders Bill: possiamo fare del nostro meglio per emendarlo, vedere se possiamo salvaguardarlo, in particolare per le famiglie perch\u00e9 credo che siano pi\u00f9 numerose rispetto a chi non ne ha. Quindi noi continueremo su questo fronte a sfidare il governo, e il modo migliore per farlo \u00e8 spostare emendamenti nella legislazione del governo per proteggere i diritti dei bambini che hanno bisogno di venire qui.<\/p><\/blockquote>\n<p><strong>MOAS: <\/strong>le ONG e i cittadini come possono sostenere i minori non accompagnati?<\/p>\n<blockquote><p><strong>Lord Dubs: <\/strong>Dico sempre che i cittadini dovrebbero far sentire la loro voce. Vale a dire che dovrebbero parlare con i membri del loro parlamento e con i consiglieri locali. I gruppi religiosi possono essere di aiuto, cos\u00ec come qualsiasi altra organizzazione di cui le persone sono membri, che si tratti di sindacati o imprese, dovrebbero far sentire la voce collettiva e questa voce dovrebbe essere accogliente: questo \u00e8 davvero importante. E, naturalmente, a livello locale se una voce pu\u00f2 essere ascoltata pu\u00f2 avere pi\u00f9 risonanza se \u00e8 legata ai ragazzi che frequentano le scuole locali. Quindi s\u00ec, penso che sia cruciale che quelli di noi che credono in ci\u00f2 per cui si battono dovrebbero far sentire la propria voce e far sapere agli altri che queste sono le politiche giuste da seguire.<\/p><\/blockquote>\n<p><strong>MOAS: <\/strong>Questo mi porta a porgere la domanda finale, una domanda generale sui percorsi sicuri e legali per i richiedenti asilo. Ora, MOAS \u00e8 stata la prima ONG a svolgere attivit\u00e0 di ricerca e soccorso nel Mediterraneo e, da allora, abbiamo concentrato le nostre energie per portare avanti una campagna per l\u2019implementazione di vie sicure e legali: vogliamo far capire alle persone che cosa sono le vie sicure e legali e come sostenere la loro implementazione. Mi stavo chiedendo come pensa che potremmo generale cooperazione tra gli stati membri dell\u2019Unione Europea, perch\u00e9 ovviamente questo sarebbe l\u2019ideale. Ma come possiamo provare a generare questa cooperazione e, in un mondo ideale, quali sarebbero i percorsi sicuri e legali per i richiedenti asilo?<\/p>\n<blockquote><p><strong>Lord Dubs:<\/strong>. Sfortunatamente, non essendo nell\u2019UE, l\u2019influenza del Regno Unito sugli altri paesi \u00e8 diminuita sostanzialmente. Tuttavia io ho sempre sostenuto che questo tema non dovrebbe essere gestito solo a livello europeo, ma dovrebbe andare ben oltre i confini dell\u2019UE. Quindi, una delle tragedie \u00e8 stata che, poich\u00e9 gran parte dell\u2019onere cadeva su alcuni paesi come la Germania, i partiti politici di estrema destra potevano sfruttare la situazione; questo \u00e8 un altro argomento per cui l\u2019opinione pubblica dovrebbe essere dalla nostra parte perch\u00e9 i partiti di estrema destra hanno avuto un effetto dannoso sulla politica dei loro paesi, siano essi Francia, Italia o Ungheria. Dobbiamo cercare di ottenere la massima cooperazione internazionale. E questo va a minare i partiti di estrema destra che, comunque, hanno fatto una campagna di totale opposizione ai rifugiati. Penso che dovremmo usare ogni forum internazionale possibile; ad esempio, sono stato coinvolto nell\u2019Organizzazione dell\u2019Assemblea Parlamentare dell\u2019OSCE per la sicurezza e la cooperazione in Europa. Faccio parte del Migration Committee, che abbiamo sostenuto quando abbiamo avuto incontri congiunti con il Consiglio d\u2019Europa. Dobbiamo fare in modo che i paesi europei lavorino insieme e condividano le responsabilit\u00e0 \u2013 questa deve diventare una richiesta politica chiave. Penso che lavoreremo insieme all\u2019UNHCR e all\u2019Organizzazione Internazionale per le Migrazioni per vedere qual \u00e8 la portata o il volume degli arrivi e come possiamo condividerli tra i diversi paesi. Dobbiamo valutare che sono rifugiati, non solo migranti economici. Non c\u2019\u00e8 niente di sbagliato nell\u2019essere un migrante economico, ma spetta a ciascun paese decidere quante persone accogliere e di che cosa hanno bisogno. Ma se stiamo parlando di rifugiati, penso che un possibile modello sia quello che ho menzionato prima: ottenere la cooperazione tra l\u2019UNHCR e una\/due altre organizzazioni internazionali, e vedere se riusciamo a capire di che numeri stiamo parlando e, successivamente, di come trasferirli da un paese dell\u2019UE all\u2019altro e condividerne la responsabilit\u00e0. Quindi, potremmo dire alla Grecia di volerla aiutare, dando priorit\u00e0 ai pi\u00f9 vulnerabili, considerando che molte persone qualificate, pur essendo rifugiate, rimangono a Lesbo. In questo modo, ad esempio, 800 \u00a0rifugiati arriveranno nel Regno Unito, in Francia, in Spagna e via dicendo. Questo \u00e8 quello che dovremmo fare ora. Potrebbe essere troppo idealistico, ma credo ancora che il mondo potrebbe cooperare in questo modo. Ed \u00e8 proprio quello che mi piacerebbe vedere.<\/p><\/blockquote>\n<p><strong>MOAS: <\/strong>S\u00ec, spero che questa diventi una possibilit\u00e0 reale se continuiamo a sostenere questa idea e a galvanizzare le comunit\u00e0.<\/p>\n<blockquote><p><strong>Lord Dubs: <\/strong>D\u2019accordo, allora dobbiamo continuare a dire la stessa cosa quando ci dicono che non possiamo gestire queste persone. Non si pu\u00f2 affermare, perch\u00e9 nessuno chiede di condividere la responsabilit\u00e0 con altri paesi. Personalmente odio quei gommoni che attraversano la Manica perch\u00e9 le persone vengono sfruttate perch\u00e9 sono molto, molto pericolose. Le persone dovrebbero seguire strade pi\u00f9 sicure e legali. Odio l&#8217;idea che le persone vengano sfruttate, salendo sui gommoni. Beh, negli anni precedenti arrivavano principalmente sul retro dei camion, ma comunque odio le rotte illegali. Sono pericolose, umilianti e sfruttatrici. E dobbiamo avere un accordo su percorsi sicuri e legali. Facevo parte di una commissione parlamentare per questo parlamento e stavamo osservando come le persone attraversavano il Mediterraneo in quel momento.<\/p>\n<p>Come si chiamava? Operazione Sofia. Penso che fosse una missione destinata a catturare i trafficanti. Ebbene, non \u00e8 stato cos\u00ec. Ha salvato vite, ma non ha catturato i trafficanti perch\u00e9 purtroppo i trafficanti in Libia spingono semplicemente le barche per molte miglia al di fuori delle acque territoriali. Quindi \u00e8 stata interrotta. Le barche sono state fermate e poi sono stati presi vari accordi con la Libia. E come sai, quei rifugiati che arrivano in Libia vengono sfruttati e alla fine tenuti come schiavi nei campi di detenzione a meno che non possano pagare i trafficanti per portarli attraverso il Mar Mediterraneo. E ovviamente, dobbiamo fare tutto il possibile per cercare di stabilizzare la situazione in Libia, che funzioni o meno. Ma non sono sicuro. La Libia si trova in una situazione terribilmente difficile.<\/p><\/blockquote>\n<p><strong>MOAS: <\/strong>S\u00ec, sicuramente. Queste erano tutte le mie domande oggi. Quindi grazie mille per averci dedicato del tempo e per averne parlato con noi. Speriamo che anche gli ascoltatori abbiamo imparato molto.<\/p>\n<blockquote><p><strong>Lord Dubs: <\/strong>Grazie per averlo detto. C&#8217;\u00e8 un ultimo messaggio: molti di noi hanno lavorato bene. \u00c8 sbagliato che sia solo io a ricevere visibilit\u00e0, ma immagino che sia il modo in cui operano i media. Molte brave persone stanno lavorando su questo. Posso aggiungere che ci sono dei fantastici volontari che lavorano nei campi? Sapete, persone e giovani rinunciano a un anno, due anni della loro vita per aiutare i giovani pi\u00f9 vulnerabili nelle dure condizioni di quella che era la giungla di Calais e nelle pessime condizioni delle isole greche &#8211; e questi giovani sono fantastici. Meritano tutte le medaglie, cos\u00ec come tutte le ONG che lavorano con i rifugiati, che fanno un lavoro fantastico.<\/p><\/blockquote>\n<p><strong>MOAS<\/strong><strong>: <\/strong>\u00c8 stato un vero piacere parlare con Lord Dubs oggi. Potete controllare il sito web e i canali social di MOAS per ricevere ulteriori informazioni sui percorsi sicuri e legali e su <a href=\"https:\/\/www.moas.eu\/it\/viesicureelegali\/\">come partecipare alla campagna<\/a> per implementarli.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Benvenuti nel podcast di MOAS. Oggi parliamo di #VieSicureeLegali con Lord Alf Dubs, uno dei bambini Cechi salvati dal regime nazista attraverso i Kindertransport e &#8230; <a title=\"Podcast &#8211; L\u2019importanza di Vie Sicure e legali. Intervista a Lord Dubs\" class=\"read-more\" href=\"https:\/\/www.moas.eu\/it\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\/\" aria-label=\"Per saperne di pi\u00f9 su Podcast &#8211; L\u2019importanza di Vie Sicure e legali. Intervista a Lord Dubs\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":48554,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"nf_dc_page":"","footnotes":""},"categories":[14,19],"tags":[],"class_list":["post-49351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-blog-it","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","resize-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Podcast - L\u2019importanza di Vie Sicure e legali. Intervista a Lord Dubs - MOAS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.moas.eu\/it\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Podcast - L\u2019importanza di Vie Sicure e legali. Intervista a Lord Dubs - MOAS\" \/>\n<meta property=\"og:description\" content=\"Benvenuti nel podcast di MOAS. Oggi parliamo di #VieSicureeLegali con Lord Alf Dubs, uno dei bambini Cechi salvati dal regime nazista attraverso i Kindertransport e ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.moas.eu\/it\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\/\" \/>\n<meta property=\"og:site_name\" content=\"MOAS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/migrantoffshoreaidstation\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-05T08:52:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-20T09:09:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Black-Friday-Sale-Instagram-Post.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christina Lejman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@moas_eu\" \/>\n<meta name=\"twitter:site\" content=\"@moas_eu\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christina Lejman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"17 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\\\/\"},\"author\":{\"name\":\"Christina Lejman\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/person\\\/be1af883120febb082823c3c74304c69\"},\"headline\":\"Podcast &#8211; L\u2019importanza di Vie Sicure e legali. Intervista a Lord Dubs\",\"datePublished\":\"2021-08-05T08:52:02+00:00\",\"dateModified\":\"2022-10-20T09:09:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\\\/\"},\"wordCount\":3443,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Black-Friday-Sale-Instagram-Post.jpg\",\"articleSection\":[\"Blog\",\"Blog\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.moas.eu\\\/it\\\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\\\/\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\\\/\",\"name\":\"Podcast - L\u2019importanza di Vie Sicure e legali. Intervista a Lord Dubs - MOAS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Black-Friday-Sale-Instagram-Post.jpg\",\"datePublished\":\"2021-08-05T08:52:02+00:00\",\"dateModified\":\"2022-10-20T09:09:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.moas.eu\\\/it\\\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Black-Friday-Sale-Instagram-Post.jpg\",\"contentUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Black-Friday-Sale-Instagram-Post.jpg\",\"width\":1080,\"height\":1080,\"caption\":\"Black Friday Sale Instagram Post\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Podcast &#8211; L\u2019importanza di Vie Sicure e legali. Intervista a Lord Dubs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/\",\"name\":\"MOAS\",\"description\":\"MOAS\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.moas.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\",\"name\":\"MOAS\",\"alternateName\":\"Migrant Offshore Aid Station\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/moas-logo-oval.png\",\"contentUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/moas-logo-oval.png\",\"width\":793,\"height\":354,\"caption\":\"MOAS\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/migrantoffshoreaidstation\",\"https:\\\/\\\/x.com\\\/moas_eu\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/migrant-offshore-aid-station\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZHcDS7ePIBW66d3KvX2K0Q\",\"https:\\\/\\\/www.instagram.com\\\/moas_eu\\\/?hl=en\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/person\\\/be1af883120febb082823c3c74304c69\",\"name\":\"Christina Lejman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"caption\":\"Christina Lejman\"},\"url\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/author\\\/clejman\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Podcast - L\u2019importanza di Vie Sicure e legali. Intervista a Lord Dubs - MOAS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.moas.eu\/it\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\/","og_locale":"it_IT","og_type":"article","og_title":"Podcast - L\u2019importanza di Vie Sicure e legali. Intervista a Lord Dubs - MOAS","og_description":"Benvenuti nel podcast di MOAS. Oggi parliamo di #VieSicureeLegali con Lord Alf Dubs, uno dei bambini Cechi salvati dal regime nazista attraverso i Kindertransport e ... Read more","og_url":"https:\/\/www.moas.eu\/it\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\/","og_site_name":"MOAS","article_publisher":"https:\/\/www.facebook.com\/migrantoffshoreaidstation","article_published_time":"2021-08-05T08:52:02+00:00","article_modified_time":"2022-10-20T09:09:42+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Black-Friday-Sale-Instagram-Post.jpg","type":"image\/jpeg"}],"author":"Christina Lejman","twitter_card":"summary_large_image","twitter_creator":"@moas_eu","twitter_site":"@moas_eu","twitter_misc":{"Scritto da":"Christina Lejman","Tempo di lettura stimato":"17 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.moas.eu\/it\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\/#article","isPartOf":{"@id":"https:\/\/www.moas.eu\/it\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\/"},"author":{"name":"Christina Lejman","@id":"https:\/\/www.moas.eu\/#\/schema\/person\/be1af883120febb082823c3c74304c69"},"headline":"Podcast &#8211; L\u2019importanza di Vie Sicure e legali. Intervista a Lord Dubs","datePublished":"2021-08-05T08:52:02+00:00","dateModified":"2022-10-20T09:09:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.moas.eu\/it\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\/"},"wordCount":3443,"commentCount":0,"publisher":{"@id":"https:\/\/www.moas.eu\/#organization"},"image":{"@id":"https:\/\/www.moas.eu\/it\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\/#primaryimage"},"thumbnailUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Black-Friday-Sale-Instagram-Post.jpg","articleSection":["Blog","Blog"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.moas.eu\/it\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.moas.eu\/it\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\/","url":"https:\/\/www.moas.eu\/it\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\/","name":"Podcast - L\u2019importanza di Vie Sicure e legali. Intervista a Lord Dubs - MOAS","isPartOf":{"@id":"https:\/\/www.moas.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.moas.eu\/it\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\/#primaryimage"},"image":{"@id":"https:\/\/www.moas.eu\/it\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\/#primaryimage"},"thumbnailUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Black-Friday-Sale-Instagram-Post.jpg","datePublished":"2021-08-05T08:52:02+00:00","dateModified":"2022-10-20T09:09:42+00:00","breadcrumb":{"@id":"https:\/\/www.moas.eu\/it\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.moas.eu\/it\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.moas.eu\/it\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\/#primaryimage","url":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Black-Friday-Sale-Instagram-Post.jpg","contentUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Black-Friday-Sale-Instagram-Post.jpg","width":1080,"height":1080,"caption":"Black Friday Sale Instagram Post"},{"@type":"BreadcrumbList","@id":"https:\/\/www.moas.eu\/it\/podcast-limportanza-di-vie-sicure-e-legali-intervista-a-lord-dubs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.moas.eu\/it\/"},{"@type":"ListItem","position":2,"name":"Podcast &#8211; L\u2019importanza di Vie Sicure e legali. Intervista a Lord Dubs"}]},{"@type":"WebSite","@id":"https:\/\/www.moas.eu\/#website","url":"https:\/\/www.moas.eu\/","name":"MOAS","description":"MOAS","publisher":{"@id":"https:\/\/www.moas.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.moas.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.moas.eu\/#organization","name":"MOAS","alternateName":"Migrant Offshore Aid Station","url":"https:\/\/www.moas.eu\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.moas.eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/moas-logo-oval.png","contentUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/moas-logo-oval.png","width":793,"height":354,"caption":"MOAS"},"image":{"@id":"https:\/\/www.moas.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/migrantoffshoreaidstation","https:\/\/x.com\/moas_eu","https:\/\/www.linkedin.com\/company\/migrant-offshore-aid-station","https:\/\/www.youtube.com\/channel\/UCZHcDS7ePIBW66d3KvX2K0Q","https:\/\/www.instagram.com\/moas_eu\/?hl=en"]},{"@type":"Person","@id":"https:\/\/www.moas.eu\/#\/schema\/person\/be1af883120febb082823c3c74304c69","name":"Christina Lejman","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","caption":"Christina Lejman"},"url":"https:\/\/www.moas.eu\/it\/author\/clejman\/"}]}},"_links":{"self":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/49351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/comments?post=49351"}],"version-history":[{"count":1,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/49351\/revisions"}],"predecessor-version":[{"id":49352,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/49351\/revisions\/49352"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/media\/48554"}],"wp:attachment":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/media?parent=49351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/categories?post=49351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/tags?post=49351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}