{"id":49319,"date":"2021-05-31T04:00:31","date_gmt":"2021-05-31T04:00:31","guid":{"rendered":"http:\/\/just2093.temp.domains\/~tqmoaseu\/aggiornamento-sulle-operazioni-moas-a-malta\/"},"modified":"2022-10-20T09:09:45","modified_gmt":"2022-10-20T09:09:45","slug":"aggiornamento-sulle-operazioni-moas-a-malta","status":"publish","type":"post","link":"https:\/\/www.moas.eu\/it\/aggiornamento-sulle-operazioni-moas-a-malta\/","title":{"rendered":"Aggiornamento sulle operazioni MOAS a Malta"},"content":{"rendered":"<p><a href=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Blog-posts-3.png\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-38931\" src=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Blog-posts-3-1024x1024.png\" alt=\"Blog posts (3)\" width=\"831\" height=\"831\" \/><\/a><\/p>\n<p>Come per molti Paesi in tutta Europa e nel resto del mondo, la prima met\u00e0 del 2021 \u00e8 stata molto impegnativa. Nonostante le speranze di un imminente ritorno alla normalit\u00e0, la pandemia ha proseguito il suo corso e, nel caso di Malta, ha portato alla registrazione di nuovi casi COVID-19 e a un secondo lockdown. Le restrizioni imposte per mitigare la diffusione del virus hanno alimentato una rinnovata necessit\u00e0 di misure preventive e risorse per l&#8217;apprendimento online. Di conseguenza, MOAS ha proseguito negli ultimi mesi il progetto di produzione di mascherine riutilizzabili e le attivit\u00e0 incentrate sull&#8217;istruzione a distanza, e ha avviato nuove iniziative a sostegno di migranti e rifugiati sull&#8217;isola.<\/p>\n<p><strong>Donazioni e consegne<\/strong><\/p>\n<p>Il secondo round del nostro progetto \u00e8 continuato con la distribuzione di oltre 2000 maschere dall&#8217;inizio dell&#8217;anno. A fine gennaio sono state consegnate ad AWAS, l\u2019agenzia governativa che si occupa dei rifugiati a Malta, 1.600 mascherine per adulti e 200 per bambini. Dopo la donazione, queste mascherine sono state distribuite da AWAS ai migranti in tutta l&#8217;isola. Oltre a ci\u00f2, abbiamo effettuato la <a href=\"https:\/\/www.moas.eu\/it\/comunicatostampa-covid-19-moas-dona-gel-igienizzante-per-le-mani-e-mascherine-alle-comunita-vulnerabili-di-malta\/\">consegna di oltre 400 mascherine<\/a> alle organizzazioni che supportano le comunit\u00e0 pi\u00f9 vulnerabili a Malta, tra cui Peace Lab, Osanna Pia e Emigrants Commission. Oltre alla fornitura di mascherine, abbiamo anche consegnato 1000 flaconi di disinfettante per le mani, donati a MOAS da The BioArte Ltd. Poich\u00e9 Malta ha registrato molti casi di coronavirus negli ultimi mesi, facilitare l&#8217;accesso a misure preventive come il disinfettante per le mani e le mascherine \u00e8 stato fondamentale. Di conseguenza, siamo incredibilmente grati ai nostri donatori e ai volontari che hanno reso possibili queste consegne. L&#8217;ultima fase del progetto mascherine ha registrato la produzione di quasi 3000 maschere durante il secondo round e quasi 10.000 mascherine sono state consegnate attraverso il progetto sin dal suo inizio.<\/p>\n<p>Oltre alla protezione essenziale dal COVID-19, abbiamo anche cercato di continuare a fare donazioni a bambini e adolescenti nel centro per minori non accompagnati di Malta, quando possibile. In seguito alla nostra a febbraio, abbiamo visitato l&#8217;Hal Far Migrant Open Center per fare una donazione di dolci e regali. Questa \u00e8 stata poi seguita, ad aprile, dalla nostra <a href=\"https:\/\/www.moas.eu\/it\/malta-moas-regala-un-dolce-pensiero-ai-minori-non-accompagnati-a-malta\/\">consegna di Smarties<\/a> tra i minori non accompagnati e i residenti nel centro di Hal Far e gli ospiti del Disruption Peace Lab.<\/p>\n<p><a href=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2021\/05\/MOAS_Sweets_delviery_SD-42-scaled.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-large wp-image-38934\" src=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/MOAS_Sweets_delviery_SD-42-1-scaled.jpg\" alt=\"MOAS_Sweets_delviery_SD-42\" width=\"1024\" height=\"683\" \/><\/a><\/p>\n<p><strong>Iniziative per l\u2019istruzione online<\/strong><\/p>\n<p>Gli ultimi mesi hanno visto anche la continuazione del <a href=\"https:\/\/www.moas.eu\/it\/covid-19-moas-a-fianco-delle-famiglie-migranti-di-malta-con-il-remote-learning-project-per-la-didattica-a-distanza\/\">Remote Learning Project<\/a>. A febbraio, abbiamo consegnato altri 3 tablet e modem con connessione Internet alle famiglie di migranti che vivono nel centro HFO, identificate da AWAS. Considerando che le scuole hanno subito ulteriori chiusure durante il 2021 e l&#8217;apprendimento a distanza \u00e8 stato ancora una volta un metodo di istruzione primario, consentire l&#8217;accesso a queste risorse \u00e8 fondamentale per i bambini e gli adolescenti migranti per proseguire i loro studi. Continueremo a coordinarci con AWAS su questo progetto per distribuire dispositivi digitali alle famiglie migranti che ne hanno bisogno.<\/p>\n<p>Per tutta la <a href=\"https:\/\/www.moas.eu\/it\/blog-quali-sono-i-nostri-piani-per-il-2021\/\">seconda met\u00e0 di quest&#8217;anno<\/a>, speriamo di implementare ulteriormente le nostre iniziative incentrate sull&#8217;istruzione. In seguito al successo del Remote Learning Project, MOAS sta iniziando a pianificare la realizzazione di uno spazio di apprendimento multifunzionale presso l&#8217;Hangar Open Center (HOC). MOAS vorrebbe che questo centro di apprendimento fosse dotato di risorse educative come computer, stampanti, proiettori, libri e altri strumenti di digitali e venisse utilizzato dai residenti del centro per l&#8217;istruzione formale, attivit\u00e0 di formazione come lezioni di lingua, studio o attivit\u00e0 essenziali come la scrittura di CV, ricerca di lavoro e registrazione ai servizi online.<\/p>\n<p><strong>Considerazioni finali<\/strong><\/p>\n<p>Siamo ben consapevoli che la pandemia non \u00e8 finita e che le criticit\u00e0 che abbiamo dovuto affrontare sin dal suo inizio potrebbero continuare. Le mascherine restano un presidio essenziale e l&#8217;apprendimento online rimarr\u00e0 probabilmente una componente chiave dell&#8217;istruzione in futuro. MOAS continua a monitorare le disuguaglianze e le sfide che devono affrontare migranti e rifugiati a Malta, e proseguiremo nel fornire il nostro supporto e le nostre risorse ogni volta che possiamo.<\/p>\n<p><strong>Se sei interessato alle attivit\u00e0 MOAS e a quelle dei nostri partner seguici sui social, iscriviti alla nostra newsletter e condividi i nostri contenuti. Puoi scriverci a\u00a0<\/strong><a href=\"mailto:info@moas.eu\"><strong>info@moas.eu<\/strong><\/a><strong>. <\/strong><strong>Per supportare le nostre\u00a0operazioni dona su\u00a0<\/strong><a href=\"https:\/\/www.moas.eu\/it\/donate\/\"><strong>https:\/\/www.moas.eu\/it\/donate\/<\/strong><\/a><strong>\u00a0o scegli di devolvere il tuo 5\u00d71000 a MOAS\u00a0<\/strong><a href=\"https:\/\/www.moas.eu\/it\/\"><strong>https:\/\/www.moas.eu\/it<\/strong><\/a><\/p>\n<p><a href=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/eupa-logo-1-1.png\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-38078\" src=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/eupa-logo-1-1.png\" alt=\"\" width=\"177\" height=\"156\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Come per molti Paesi in tutta Europa e nel resto del mondo, la prima met\u00e0 del 2021 \u00e8 stata molto impegnativa. Nonostante le speranze di &#8230; <a title=\"Aggiornamento sulle operazioni MOAS a Malta\" class=\"read-more\" href=\"https:\/\/www.moas.eu\/it\/aggiornamento-sulle-operazioni-moas-a-malta\/\" aria-label=\"Per saperne di pi\u00f9 su Aggiornamento sulle operazioni MOAS a Malta\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":48457,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"nf_dc_page":"","footnotes":""},"categories":[14,19],"tags":[],"class_list":["post-49319","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-blog-it","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","resize-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aggiornamento sulle operazioni MOAS a Malta - MOAS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.moas.eu\/it\/aggiornamento-sulle-operazioni-moas-a-malta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aggiornamento sulle operazioni MOAS a Malta - MOAS\" \/>\n<meta property=\"og:description\" content=\"Come per molti Paesi in tutta Europa e nel resto del mondo, la prima met\u00e0 del 2021 \u00e8 stata molto impegnativa. Nonostante le speranze di ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.moas.eu\/it\/aggiornamento-sulle-operazioni-moas-a-malta\/\" \/>\n<meta property=\"og:site_name\" content=\"MOAS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/migrantoffshoreaidstation\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-31T04:00:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-20T09:09:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Blog-posts-3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Christina Lejman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@moas_eu\" \/>\n<meta name=\"twitter:site\" content=\"@moas_eu\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christina Lejman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/aggiornamento-sulle-operazioni-moas-a-malta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/aggiornamento-sulle-operazioni-moas-a-malta\\\/\"},\"author\":{\"name\":\"Christina Lejman\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/person\\\/be1af883120febb082823c3c74304c69\"},\"headline\":\"Aggiornamento sulle operazioni MOAS a Malta\",\"datePublished\":\"2021-05-31T04:00:31+00:00\",\"dateModified\":\"2022-10-20T09:09:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/aggiornamento-sulle-operazioni-moas-a-malta\\\/\"},\"wordCount\":719,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/aggiornamento-sulle-operazioni-moas-a-malta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Blog-posts-3.png\",\"articleSection\":[\"Blog\",\"Blog\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.moas.eu\\\/it\\\/aggiornamento-sulle-operazioni-moas-a-malta\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/aggiornamento-sulle-operazioni-moas-a-malta\\\/\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/aggiornamento-sulle-operazioni-moas-a-malta\\\/\",\"name\":\"Aggiornamento sulle operazioni MOAS a Malta - MOAS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/aggiornamento-sulle-operazioni-moas-a-malta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/aggiornamento-sulle-operazioni-moas-a-malta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Blog-posts-3.png\",\"datePublished\":\"2021-05-31T04:00:31+00:00\",\"dateModified\":\"2022-10-20T09:09:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/aggiornamento-sulle-operazioni-moas-a-malta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.moas.eu\\\/it\\\/aggiornamento-sulle-operazioni-moas-a-malta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/aggiornamento-sulle-operazioni-moas-a-malta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Blog-posts-3.png\",\"contentUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Blog-posts-3.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/aggiornamento-sulle-operazioni-moas-a-malta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aggiornamento sulle operazioni MOAS a Malta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/\",\"name\":\"MOAS\",\"description\":\"MOAS\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.moas.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\",\"name\":\"MOAS\",\"alternateName\":\"Migrant Offshore Aid Station\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/moas-logo-oval.png\",\"contentUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/moas-logo-oval.png\",\"width\":793,\"height\":354,\"caption\":\"MOAS\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/migrantoffshoreaidstation\",\"https:\\\/\\\/x.com\\\/moas_eu\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/migrant-offshore-aid-station\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZHcDS7ePIBW66d3KvX2K0Q\",\"https:\\\/\\\/www.instagram.com\\\/moas_eu\\\/?hl=en\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/person\\\/be1af883120febb082823c3c74304c69\",\"name\":\"Christina Lejman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"caption\":\"Christina Lejman\"},\"url\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/author\\\/clejman\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aggiornamento sulle operazioni MOAS a Malta - MOAS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.moas.eu\/it\/aggiornamento-sulle-operazioni-moas-a-malta\/","og_locale":"it_IT","og_type":"article","og_title":"Aggiornamento sulle operazioni MOAS a Malta - MOAS","og_description":"Come per molti Paesi in tutta Europa e nel resto del mondo, la prima met\u00e0 del 2021 \u00e8 stata molto impegnativa. Nonostante le speranze di ... Read more","og_url":"https:\/\/www.moas.eu\/it\/aggiornamento-sulle-operazioni-moas-a-malta\/","og_site_name":"MOAS","article_publisher":"https:\/\/www.facebook.com\/migrantoffshoreaidstation","article_published_time":"2021-05-31T04:00:31+00:00","article_modified_time":"2022-10-20T09:09:45+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Blog-posts-3.png","type":"image\/png"}],"author":"Christina Lejman","twitter_card":"summary_large_image","twitter_creator":"@moas_eu","twitter_site":"@moas_eu","twitter_misc":{"Scritto da":"Christina Lejman","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.moas.eu\/it\/aggiornamento-sulle-operazioni-moas-a-malta\/#article","isPartOf":{"@id":"https:\/\/www.moas.eu\/it\/aggiornamento-sulle-operazioni-moas-a-malta\/"},"author":{"name":"Christina Lejman","@id":"https:\/\/www.moas.eu\/#\/schema\/person\/be1af883120febb082823c3c74304c69"},"headline":"Aggiornamento sulle operazioni MOAS a Malta","datePublished":"2021-05-31T04:00:31+00:00","dateModified":"2022-10-20T09:09:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.moas.eu\/it\/aggiornamento-sulle-operazioni-moas-a-malta\/"},"wordCount":719,"commentCount":0,"publisher":{"@id":"https:\/\/www.moas.eu\/#organization"},"image":{"@id":"https:\/\/www.moas.eu\/it\/aggiornamento-sulle-operazioni-moas-a-malta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Blog-posts-3.png","articleSection":["Blog","Blog"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.moas.eu\/it\/aggiornamento-sulle-operazioni-moas-a-malta\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.moas.eu\/it\/aggiornamento-sulle-operazioni-moas-a-malta\/","url":"https:\/\/www.moas.eu\/it\/aggiornamento-sulle-operazioni-moas-a-malta\/","name":"Aggiornamento sulle operazioni MOAS a Malta - MOAS","isPartOf":{"@id":"https:\/\/www.moas.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.moas.eu\/it\/aggiornamento-sulle-operazioni-moas-a-malta\/#primaryimage"},"image":{"@id":"https:\/\/www.moas.eu\/it\/aggiornamento-sulle-operazioni-moas-a-malta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Blog-posts-3.png","datePublished":"2021-05-31T04:00:31+00:00","dateModified":"2022-10-20T09:09:45+00:00","breadcrumb":{"@id":"https:\/\/www.moas.eu\/it\/aggiornamento-sulle-operazioni-moas-a-malta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.moas.eu\/it\/aggiornamento-sulle-operazioni-moas-a-malta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.moas.eu\/it\/aggiornamento-sulle-operazioni-moas-a-malta\/#primaryimage","url":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Blog-posts-3.png","contentUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Blog-posts-3.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.moas.eu\/it\/aggiornamento-sulle-operazioni-moas-a-malta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.moas.eu\/it\/"},{"@type":"ListItem","position":2,"name":"Aggiornamento sulle operazioni MOAS a Malta"}]},{"@type":"WebSite","@id":"https:\/\/www.moas.eu\/#website","url":"https:\/\/www.moas.eu\/","name":"MOAS","description":"MOAS","publisher":{"@id":"https:\/\/www.moas.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.moas.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.moas.eu\/#organization","name":"MOAS","alternateName":"Migrant Offshore Aid Station","url":"https:\/\/www.moas.eu\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.moas.eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/moas-logo-oval.png","contentUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/moas-logo-oval.png","width":793,"height":354,"caption":"MOAS"},"image":{"@id":"https:\/\/www.moas.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/migrantoffshoreaidstation","https:\/\/x.com\/moas_eu","https:\/\/www.linkedin.com\/company\/migrant-offshore-aid-station","https:\/\/www.youtube.com\/channel\/UCZHcDS7ePIBW66d3KvX2K0Q","https:\/\/www.instagram.com\/moas_eu\/?hl=en"]},{"@type":"Person","@id":"https:\/\/www.moas.eu\/#\/schema\/person\/be1af883120febb082823c3c74304c69","name":"Christina Lejman","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","caption":"Christina Lejman"},"url":"https:\/\/www.moas.eu\/it\/author\/clejman\/"}]}},"_links":{"self":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/49319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/comments?post=49319"}],"version-history":[{"count":1,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/49319\/revisions"}],"predecessor-version":[{"id":49321,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/49319\/revisions\/49321"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/media\/48457"}],"wp:attachment":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/media?parent=49319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/categories?post=49319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/tags?post=49319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}