{"id":49303,"date":"2021-04-19T05:00:00","date_gmt":"2021-04-19T05:00:00","guid":{"rendered":"http:\/\/just2093.temp.domains\/~tqmoaseu\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\/"},"modified":"2022-10-20T09:09:47","modified_gmt":"2022-10-20T09:09:47","slug":"vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue","status":"publish","type":"post","link":"https:\/\/www.moas.eu\/it\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\/","title":{"rendered":"Vie Sicure e legali: focus sulle frontiere esterne e proposte di azione dell&#8217;UE"},"content":{"rendered":"<p><a href=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/boat-1-scaled.jpeg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-large wp-image-38735\" src=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/boat-1-scaled.jpeg\" alt=\"\" width=\"1024\" height=\"683\" \/><\/a><\/p>\n<p>Ogni anno migliaia di rifugiati e persone migranti sono costretti a intraprendere viaggi pericolosi in cerca di salvezza e protezione. Alla fine di marzo 2021, gli arrivi via mare in Europa sono stati 13.191, mentre <a href=\"https:\/\/migration.iom.int\/europe?type=arrivals\">306 persone<\/a> risultano scomparse o presumibilmente morte un dato che ci ricorda i gravi pericoli connessi alle traversate via mare. Tuttavia, molte persone intraprendono anche viaggi via terra durante i quali subiscono abusi, vivono in condizioni difficili e ricevono poca o nessuna assistenza. Occorre, quindi, implementare percorsi sicuri e legali di migrazione per prevenire le tragedie e i maltrattamenti durante il viaggio. In questo blog, approfondiamo alcune delle situazioni pi\u00f9 complesse che le persone migranti si trovano ad affrontare e le recenti proposte dell&#8217;UE in merito alle soluzioni da adottare per la gestione del fenomeno migratorio.<\/p>\n<p><strong>Le rotte balcaniche<\/strong><\/p>\n<p>Alla fine di ottobre dello scorso anno, circa <a href=\"https:\/\/ec.europa.eu\/home-affairs\/sites\/homeaffairs\/files\/what-we-do\/policies\/european-agenda-migration\/background-information\/docs\/western_balkans_route_state_of_play_report_en.pdf\">700.000<\/a> persone hanno percorso la rotta dei Balcani occidentali dalla Grecia all&#8217;Europa centrale. Il viaggio \u00e8 estremamente lungo e le persone migranti devono compiere un viaggio particolarmente difficoltoso. La parte finale del viaggio <a href=\"https:\/\/www.theguardian.com\/global-development\/2021\/jan\/14\/journeys-of-hope-what-will-migration-routes-into-europe-look-like-in-2021\">attraversa &#8220;montagne e foreste innevate&#8221;<\/a> e durante i mesi invernali le persone sono costrette a correre rischi ancora maggiori. Il passaggio in Croazia sta diventando sempre pi\u00f9 impraticabile poich\u00e9 violenti respingimenti costringono migliaia di rifugiati e persone migranti a campeggiare a temperature sotto lo zero senza accesso ai servizi di base. L&#8217;anno scorso, il Consiglio danese per i rifugiati ha registrato <a href=\"https:\/\/www.theguardian.com\/global-development\/2021\/jan\/14\/journeys-of-hope-what-will-migration-routes-into-europe-look-like-in-2021\">15.672 respingimenti<\/a> dalla Croazia alla Bosnia-Erzegovina, di cui oltre il 60% perpetrato in modo violento.<\/p>\n<p>Molti richiedenti asilo sono bloccati al confine con la Bosnia-Erzegovina a causa <a href=\"https:\/\/www.infomigrants.net\/en\/post\/29534\/refugees-stuck-in-hopeless-situation-at-eu-border-in-bosnia\">dell&#8217;inasprimento delle restrizioni alle frontiere dell&#8217;UE<\/a>. Oltre <a href=\"https:\/\/www.voanews.com\/europe\/conditions-deteriorate-thousands-migrants-stranded-bosnia\">6.000 persone sono attualmente ospitate<\/a> in centri di accoglienza dopo che il campo di Lipa \u00e8 stato ufficialmente chiuso a causa della cattiva gestione adottata dal governo. Tuttavia, oltre <a href=\"https:\/\/www.voanews.com\/europe\/conditions-deteriorate-thousands-migrants-stranded-bosnia\">3.000 persone al confine croato sono attualmente costrette a dormire all\u2019addi<\/a>accio. Pi\u00f9 di recente, nel vecchio campo di Lipa sono state allestite tende militari per ospitare 750 persone, poich\u00e9 non \u00e8 stato possibile raggiungere un consenso politico in merito all\u2019offerta di alloggi alternativi che offrano condizioni di vita accettabili. Con l&#8217;aumento della tensione politica nella regione, le persone migranti devono affrontare respingimenti illegali alle frontiere e i loro <a href=\"https:\/\/www.rferl.org\/a\/bosnia-urged-to-swiftly-handle-dire-migrant-humanitarian-situation\/31048458.html\">bisogni primari vengono sempre pi\u00f9 trascurati<\/a>. Nei campi istituiti dopo la chiusura ufficiale di Lipa, si vive in <a href=\"https:\/\/www.rferl.org\/a\/bosnia-urged-provide-migrants-accommodation-lipa-cold-weather\/31062066.html\">condizioni di sovraffollamento e<\/a> i residenti hanno poco o nessun accesso all&#8217;acqua corrente e ai servizi igienici di base. Questo mancato rispetto dei diritti umani fondamentali, insieme alla continua diffusione del Covid-19, significa che le persone migranti non vengono trattate con l&#8217;umanit\u00e0 e la dignit\u00e0 cui hanno diritto. Occorre trovare con urgenza <a href=\"https:\/\/www.hrw.org\/news\/2021\/01\/21\/bosnia-and-herzegovina-migrants-left-cold\">soluzioni pi\u00f9 a lungo termine<\/a>.<\/p>\n<p><strong>Le politiche di asilo nel Regno Unito in seguito alla Brexit<\/strong><\/p>\n<p>In seguito alla Brexit, l&#8217;uscita del Regno Unito dall&#8217;Unione Europea potrebbe avere gravi ripercussioni sulla politica migratoria della nazione. Negli ultimi anni, il procedimento per la richiesta di asilo nel Regno Unito \u00e8 diventato sempre pi\u00f9 complesso e ostile, con l&#8217;adozione di misure strutturali atte a scoraggiare le domande. C&#8217;\u00e8 una grande ambiguit\u00e0 sulla natura della politica dei provvedimenti adottati nel Regno Unito, ma intanto dal 1\u00b0 gennaio 2021 il ricongiungimento familiare avr\u00e0 luogo solo se lo <a href=\"https:\/\/www.infomigrants.net\/en\/post\/29374\/brexit-what-changes-for-migrants-on-january-1\">status di rifugiato \u00e8 stato concesso<\/a> alla persona gi\u00e0 residente nel Paese e i minori non accompagnati possono essere ricongiunti solo con i loro genitori. Per la maggior parte delle persone in fuga da condizioni disperate, le opzioni di riunirsi ai famigliari nel Regno Unito sono dunque estremamente limitate. Con l&#8217;eccezione di alcuni programmi di reinsediamento, <a href=\"https:\/\/www.jcwi.org.uk\/Handlers\/Download.ashx?IDMF=fdf3ab13-95ef-44eb-8947-b5d975545090\">spesso non \u00e8 possibile richiedere asilo<\/a> a meno che non si raggiungano fisicamente i confini del Paese. Il governo mantiene un <a href=\"https:\/\/www.refugee-action.org.uk\/channel-crossings-we-need-safe-and-legal-routes-because-asylum-is-a-human-right\/\">certo riserbo in merito ai piani futuri<\/a> dopo che i programmi di accoglienza sono stati sospesi a causa delle restrizioni dovute al Covid-19. Pertanto, senza facilitare iniziative pi\u00f9 ampie di reinsediamento e processi di ricongiungimento, esiste il pericolo reale che rifugiati e persone migranti siano costretti a intraprendere rotte pi\u00f9 pericolose per raggiungere il Regno Unito, come l\u2019attraversamento della Manica, mettendo a rischio molte vite.<\/p>\n<p><a href=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/white-kliff-4411679_1280.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-large wp-image-38738\" src=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/white-kliff-4411679_1280-1024x682.jpg\" alt=\"\" width=\"1024\" height=\"682\" \/><\/a><\/p>\n<p><strong>Il Patto UE sulla migrazione e l\u2019asilo<\/strong><\/p>\n<p>Mentre il Regno Unito cerca di sviluppare la propria politica in materia di migrazione, <a href=\"https:\/\/www.infomigrants.net\/en\/post\/30254\/migrants-iom-urges-end-of-pushbacks-violence-at-eu-borders\">organizzazioni internazionali tra cui l&#8217;OIM<\/a> hanno sottolineato la necessit\u00e0 di migliorare la governance in materia di migrazione e asilo e di attuare pratiche basate sul rispetto diritti umani lungo le frontiere esterne dell&#8217;UE. Le agenzie delle Nazioni Unite e <a href=\"https:\/\/www.infomigrants.net\/en\/post\/30175\/pope-renew-efforts-to-protect-refugees-renegotiate-eu-pact\">altri commentatori<\/a> auspicano che ci\u00f2 sar\u00e0 realizzato attraverso il nuovo patto dell&#8217;UE sulla migrazione e l&#8217;asilo. Annunciato nel settembre 2020, il patto intende creare un nuovo <a href=\"https:\/\/ec.europa.eu\/commission\/presscorner\/detail\/en\/ip_20_1706\">meccanismo di solidariet\u00e0<\/a>, in base al quale gli Stati membri possono adottare un sistema di gestione della migrazione affidabile e mettere in atto soluzioni comuni. La proposta suggerisce un <a href=\"https:\/\/www.robert-schuman.eu\/en\/european-issues\/0577-understanding-the-new-pact-on-migration-and-asylum\">nuovo meccanismo<\/a> che prevede un piano di distribuzione che tenga conto del PIL nazionale e delle dimensioni della popolazione, in modo da alleggerire gli Stati membri che affrontano una significativa pressione migratoria. Sebbene la ricollocazione rimarrebbe un&#8217;opzione, gli Stati membri che si oppongono all&#8217;accoglienza di persone ricollocate potrebbero sponsorizzare il rimpatrio nel Paese di origine e assumersi l\u2019onere di tale rimpatrio. La Commissione Europea si propone, inoltre, di creare un gruppo informale di esperti in materia di migrazione e asilo, che tenga conto del punto di vista dei richiedenti asilo e dei migranti. Sebbene il messaggio centrale di questo patto sia la solidariet\u00e0, i meccanismi previsti non si integrano completamente con gli aspetti politici necessari a costruire un sistema migratorio progressivo ed equo. Tuttavia, poich\u00e9 i negoziati sul patto sono attualmente in corso, c&#8217;\u00e8 ancora la possibilit\u00e0 di apportare modifiche prima dell\u2019attuazione.<\/p>\n<p><strong>Considerazioni finali <\/strong><\/p>\n<p>Considerando gli ostacoli, i maltrattamenti e i rischi che rifugiati e persone migranti sono continuamente costretti ad affrontare, grande speranza viene riposta nelle soluzioni proposte dal nuovo patto dell&#8217;UE. Tuttavia, oltre a ci\u00f2, \u00e8 necessaria una maggiore spinta per l\u2019implementazione di percorsi sicuri e legali di migrazione. Per questo MOAS promuove la campagna per #VieSicureELegali, che consentirebbero di salvare molte persone e di offrire protezione e rispetto, attraverso la messa in atto di strumenti migratori sicuri e legali, come corridoi umanitari, visti per studenti, medici e umanitari, e sponsorizzazioni private.<\/p>\n<p>Per sostenere la nostra campagna per Vie Sicure e Legali firma il nostro appello: <a href=\"https:\/\/www.moas.eu\/it\/safeandlegalroutes\/\">https:\/\/www.moas.eu\/it\/safeandlegalroutes\/<\/a><\/p>\n<p><strong>Se sei interessato alle attivit\u00e0 MOAS e a quelle dei nostri partner seguici sui social, iscriviti alla nostra newsletter e condividi i nostri contenuti. Puoi scriverci a <\/strong><a href=\"mailto:info@moas.eu\"><strong>info@moas.eu<\/strong><\/a><strong>. Per supportare le nostre operazioni dona su <\/strong><a href=\"https:\/\/www.moas.eu\/it\/donate\/\"><strong>www.moas.eu\/it\/donate\/<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ogni anno migliaia di rifugiati e persone migranti sono costretti a intraprendere viaggi pericolosi in cerca di salvezza e protezione. Alla fine di marzo 2021, &#8230; <a title=\"Vie Sicure e legali: focus sulle frontiere esterne e proposte di azione dell&#8217;UE\" class=\"read-more\" href=\"https:\/\/www.moas.eu\/it\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\/\" aria-label=\"Per saperne di pi\u00f9 su Vie Sicure e legali: focus sulle frontiere esterne e proposte di azione dell&#8217;UE\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":48431,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"nf_dc_page":"","footnotes":""},"categories":[14,19],"tags":[],"class_list":["post-49303","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-blog-it","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","resize-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vie Sicure e legali: focus sulle frontiere esterne e proposte di azione dell&#039;UE - MOAS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.moas.eu\/it\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vie Sicure e legali: focus sulle frontiere esterne e proposte di azione dell&#039;UE - MOAS\" \/>\n<meta property=\"og:description\" content=\"Ogni anno migliaia di rifugiati e persone migranti sono costretti a intraprendere viaggi pericolosi in cerca di salvezza e protezione. Alla fine di marzo 2021, ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.moas.eu\/it\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\/\" \/>\n<meta property=\"og:site_name\" content=\"MOAS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/migrantoffshoreaidstation\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-19T05:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-20T09:09:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/slr2021ita.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Christina Lejman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@moas_eu\" \/>\n<meta name=\"twitter:site\" content=\"@moas_eu\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christina Lejman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\\\/\"},\"author\":{\"name\":\"Christina Lejman\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/person\\\/be1af883120febb082823c3c74304c69\"},\"headline\":\"Vie Sicure e legali: focus sulle frontiere esterne e proposte di azione dell&#8217;UE\",\"datePublished\":\"2021-04-19T05:00:00+00:00\",\"dateModified\":\"2022-10-20T09:09:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\\\/\"},\"wordCount\":1105,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/slr2021ita.png\",\"articleSection\":[\"Blog\",\"Blog\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.moas.eu\\\/it\\\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\\\/\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\\\/\",\"name\":\"Vie Sicure e legali: focus sulle frontiere esterne e proposte di azione dell'UE - MOAS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/slr2021ita.png\",\"datePublished\":\"2021-04-19T05:00:00+00:00\",\"dateModified\":\"2022-10-20T09:09:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.moas.eu\\\/it\\\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/slr2021ita.png\",\"contentUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/slr2021ita.png\",\"width\":1080,\"height\":1080,\"caption\":\"slr2021ita\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vie Sicure e legali: focus sulle frontiere esterne e proposte di azione dell&#8217;UE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/\",\"name\":\"MOAS\",\"description\":\"MOAS\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.moas.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\",\"name\":\"MOAS\",\"alternateName\":\"Migrant Offshore Aid Station\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/moas-logo-oval.png\",\"contentUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/moas-logo-oval.png\",\"width\":793,\"height\":354,\"caption\":\"MOAS\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/migrantoffshoreaidstation\",\"https:\\\/\\\/x.com\\\/moas_eu\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/migrant-offshore-aid-station\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZHcDS7ePIBW66d3KvX2K0Q\",\"https:\\\/\\\/www.instagram.com\\\/moas_eu\\\/?hl=en\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/person\\\/be1af883120febb082823c3c74304c69\",\"name\":\"Christina Lejman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"caption\":\"Christina Lejman\"},\"url\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/author\\\/clejman\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vie Sicure e legali: focus sulle frontiere esterne e proposte di azione dell'UE - MOAS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.moas.eu\/it\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\/","og_locale":"it_IT","og_type":"article","og_title":"Vie Sicure e legali: focus sulle frontiere esterne e proposte di azione dell'UE - MOAS","og_description":"Ogni anno migliaia di rifugiati e persone migranti sono costretti a intraprendere viaggi pericolosi in cerca di salvezza e protezione. Alla fine di marzo 2021, ... Read more","og_url":"https:\/\/www.moas.eu\/it\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\/","og_site_name":"MOAS","article_publisher":"https:\/\/www.facebook.com\/migrantoffshoreaidstation","article_published_time":"2021-04-19T05:00:00+00:00","article_modified_time":"2022-10-20T09:09:47+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/slr2021ita.png","type":"image\/png"}],"author":"Christina Lejman","twitter_card":"summary_large_image","twitter_creator":"@moas_eu","twitter_site":"@moas_eu","twitter_misc":{"Scritto da":"Christina Lejman","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.moas.eu\/it\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\/#article","isPartOf":{"@id":"https:\/\/www.moas.eu\/it\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\/"},"author":{"name":"Christina Lejman","@id":"https:\/\/www.moas.eu\/#\/schema\/person\/be1af883120febb082823c3c74304c69"},"headline":"Vie Sicure e legali: focus sulle frontiere esterne e proposte di azione dell&#8217;UE","datePublished":"2021-04-19T05:00:00+00:00","dateModified":"2022-10-20T09:09:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.moas.eu\/it\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\/"},"wordCount":1105,"commentCount":0,"publisher":{"@id":"https:\/\/www.moas.eu\/#organization"},"image":{"@id":"https:\/\/www.moas.eu\/it\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\/#primaryimage"},"thumbnailUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/slr2021ita.png","articleSection":["Blog","Blog"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.moas.eu\/it\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.moas.eu\/it\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\/","url":"https:\/\/www.moas.eu\/it\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\/","name":"Vie Sicure e legali: focus sulle frontiere esterne e proposte di azione dell'UE - MOAS","isPartOf":{"@id":"https:\/\/www.moas.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.moas.eu\/it\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\/#primaryimage"},"image":{"@id":"https:\/\/www.moas.eu\/it\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\/#primaryimage"},"thumbnailUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/slr2021ita.png","datePublished":"2021-04-19T05:00:00+00:00","dateModified":"2022-10-20T09:09:47+00:00","breadcrumb":{"@id":"https:\/\/www.moas.eu\/it\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.moas.eu\/it\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.moas.eu\/it\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\/#primaryimage","url":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/slr2021ita.png","contentUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/slr2021ita.png","width":1080,"height":1080,"caption":"slr2021ita"},{"@type":"BreadcrumbList","@id":"https:\/\/www.moas.eu\/it\/vie-sicure-e-legali-focus-sulle-frontiere-esterne-e-proposte-di-azione-dellue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.moas.eu\/it\/"},{"@type":"ListItem","position":2,"name":"Vie Sicure e legali: focus sulle frontiere esterne e proposte di azione dell&#8217;UE"}]},{"@type":"WebSite","@id":"https:\/\/www.moas.eu\/#website","url":"https:\/\/www.moas.eu\/","name":"MOAS","description":"MOAS","publisher":{"@id":"https:\/\/www.moas.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.moas.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.moas.eu\/#organization","name":"MOAS","alternateName":"Migrant Offshore Aid Station","url":"https:\/\/www.moas.eu\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.moas.eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/moas-logo-oval.png","contentUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/moas-logo-oval.png","width":793,"height":354,"caption":"MOAS"},"image":{"@id":"https:\/\/www.moas.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/migrantoffshoreaidstation","https:\/\/x.com\/moas_eu","https:\/\/www.linkedin.com\/company\/migrant-offshore-aid-station","https:\/\/www.youtube.com\/channel\/UCZHcDS7ePIBW66d3KvX2K0Q","https:\/\/www.instagram.com\/moas_eu\/?hl=en"]},{"@type":"Person","@id":"https:\/\/www.moas.eu\/#\/schema\/person\/be1af883120febb082823c3c74304c69","name":"Christina Lejman","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","caption":"Christina Lejman"},"url":"https:\/\/www.moas.eu\/it\/author\/clejman\/"}]}},"_links":{"self":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/49303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/comments?post=49303"}],"version-history":[{"count":1,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/49303\/revisions"}],"predecessor-version":[{"id":49304,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/49303\/revisions\/49304"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/media\/48431"}],"wp:attachment":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/media?parent=49303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/categories?post=49303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/tags?post=49303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}