{"id":49300,"date":"2021-02-28T13:19:44","date_gmt":"2021-02-28T13:19:44","guid":{"rendered":"http:\/\/just2093.temp.domains\/~tqmoaseu\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\/"},"modified":"2022-10-20T09:09:50","modified_gmt":"2022-10-20T09:09:50","slug":"lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh","status":"publish","type":"post","link":"https:\/\/www.moas.eu\/it\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\/","title":{"rendered":"L\u2019Otto per Mille della Chiesa Valdese e MOAS Italia in Bangladesh"},"content":{"rendered":"<p><a href=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2021\/04\/Water-sources-in-the-camps-scaled.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-38710\" src=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Water-sources-in-the-camps-2-scaled.jpg\" alt=\"Water-sources-in-the-camps\" width=\"594\" height=\"594\" \/><\/a><\/p>\n<p>In Bangladesh, nei campi profughi dove vivono i rifugiati Rohingya fuggiti dalle torture e dalle violenze perpetrate in Myanmar, tra il 2019 e il 2020 venti bambini hanno perso la vita a causa dell\u2019annegamento nei bacini d\u2019acqua formatisi in seguito alle alluvioni monsoniche.<\/p>\n<p>Nel distretto di Cox\u2019s Bazar la risposta a tali emergenze costituisce una priorit\u00e0 urgente. Quest\u2019area del Bangladesh \u00e8 interessata da inondazioni improvvise legate alla stagione dei monsoni e dei cicloni e, a causa delle competenze limitate e delle scarse attrezzature a disposizione, oggi non \u00e8 possibile garantire adeguate condizioni di sicurezza per coloro i quali vivono all\u2019interno dei campi profughi.<\/p>\n<p>Secondo il <a href=\"https:\/\/www.moas.eu\/it\/blog-indagine-incidenti-mortali-annegamento-infantile-coxs-bazar\/\">report preparato da MOAS<\/a> e dedicato agli incidenti mortali causati dall\u2019annegamento infantile nei campi profughi di Cox\u2019s Bazar, la fascia pi\u00f9 a rischio \u00e8 quella compresa tra i 5 e i 17 anni. In gran parte dei casi i bambini e i ragazzi stavano giocando nei dintorni del loro rifugio mentre i genitori svolgevano le attivit\u00e0 domestiche.<\/p>\n<p>Grazie al finanziamento <a href=\"https:\/\/www.ottopermillevaldese.org\/\">dell\u2019Otto per Mille della Chiesa Valdese<\/a>, MOAS Italia, in collaborazione con il partner <a href=\"https:\/\/www.helvetas.org\/en\/bangladesh\">Helvetas<\/a>, sta realizzando in Bangladesh un progetto di formazione per la sicurezza e il salvataggio in acqua destinato a 700 volontari, 200 appartenenti alla comunit\u00e0 bengalese ospitante e 500 appartenenti alla comunit\u00e0 dei rifugiati Rohingya. Il corso fornisce ai partecipanti elementi di base sui rischi legati alle alluvioni, la capacit\u00e0 di identificare le aree a maggior rischio e di operare in sicurezza nella prevenzione e nel salvataggio delle persone a rischio di annegamento.<\/p>\n<p>Al termine del corso saranno forniti ai partecipanti 700 throwbags e 28 bottle rings, dispositivi di salvataggio che vengono impiegati sia durante il training che successivamente in caso di necessit\u00e0. \u00a0La produzione dei dispositivi di salvataggio viene realizzata a Cox\u2019s Bazar all\u2019interno del laboratorio che abbiamo appositamente adibito, e dove sarte e sarti locali, molti dei quali avevano perso il lavoro a causa della pandemia di Covid-19, utilizzando materiali prodotti in loco, possono continuare a sostenere le proprie famiglie.<\/p>\n<p>Nonostante le sfide poste dalla diffusione della pandemia e le difficolt\u00e0 causate dalle restrizioni introdotte per attenuare la corsa del virus, il nostro impegno sul campo continua a essere costante. In questo periodo cos\u00ec difficile, a seguito delle alluvioni che hanno colpito il Paese nel 2020, grazie alla cooperazione con il nostro partner, e con il prezioso sostegno del fondo dell\u2019Otto per Mille dalla Chiesa Valdese, possiamo fare la differenza e salvare la vita delle persone pi\u00f9 bisognose.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In Bangladesh, nei campi profughi dove vivono i rifugiati Rohingya fuggiti dalle torture e dalle violenze perpetrate in Myanmar, tra il 2019 e il 2020 &#8230; <a title=\"L\u2019Otto per Mille della Chiesa Valdese e MOAS Italia in Bangladesh\" class=\"read-more\" href=\"https:\/\/www.moas.eu\/it\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\/\" aria-label=\"Per saperne di pi\u00f9 su L\u2019Otto per Mille della Chiesa Valdese e MOAS Italia in Bangladesh\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":49302,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"nf_dc_page":"","footnotes":""},"categories":[14,19],"tags":[27,72,73,74,29,75,76,77],"class_list":["post-49300","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-blog-it","tag-bangladesh","tag-chiesa-valdese","tag-cicloni","tag-cox-bazar","tag-moas","tag-monsoni","tag-rifugiati","tag-rohingya","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019Otto per Mille della Chiesa Valdese e MOAS Italia in Bangladesh - MOAS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.moas.eu\/it\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019Otto per Mille della Chiesa Valdese e MOAS Italia in Bangladesh - MOAS\" \/>\n<meta property=\"og:description\" content=\"In Bangladesh, nei campi profughi dove vivono i rifugiati Rohingya fuggiti dalle torture e dalle violenze perpetrate in Myanmar, tra il 2019 e il 2020 ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.moas.eu\/it\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\/\" \/>\n<meta property=\"og:site_name\" content=\"MOAS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/migrantoffshoreaidstation\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-28T13:19:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-20T09:09:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Water-sources-in-the-camps-scaled-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christina Lejman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@moas_eu\" \/>\n<meta name=\"twitter:site\" content=\"@moas_eu\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christina Lejman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\\\/\"},\"author\":{\"name\":\"Christina Lejman\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/person\\\/be1af883120febb082823c3c74304c69\"},\"headline\":\"L\u2019Otto per Mille della Chiesa Valdese e MOAS Italia in Bangladesh\",\"datePublished\":\"2021-02-28T13:19:44+00:00\",\"dateModified\":\"2022-10-20T09:09:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\\\/\"},\"wordCount\":418,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Water-sources-in-the-camps-scaled-2.jpg\",\"keywords\":[\"Bangladesh\",\"chiesa valdese\",\"cicloni\",\"cox bazar\",\"moas\",\"monsoni\",\"rifugiati\",\"Rohingya\"],\"articleSection\":[\"Blog\",\"Blog\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.moas.eu\\\/it\\\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\\\/\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\\\/\",\"name\":\"L\u2019Otto per Mille della Chiesa Valdese e MOAS Italia in Bangladesh - MOAS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Water-sources-in-the-camps-scaled-2.jpg\",\"datePublished\":\"2021-02-28T13:19:44+00:00\",\"dateModified\":\"2022-10-20T09:09:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.moas.eu\\\/it\\\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Water-sources-in-the-camps-scaled-2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Water-sources-in-the-camps-scaled-2.jpg\",\"width\":2560,\"height\":2560,\"caption\":\"Water-sources-in-the-camps\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019Otto per Mille della Chiesa Valdese e MOAS Italia in Bangladesh\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/\",\"name\":\"MOAS\",\"description\":\"MOAS\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.moas.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\",\"name\":\"MOAS\",\"alternateName\":\"Migrant Offshore Aid Station\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/moas-logo-oval.png\",\"contentUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/moas-logo-oval.png\",\"width\":793,\"height\":354,\"caption\":\"MOAS\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/migrantoffshoreaidstation\",\"https:\\\/\\\/x.com\\\/moas_eu\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/migrant-offshore-aid-station\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZHcDS7ePIBW66d3KvX2K0Q\",\"https:\\\/\\\/www.instagram.com\\\/moas_eu\\\/?hl=en\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/person\\\/be1af883120febb082823c3c74304c69\",\"name\":\"Christina Lejman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"caption\":\"Christina Lejman\"},\"url\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/author\\\/clejman\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019Otto per Mille della Chiesa Valdese e MOAS Italia in Bangladesh - MOAS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.moas.eu\/it\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\/","og_locale":"it_IT","og_type":"article","og_title":"L\u2019Otto per Mille della Chiesa Valdese e MOAS Italia in Bangladesh - MOAS","og_description":"In Bangladesh, nei campi profughi dove vivono i rifugiati Rohingya fuggiti dalle torture e dalle violenze perpetrate in Myanmar, tra il 2019 e il 2020 ... Read more","og_url":"https:\/\/www.moas.eu\/it\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\/","og_site_name":"MOAS","article_publisher":"https:\/\/www.facebook.com\/migrantoffshoreaidstation","article_published_time":"2021-02-28T13:19:44+00:00","article_modified_time":"2022-10-20T09:09:50+00:00","og_image":[{"width":2560,"height":2560,"url":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Water-sources-in-the-camps-scaled-2.jpg","type":"image\/jpeg"}],"author":"Christina Lejman","twitter_card":"summary_large_image","twitter_creator":"@moas_eu","twitter_site":"@moas_eu","twitter_misc":{"Scritto da":"Christina Lejman","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.moas.eu\/it\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\/#article","isPartOf":{"@id":"https:\/\/www.moas.eu\/it\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\/"},"author":{"name":"Christina Lejman","@id":"https:\/\/www.moas.eu\/#\/schema\/person\/be1af883120febb082823c3c74304c69"},"headline":"L\u2019Otto per Mille della Chiesa Valdese e MOAS Italia in Bangladesh","datePublished":"2021-02-28T13:19:44+00:00","dateModified":"2022-10-20T09:09:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.moas.eu\/it\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\/"},"wordCount":418,"commentCount":0,"publisher":{"@id":"https:\/\/www.moas.eu\/#organization"},"image":{"@id":"https:\/\/www.moas.eu\/it\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\/#primaryimage"},"thumbnailUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Water-sources-in-the-camps-scaled-2.jpg","keywords":["Bangladesh","chiesa valdese","cicloni","cox bazar","moas","monsoni","rifugiati","Rohingya"],"articleSection":["Blog","Blog"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.moas.eu\/it\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.moas.eu\/it\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\/","url":"https:\/\/www.moas.eu\/it\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\/","name":"L\u2019Otto per Mille della Chiesa Valdese e MOAS Italia in Bangladesh - MOAS","isPartOf":{"@id":"https:\/\/www.moas.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.moas.eu\/it\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\/#primaryimage"},"image":{"@id":"https:\/\/www.moas.eu\/it\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\/#primaryimage"},"thumbnailUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Water-sources-in-the-camps-scaled-2.jpg","datePublished":"2021-02-28T13:19:44+00:00","dateModified":"2022-10-20T09:09:50+00:00","breadcrumb":{"@id":"https:\/\/www.moas.eu\/it\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.moas.eu\/it\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.moas.eu\/it\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\/#primaryimage","url":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Water-sources-in-the-camps-scaled-2.jpg","contentUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Water-sources-in-the-camps-scaled-2.jpg","width":2560,"height":2560,"caption":"Water-sources-in-the-camps"},{"@type":"BreadcrumbList","@id":"https:\/\/www.moas.eu\/it\/lotto-per-mille-della-chiesa-valdese-e-moas-italia-in-bangladesh\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.moas.eu\/it\/"},{"@type":"ListItem","position":2,"name":"L\u2019Otto per Mille della Chiesa Valdese e MOAS Italia in Bangladesh"}]},{"@type":"WebSite","@id":"https:\/\/www.moas.eu\/#website","url":"https:\/\/www.moas.eu\/","name":"MOAS","description":"MOAS","publisher":{"@id":"https:\/\/www.moas.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.moas.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.moas.eu\/#organization","name":"MOAS","alternateName":"Migrant Offshore Aid Station","url":"https:\/\/www.moas.eu\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.moas.eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/moas-logo-oval.png","contentUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/moas-logo-oval.png","width":793,"height":354,"caption":"MOAS"},"image":{"@id":"https:\/\/www.moas.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/migrantoffshoreaidstation","https:\/\/x.com\/moas_eu","https:\/\/www.linkedin.com\/company\/migrant-offshore-aid-station","https:\/\/www.youtube.com\/channel\/UCZHcDS7ePIBW66d3KvX2K0Q","https:\/\/www.instagram.com\/moas_eu\/?hl=en"]},{"@type":"Person","@id":"https:\/\/www.moas.eu\/#\/schema\/person\/be1af883120febb082823c3c74304c69","name":"Christina Lejman","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","caption":"Christina Lejman"},"url":"https:\/\/www.moas.eu\/it\/author\/clejman\/"}]}},"_links":{"self":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/49300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/comments?post=49300"}],"version-history":[{"count":1,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/49300\/revisions"}],"predecessor-version":[{"id":49301,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/49300\/revisions\/49301"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/media\/49302"}],"wp:attachment":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/media?parent=49300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/categories?post=49300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/tags?post=49300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}