{"id":49173,"date":"2020-07-16T12:18:24","date_gmt":"2020-07-16T12:18:24","guid":{"rendered":"http:\/\/just2093.temp.domains\/~tqmoaseu\/raccogliere-fondi-senza-donare\/"},"modified":"2022-10-20T09:11:19","modified_gmt":"2022-10-20T09:11:19","slug":"raccogliere-fondi-senza-donare","status":"publish","type":"post","link":"https:\/\/www.moas.eu\/it\/raccogliere-fondi-senza-donare\/","title":{"rendered":"Raccogliere fondi senza donare"},"content":{"rendered":"<p>Molti di noi sono appassionati a cause politiche, umanitarie o ambientali e pronti a sostenere le organizzazioni e le Onlus che sentono pi\u00f9 vicine. Non tutti, pero\u2019, hanno i mezzi per poter contribuire economicamente, o magari desiderano integrare le donazioni con altre forme di sostegno. Non \u00e8 sempre facile contribuire ai progetti che si scelgono senza mettere mano al portafogli, ma questa settimana il team fundraising di MOAS ha stilato un piccolo elenco delle modalita\u2019 con cui la nostra comunit\u00e0 si attiva per supportare il lavoro della nostra organizzazione. Ci auguriamo che possiate trovare ispirazionecompiere un gesto significativo per la causa piu\u2019 vicina ai vostri cuori.<\/p>\n<p><strong>Volontariato \/ Offrire competenze<\/strong><\/p>\n<p>Il modo pi\u00f9 ovvio per collaborare con la onlus preferita senza spendere un centesimo \u00e8 donare il proprio tempo e le proprie competenze. La maggior parte delle ONG e delle organizzazioni benefiche ha una sezione volontari il cui contributo e\u2019 coordinato sulla base del tempo che si mette a disposizione, delle competenze che si possono offrire e i progetti verso i quali si \u00e8 meglio orientati.<\/p>\n<p><span style=\"color: #000000;\">Quando doni l tuo tempo a qualsiasi organizzazione sii chiaro circa ci\u00f2 che hai da offrire<\/span>: sei del posto e puoi prestare lavoro manuale? Hai una competenza tecnica specifica che puoi seguire da remoto, come la gestione della contabilit\u00e0, digital marketing, web design, organizzazione di eventi? Sei uno specialista sul campo, un esperto di logistica, un medico, un infermiere, ecc. che vuole viaggiare per fare volontariato sul campo? Sii chiaro e onesto quando ti proponi e tieni in conto che gli impegni di volontariato dovrebbero essere presi tanto seriamente quanto gli impegni di lavoro, poich\u00e9 le persone faranno affidamento su di te e sul tuo contributo.<\/p>\n<p><strong><em>Per fare volontariato con MOAS scrivici a <\/em><\/strong><a href=\"mailto:info@moas.eu\"><strong><em>info@moas.eu<\/em><\/strong><\/a><\/p>\n<figure id=\"attachment_35834\" aria-describedby=\"caption-attachment-35834\" style=\"width: 1014px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Volunteers.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-35834 size-large\" src=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Volunteers.jpg\" alt=\"Volunteers\" width=\"1024\" height=\"576\" \/><\/a><figcaption id=\"caption-attachment-35834\" class=\"wp-caption-text\"><em>\u00a0Un volontario MOAS EVS in uno stand a Valletta.\u00a0<\/em><\/figcaption><\/figure>\n<p><strong>Promozione \/ Advocacy<\/strong><\/p>\n<p>Non sottovalutare il potere della community online. Ogni organizzazione cerca di allargare il proprio raggio di azione e trovare nuovi sostenitori tramite i social media. Seguire pagine di organizzazioni come MOAS e condividere le loro petizioni di fundraising, il blog o gli aggiornamenti sulle operazioni pu\u00f2 aumentare enormemente il loro impatto, e farli conoscere a possibili nuovi donatori.<\/p>\n<p>Le organizzazioni benefiche si impegnano su cause specifiche (protezione dei bambini, diritti degli animali, questione dei rifugiati, etc.) e quanto pi\u00f9 il loro messaggio pu\u00f2 essere diffuso tanto maggiori saranno i risultati. Un semplice gesto come quello di condividere un articolo diventa un vero atto di solidariet\u00e0.<\/p>\n<p><strong><em>Per seguire I contenuti di MOAS visita le nostre pagine <\/em><\/strong><a href=\"https:\/\/www.facebook.com\/migrantoffshoreaidstation\/\"><strong><em>Facebook<\/em><\/strong><\/a><strong><em>, <\/em><\/strong><a href=\"https:\/\/twitter.com\/moas_it\"><strong><em>Twitter<\/em><\/strong><\/a><strong><em>, <\/em><\/strong><a href=\"https:\/\/www.instagram.com\/moas_eu\/\"><strong><em>Instagram<\/em><\/strong><\/a><strong><em>, <\/em><\/strong><a href=\"https:\/\/mt.linkedin.com\/company\/migrant-offshore-aid-station\"><strong><em>LinkedIn<\/em><\/strong><\/a><strong><em> e iscriviti alla nostra newsletter.<\/em><\/strong><\/p>\n<p><strong>Raccolta fondi nelle comunit\u00e0 \/ trovare<\/strong> <strong>ponsorizzazioni<\/strong><\/p>\n<p>Anche se non ti trovi nella posizione di poter donare, potrebbero esserci persone nella tua comunit\u00e0 che lo sono! Raccolte fondi come vendita di dolci, feste di compleanno, giornate informali al lavoro e mercatini dell\u2019usato sono un ottimo modo non solo per raccogliere denaro per l\u2019organizzazione che hai scelto, ma anche per sensibilizzare sulla loro causa. Trovare sponsorizzazioni gare sportivecamminate o maratone sponsorizzate etc.) \u00e8 un altro buon sistema per raccogliere fondi senza metter mano al portafoglio.<\/p>\n<p><strong><em>MOAS ha creato la sua <\/em><\/strong><a href=\"https:\/\/www.moasfundraising.com\/\"><strong><em>piattaforma di raccolta fondi<\/em><\/strong><\/a><strong><em> per aiutarti a creare questo genere di campagne e condividerle con i tuoi amici e parenti. <\/em><\/strong>In ogni caso, se la tua organizzazione benefica non ha la sua pagina peer-to-peer, puoi trovarne molte altre, come JustGiving, GivenGain, GoFundMe.<\/p>\n<figure id=\"attachment_35831\" aria-describedby=\"caption-attachment-35831\" style=\"width: 464px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Campaigns.png\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-35831 size-full\" src=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Campaigns.png\" alt=\"Campaigns\" width=\"474\" height=\"622\" \/><\/a><figcaption id=\"caption-attachment-35831\" class=\"wp-caption-text\"><em>\u00a0Una recente campagna sulla piattaforma Fundraising di MOAS.\u00a0<\/em><\/figcaption><\/figure>\n<p><strong>Nomination (Premi\/chiesa\/eventi\/lavoro)<\/strong><\/p>\n<p>Ci sono numerose opportunit\u00e0 per candidare l\u2019organizzazione che hai scelto a premi e programmi che possano assicurarle un riconoscimento, un finanziamenti o notorieta\u2019. Alcuni datori di lavoro accettano suggerimenti da parte dei dipendenti per attivit\u00e0 di fundraising e sostegno a livello aziendale. Ci sono molti riconoscimenti con premi in denato per diverse categorie per le quali puoi candidare l\u2019organizzazione scelta. \u00a0Alcuni quotidiani, canali televisivi o stazioni radio lanciano campagne nel periodo natalizio a favore delle rganizzazioni umanitarie, che in questa occasione possono raccogliere anche milioni. Inoltre, molte chiese, gruppi religiosi o societ\u00e0 scelgono ogni anno alcune organizzazioni da sostenere. Informati e sicuramente troverai opportunit\u00e0 di candidare la tua organizzazione per alcuni ottimi programmi.<\/p>\n<p>MOAS ha vinto premi, \u00e8 stata nominata la migliore \u201cOrganizzazione di Natale\u201d dal quotidiano inglese <em>The Guardian<\/em> ed \u00e8 registrata per dozzine di programmi di donazione grazie alle nomination da parte della nostra preziosa comunit\u00e0 di sostenitori!<\/p>\n<p><strong>Tasse<\/strong><\/p>\n<p>Molti Paesi offrono la possibilit\u00e0 di devolver parte delle tasse a organizzazioni registrate a livello locale o di partecipare a programmi che permettono di sostenere le onlus tramite finanziamenti pubblici. Contatta una sezione locale dell\u2019organizzazione di tuo interesse per capire come poter veicolare \u00a0contributi statali in suo favore senza costi a tuo carico.<\/p>\n<p>MOAS partecipa in Italia al programma <a href=\"https:\/\/www.moas.eu\/it\/5x1000\/\">Cinque per Mille<\/a> , inoltre ha regime fiscale negli Stati Uniti, Regno Unito, Germania e Malta.<\/p>\n<figure id=\"attachment_35840\" aria-describedby=\"caption-attachment-35840\" style=\"width: 766px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/5x1000-final.png\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-35840 size-full\" src=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/5x1000-final.png\" alt=\"5\u00d71000 final\" width=\"776\" height=\"308\" \/><\/a><figcaption id=\"caption-attachment-35840\" class=\"wp-caption-text\"><em>\u00a0Ecco come donare il 5&#215;1000 a MOAS.\u00a0<\/em><\/figcaption><\/figure>\n<p><strong>Donazioni al checkout \/ Punti Fedelt\u00e0<\/strong><\/p>\n<p>Molte grandi aziende come Amazon o Target usano un sistema durante il checkout online che permette di selezionare un\u2019organizzazione benefica a cui devolvere una donazione tramite il tuo ordine. Molti di questi programmi non aggiungono costi extra, ma le aziende li usano per dirigere il flusso di denaro che ricevono come una percentuale sulle vendite.<\/p>\n<p>Ci sono anche diversi negozi e operatori che permettono di convertire i punti fedelt\u00e0 o le miglia accumulate in donazioni per beneficienza. Informati su questo servizio quando ti registri per un programma di fedelt\u00e0. In particolare, le miglia possono essere usate non solo per essere convertite in donazioni in denaro, ma anche per finaziare i viaggi degli operatori umanitari dentro e fuori zone di crisi.<\/p>\n<p><strong>Lasciti testamentari<\/strong><\/p>\n<p>Se in questo momento non sei in grado di fare una donazione, ma pensi di voler lasciare qualcosa alla tua onlus preferita quando non ci sarai piu\u2019, allora il lascito testamentario potrebbe fare per te. Consulta un notaio ed informati sulle modalita\u2019 per capire come funziona e leggi la <a href=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2019\/05\/your-guide-to-leaving-a-gift-in-your-will-to-moas.pdf\">Guida MOAS per principianti per i lasciti testamentari<\/a>. Per maggiori informazioni contattaci a <a href=\"mailto:info@moas.eu\">info@moas.eu<\/a><\/p>\n<p><strong>App\/Browser<\/strong><\/p>\n<p>Molti giochi, app e browser devolvono parte dei ricavi pubblicitari ad organizzazioni benefiche. Alcune di queste hanno creato i loro giochi o app nei quali e\u2019 sufficiente giocare per generare fondi. Puoi rispondere a <a href=\"https:\/\/freerice.com\/categories\/english-vocabulary\">quiz e domande per donare riso al WFP<\/a>, usare un <a href=\"https:\/\/tab.gladly.io\/\">browser speciale<\/a> o motore di ricerca per donare ogni volta che lo utilizzi, devolvere le tue miglia di esercizio, regalare <a href=\"https:\/\/www.makeuseof.com\/tag\/donate-charity-browsing-web-playing-games\/\">denaro ogni volta che posticipi la sveglia<\/a> e molto altro ancora. Tutti questi meccanismi funzionano in maniera simile: pi\u00f9 si utilizza l\u2019app\/sito pi\u00f9 ricavi vengono generati e trasformati in donazioni per la causa. <a href=\"https:\/\/www.hongkiat.com\/blog\/contribute-charities-without-spending\/\">Guarda qui per alcune idee<\/a>.<\/p>\n<p>Ci sono anche altri modi per dare online un contributo alla causa che ci interessa. Molti giochi e applicazioni sono ideati per raccogliere informazioni importanti per le organizzazioni di tutto il mondo. Ad esempio, puoi cercare app e giochi che aiutano la <a href=\"https:\/\/www.ironsrc.com\/blog\/mobile-games-charity-giving-tuesday\/\">ricerca per la cura dell\u2019Alzheimer<\/a>, curano la schizofrenia, fanno ricerca sul daltonismo e tanto altro.<\/p>\n<figure id=\"attachment_35704\" aria-describedby=\"caption-attachment-35704\" style=\"width: 758px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Masks-box-3-WM.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-35704 size-large\" src=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Masks-box-3-WM-768x1024.jpg\" alt=\"Masks box 3 WM\" width=\"768\" height=\"1024\" \/><\/a><figcaption id=\"caption-attachment-35704\" class=\"wp-caption-text\"><em>Mascherine realizzate dai volontari MOAS.\u00a0<\/em><\/figcaption><\/figure>\n<p><strong>Conclusioni<\/strong><\/p>\n<p>Non importa in che modo scegli di supportare le onlue e le tue cause preferite, ma assicurati di farlo con costanza e passione. MOAS \u00e8 principalmente sostenuto da donazioni private, ma siamo cresciuti anche grazie al sostegno forte di una comunit\u00e0 globale che raccoglie fondi, \u00e8 attiva, propone e partecipa per conto nostro. Non saremmo l\u2019organizzazione che siamo se i nostri sostenitori non avessero trovato modi creativi e fuori dagli schemi per diffondere il messaggio e il brand di MOAS.<\/p>\n<p>Se tutto questo ti sembra interessante, ma preferisci donare direttamente ti basta cliccare su <a href=\"https:\/\/www.moas.eu\/it\/donate\/\">https:\/\/www.moas.eu\/it\/donate\/<\/a>.<\/p>\n<p>Contiamo sulla tua generosita\u2019!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Molti di noi sono appassionati a cause politiche, umanitarie o ambientali e pronti a sostenere le organizzazioni e le Onlus che sentono pi\u00f9 vicine. Non &#8230; <a title=\"Raccogliere fondi senza donare\" class=\"read-more\" href=\"https:\/\/www.moas.eu\/it\/raccogliere-fondi-senza-donare\/\" aria-label=\"Per saperne di pi\u00f9 su Raccogliere fondi senza donare\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":48101,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"nf_dc_page":"","footnotes":""},"categories":[14,19],"tags":[],"class_list":["post-49173","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-blog-it","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","resize-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Raccogliere fondi senza donare - MOAS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.moas.eu\/it\/raccogliere-fondi-senza-donare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Raccogliere fondi senza donare - MOAS\" \/>\n<meta property=\"og:description\" content=\"Molti di noi sono appassionati a cause politiche, umanitarie o ambientali e pronti a sostenere le organizzazioni e le Onlus che sentono pi\u00f9 vicine. Non ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.moas.eu\/it\/raccogliere-fondi-senza-donare\/\" \/>\n<meta property=\"og:site_name\" content=\"MOAS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/migrantoffshoreaidstation\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-16T12:18:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-20T09:11:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Volunteers.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christina Lejman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@moas_eu\" \/>\n<meta name=\"twitter:site\" content=\"@moas_eu\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christina Lejman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/raccogliere-fondi-senza-donare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/raccogliere-fondi-senza-donare\\\/\"},\"author\":{\"name\":\"Christina Lejman\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/person\\\/be1af883120febb082823c3c74304c69\"},\"headline\":\"Raccogliere fondi senza donare\",\"datePublished\":\"2020-07-16T12:18:24+00:00\",\"dateModified\":\"2022-10-20T09:11:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/raccogliere-fondi-senza-donare\\\/\"},\"wordCount\":1298,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/raccogliere-fondi-senza-donare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Volunteers.jpg\",\"articleSection\":[\"Blog\",\"Blog\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.moas.eu\\\/it\\\/raccogliere-fondi-senza-donare\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/raccogliere-fondi-senza-donare\\\/\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/raccogliere-fondi-senza-donare\\\/\",\"name\":\"Raccogliere fondi senza donare - MOAS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/raccogliere-fondi-senza-donare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/raccogliere-fondi-senza-donare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Volunteers.jpg\",\"datePublished\":\"2020-07-16T12:18:24+00:00\",\"dateModified\":\"2022-10-20T09:11:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/raccogliere-fondi-senza-donare\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.moas.eu\\\/it\\\/raccogliere-fondi-senza-donare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/raccogliere-fondi-senza-donare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Volunteers.jpg\",\"contentUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Volunteers.jpg\",\"width\":1024,\"height\":576,\"caption\":\"Volunteers\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/raccogliere-fondi-senza-donare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Raccogliere fondi senza donare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/\",\"name\":\"MOAS\",\"description\":\"MOAS\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.moas.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\",\"name\":\"MOAS\",\"alternateName\":\"Migrant Offshore Aid Station\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/moas-logo-oval.png\",\"contentUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/moas-logo-oval.png\",\"width\":793,\"height\":354,\"caption\":\"MOAS\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/migrantoffshoreaidstation\",\"https:\\\/\\\/x.com\\\/moas_eu\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/migrant-offshore-aid-station\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZHcDS7ePIBW66d3KvX2K0Q\",\"https:\\\/\\\/www.instagram.com\\\/moas_eu\\\/?hl=en\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/person\\\/be1af883120febb082823c3c74304c69\",\"name\":\"Christina Lejman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"caption\":\"Christina Lejman\"},\"url\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/author\\\/clejman\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Raccogliere fondi senza donare - MOAS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.moas.eu\/it\/raccogliere-fondi-senza-donare\/","og_locale":"it_IT","og_type":"article","og_title":"Raccogliere fondi senza donare - MOAS","og_description":"Molti di noi sono appassionati a cause politiche, umanitarie o ambientali e pronti a sostenere le organizzazioni e le Onlus che sentono pi\u00f9 vicine. Non ... Read more","og_url":"https:\/\/www.moas.eu\/it\/raccogliere-fondi-senza-donare\/","og_site_name":"MOAS","article_publisher":"https:\/\/www.facebook.com\/migrantoffshoreaidstation","article_published_time":"2020-07-16T12:18:24+00:00","article_modified_time":"2022-10-20T09:11:19+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Volunteers.jpg","type":"image\/jpeg"}],"author":"Christina Lejman","twitter_card":"summary_large_image","twitter_creator":"@moas_eu","twitter_site":"@moas_eu","twitter_misc":{"Scritto da":"Christina Lejman","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.moas.eu\/it\/raccogliere-fondi-senza-donare\/#article","isPartOf":{"@id":"https:\/\/www.moas.eu\/it\/raccogliere-fondi-senza-donare\/"},"author":{"name":"Christina Lejman","@id":"https:\/\/www.moas.eu\/#\/schema\/person\/be1af883120febb082823c3c74304c69"},"headline":"Raccogliere fondi senza donare","datePublished":"2020-07-16T12:18:24+00:00","dateModified":"2022-10-20T09:11:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.moas.eu\/it\/raccogliere-fondi-senza-donare\/"},"wordCount":1298,"commentCount":0,"publisher":{"@id":"https:\/\/www.moas.eu\/#organization"},"image":{"@id":"https:\/\/www.moas.eu\/it\/raccogliere-fondi-senza-donare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Volunteers.jpg","articleSection":["Blog","Blog"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.moas.eu\/it\/raccogliere-fondi-senza-donare\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.moas.eu\/it\/raccogliere-fondi-senza-donare\/","url":"https:\/\/www.moas.eu\/it\/raccogliere-fondi-senza-donare\/","name":"Raccogliere fondi senza donare - MOAS","isPartOf":{"@id":"https:\/\/www.moas.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.moas.eu\/it\/raccogliere-fondi-senza-donare\/#primaryimage"},"image":{"@id":"https:\/\/www.moas.eu\/it\/raccogliere-fondi-senza-donare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Volunteers.jpg","datePublished":"2020-07-16T12:18:24+00:00","dateModified":"2022-10-20T09:11:19+00:00","breadcrumb":{"@id":"https:\/\/www.moas.eu\/it\/raccogliere-fondi-senza-donare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.moas.eu\/it\/raccogliere-fondi-senza-donare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.moas.eu\/it\/raccogliere-fondi-senza-donare\/#primaryimage","url":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Volunteers.jpg","contentUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/Volunteers.jpg","width":1024,"height":576,"caption":"Volunteers"},{"@type":"BreadcrumbList","@id":"https:\/\/www.moas.eu\/it\/raccogliere-fondi-senza-donare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.moas.eu\/it\/"},{"@type":"ListItem","position":2,"name":"Raccogliere fondi senza donare"}]},{"@type":"WebSite","@id":"https:\/\/www.moas.eu\/#website","url":"https:\/\/www.moas.eu\/","name":"MOAS","description":"MOAS","publisher":{"@id":"https:\/\/www.moas.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.moas.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.moas.eu\/#organization","name":"MOAS","alternateName":"Migrant Offshore Aid Station","url":"https:\/\/www.moas.eu\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.moas.eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/moas-logo-oval.png","contentUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/moas-logo-oval.png","width":793,"height":354,"caption":"MOAS"},"image":{"@id":"https:\/\/www.moas.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/migrantoffshoreaidstation","https:\/\/x.com\/moas_eu","https:\/\/www.linkedin.com\/company\/migrant-offshore-aid-station","https:\/\/www.youtube.com\/channel\/UCZHcDS7ePIBW66d3KvX2K0Q","https:\/\/www.instagram.com\/moas_eu\/?hl=en"]},{"@type":"Person","@id":"https:\/\/www.moas.eu\/#\/schema\/person\/be1af883120febb082823c3c74304c69","name":"Christina Lejman","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","caption":"Christina Lejman"},"url":"https:\/\/www.moas.eu\/it\/author\/clejman\/"}]}},"_links":{"self":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/49173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/comments?post=49173"}],"version-history":[{"count":1,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/49173\/revisions"}],"predecessor-version":[{"id":49174,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/49173\/revisions\/49174"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/media\/48101"}],"wp:attachment":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/media?parent=49173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/categories?post=49173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/tags?post=49173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}