{"id":49171,"date":"2020-07-14T08:11:11","date_gmt":"2020-07-14T08:11:11","guid":{"rendered":"http:\/\/just2093.temp.domains\/~tqmoaseu\/corridoi-umanitari\/"},"modified":"2022-10-20T09:11:20","modified_gmt":"2022-10-20T09:11:20","slug":"corridoi-umanitari","status":"publish","type":"post","link":"https:\/\/www.moas.eu\/it\/corridoi-umanitari\/","title":{"rendered":"Corridoi umanitari"},"content":{"rendered":"<p><a href=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/human-corridors-blog-1.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-large wp-image-35815\" src=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/human-corridors-blog-1-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><em><strong>\u201cI corridoi umanitari sono un messaggio all\u2019Europa per ricordarle che costruire muri non \u00e8 la soluzione alla crisi migratoria.\u201d<\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.mediterraneanhope.com\/wp-content\/uploads\/2018\/03\/Executive-Summary-Humanitarian-Corridors.pdf\">Paolo Gentiloni<\/a>, Ministro degli Affari Esteri, in occasione dell\u2019arrivo di un gruppo di rifugiati a Fiumicino il 29 febbraio 2016<\/p>\n<p style=\"text-align: left;\">\nMOAS, avendo fatto diretta esperienza dei terribili viaggi migratori che persone disperate intraprendono ogni giorno per fuggire da povert\u00e0, conflitti e altre difficolt\u00e0, \u00e8 fortemente convinta della necessit\u00e0 di canali migratori alternativi sicuri e legali. Per questo motivo abbiamo lanciato un appello per l\u2019adozione di vie sicure e legali in tutto il mondo per impedire che altre persone migranti cadano nelle mani di trafficanti di esseri umani o che intraprendano pericolosi viaggi migratori. Questa settimana approfondiamo i corridoi umanitari e perch\u00e9 potrebbero rappresentare una valida alternativa allo status-quo.<\/p>\n<p><strong>Cosa sono i Corridoi Umanitari?<\/strong><\/p>\n<p>I corridoi umanitari sono vie sicure e legali realizzate dalla cooperazione tra le organizzazioni della societ\u00e0 civile e del Paese ospitante. Uno degli obiettivi principali dei corridoi umanitari e\u2019 quello di evitare che le persone migranti percorrano le pericolose rotte del Mediterraneo, dove dal 2014 a oggi hanno perso la vita <a href=\"https:\/\/migration.iom.int\/europe?type=missing\">quasi 20.000 persone<\/a>. I corridoi umanitari, fornendo un visto umanitario per l\u2019accesso legale, riducono il rischio di sfruttamento dei migranti pi\u00f9 vulnerabili da parte dei trafficanti di esseri umani.<\/p>\n<p>Un approccio strutturato e non emergenziale \u00e8 anche molto pi\u00f9 economico sia per la comunit\u00e0 internazionale che per i Paesi ospitanti, attraverso il coordinamento interstatale e la semplificazione delle procedure.<\/p>\n<p>La concessione dei visti umanitari migliora il monitoraggio e la gestione del fenomeno prima dell\u2019arrivo sulle coste europee. La capacit\u00e0 di monitorare anticipatamente i casi, i controlli di sicurezza e le procedure di asilo aumenta la sicurezza dei Paesi ospitanti e garantisce una migliore preparazione per le attivit\u00e0 di integrazione.<\/p>\n<p><strong>Come funzionano i corridoi umanitari?<\/strong><\/p>\n<p>I corridoi umanitari sono frutto di un Protocollo d&#8217;intesa tra la <a href=\"https:\/\/www.santegidio.org\/pageID\/30112\/langID\/it\/CORRIDOI-UMANITARI.html\">Comunit\u00e0 di Sant&#8217;Egidio<\/a>, la Federazione delle Chiese Evangeliche in Italia, la Tavola Valdese, la Cei-Caritas e il governo italiano. Le associazioni inviano sul posto dei volontari, che prendono contatti diretti con i rifugiati nei paesi interessati dal progetto, predispongono una lista di potenziali beneficiari da trasmettere alle autorit\u00e0 consolari italiane, che dopo il controllo da parte del Ministero dell&#8217;Interno rilasciano dei visti umanitari con Validit\u00e0 Territoriale Limitata, validi dunque solo per l&#8217;Italia. Una volta arrivati in Italia legalmente e in sicurezza, i profughi potranno presentare domanda di asilo.<\/p>\n<p>Per poter rilasciare visti umanitari, le organizzazioni coinvolte creano dapprima una lista di potenziali beneficiari tramite partnerships (per esempio ONG o chiese e associazioni locali) nei Paesi coinvolti nel progetto di corridoio umanitario. La lista dei potenziali beneficiari di visti umanitari viene poi inviata alle autorit\u00e0 consolari italiane dei Paesi coinvolti, cos\u00ec da essere revisionata dal Ministero degli Interni italiano. <a href=\"https:\/\/www.mediterraneanhope.com\/wp-content\/uploads\/2018\/03\/Executive-Summary-Humanitarian-Corridors.pdf\">I visti umanitari vengono infine rilasciati dai consolati italiani<\/a> secondo l\u2019articolo 25 del Regolamento CE N\u00b0 810\/2009 del 13 luglio 2009, che permette a uno Stato membro di rilasciare visti per ragioni umanitarie, per ragioni di interesse nazionale o per obblighi internazionali. Il rilascio di visti umanitari segue poi un processo molto pi\u00f9 severo e formalizzato rispetto al sistema attuale.<\/p>\n<p>Inoltre, le organizzazioni coinvolte in questa iniziativa <a href=\"https:\/\/www.mediterraneanhope.com\/wp-content\/uploads\/2018\/03\/Executive-Summary-Humanitarian-Corridors.pdf\">si impegnano a fornire assistenza legale<\/a> a coloro i quali viene concesso il visto umanitario, oltre ad alloggio e accoglienza per un ragionevole periodo di tempo. Viene anche offerto loro sostegno economico per il trasferimento e sostegno per la loro integrazione in Italia, come opportunit\u00e0 di imparare l\u2019italiano o assistenza nella ricerca di impiego. Una volta che le persone sono arrivate in Italia tramite questa via sicura e legale, possono procedere con la loro richiesta di asilo.<\/p>\n<p style=\"text-align: center;\"><em><strong>\u201cUn buon esempio di ci\u00f2 che l\u2019Europa pu\u00f2 fare per aiutare i migranti e per gestire gli attuali flussi di rifugiati.\u201d<\/strong><\/em><br \/>\n<a href=\"https:\/\/www.mediterraneanhope.com\/wp-content\/uploads\/2018\/03\/Executive-Summary-Humanitarian-Corridors.pdf\">Nils Mui\u017enieks<\/a>, Commissario per i Diritti Umani del Consiglio d\u2019Europa, 2 marzo 2016<\/p>\n<p><strong>Come sono finanziati i corridoi umanitari?<\/strong><\/p>\n<p>Il progetto \u00e8 autofinanziato dalle organizzazioni che promuovono i corridoi e non dallo Stato. Il vicepresidente del Parlamento Europeo ha ribadito che una sfida chiave di questa iniziativa \u00e8 quella di <a href=\"https:\/\/www.ecre.org\/humanitarian-corridors-an-italian-model-for-the-european-union\/\">includere i finanziamenti per i Corridoi Umanitari Europei nel quadro finanziario dell\u2019UE<\/a> per il 2021-27, poich\u00e9 un sostegno finanziario significativamente pi\u00f9 grande porterebbe a un sistema pi\u00f9 forte ed efficace in tutta Europa.<\/p>\n<p><a href=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/human-corridors-blog-2.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-large wp-image-35818\" src=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/human-corridors-blog-2.jpg\" alt=\"\" width=\"1024\" height=\"683\" \/><\/a><\/p>\n<p><strong>Conclusioni<\/strong><\/p>\n<p>I corridoi umanitari sono dunque un modello facilmente replicabile in tutta Europa, non solamente da associazioni o individui privati. Tuttavia, se si vuole seriamente ridurre la migrazione irregolare attraverso canali legali \u00e8 allora necessario che ci sia una risposta europea unita. \u00c8 per questo motivo che MOAS auspica che tutti i Paesi europei concretizzino il loro impegno per incrementare le vie migratorie sicure e legali, condividendo la responsabilit\u00e0 che tutti abbiamo nei confronti delle persone migranti.<\/p>\n<p>Per sostenere la nostra campagna #VieSicureELegali firma il nostro appello:\u00a0<a href=\"https:\/\/www.moas.eu\/it\/viesicureelegali\/\">https:\/\/www.moas.eu\/it\/viesicureelegali\/<\/a><\/p>\n<p>Se sei interessato alle attivit\u00e0 MOAS e a quelle dei nostri partner seguici sui social, iscriviti alla nostra newsletter e condividi i nostri\u00a0contenuti. Puoi scriverci a info@moas.eu.<br \/>\nPer supportare le nostre\u00a0operazioni dona su\u00a0<a href=\"https:\/\/www.moas.eu\/it\/donate\/\">https:\/\/www.moas.eu\/it\/donate\/\u00a0<\/a>o scegli di devolvere il tuo 5\u00d71000 a MOAS\u00a0https:\/\/www.moas.eu\/it\/5\u00d71000\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cI corridoi umanitari sono un messaggio all\u2019Europa per ricordarle che costruire muri non \u00e8 la soluzione alla crisi migratoria.\u201d Paolo Gentiloni, Ministro degli Affari Esteri, &#8230; <a title=\"Corridoi umanitari\" class=\"read-more\" href=\"https:\/\/www.moas.eu\/it\/corridoi-umanitari\/\" aria-label=\"Per saperne di pi\u00f9 su Corridoi umanitari\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":44945,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"nf_dc_page":"","footnotes":""},"categories":[14,19],"tags":[],"class_list":["post-49171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-blog-it","generate-columns","tablet-grid-50","mobile-grid-100","grid-parent","grid-33","resize-featured-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Corridoi umanitari - MOAS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.moas.eu\/it\/corridoi-umanitari\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corridoi umanitari - MOAS\" \/>\n<meta property=\"og:description\" content=\"\u201cI corridoi umanitari sono un messaggio all\u2019Europa per ricordarle che costruire muri non \u00e8 la soluzione alla crisi migratoria.\u201d Paolo Gentiloni, Ministro degli Affari Esteri, ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.moas.eu\/it\/corridoi-umanitari\/\" \/>\n<meta property=\"og:site_name\" content=\"MOAS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/migrantoffshoreaidstation\" \/>\n<meta property=\"article:published_time\" content=\"2020-07-14T08:11:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-20T09:11:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/human-corridors-blog-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Christina Lejman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@moas_eu\" \/>\n<meta name=\"twitter:site\" content=\"@moas_eu\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christina Lejman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/corridoi-umanitari\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/corridoi-umanitari\\\/\"},\"author\":{\"name\":\"Christina Lejman\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/person\\\/be1af883120febb082823c3c74304c69\"},\"headline\":\"Corridoi umanitari\",\"datePublished\":\"2020-07-14T08:11:11+00:00\",\"dateModified\":\"2022-10-20T09:11:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/corridoi-umanitari\\\/\"},\"wordCount\":853,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/corridoi-umanitari\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/human-corridors-blog-1.jpg\",\"articleSection\":[\"Blog\",\"Blog\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.moas.eu\\\/it\\\/corridoi-umanitari\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/corridoi-umanitari\\\/\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/corridoi-umanitari\\\/\",\"name\":\"Corridoi umanitari - MOAS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/corridoi-umanitari\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/corridoi-umanitari\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/human-corridors-blog-1.jpg\",\"datePublished\":\"2020-07-14T08:11:11+00:00\",\"dateModified\":\"2022-10-20T09:11:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/corridoi-umanitari\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.moas.eu\\\/it\\\/corridoi-umanitari\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/corridoi-umanitari\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/human-corridors-blog-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/human-corridors-blog-1.jpg\",\"width\":1280,\"height\":854,\"caption\":\"human corridors blog 1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/corridoi-umanitari\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Corridoi umanitari\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/\",\"name\":\"MOAS\",\"description\":\"MOAS\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.moas.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#organization\",\"name\":\"MOAS\",\"alternateName\":\"Migrant Offshore Aid Station\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/moas-logo-oval.png\",\"contentUrl\":\"https:\\\/\\\/www.moas.eu\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/moas-logo-oval.png\",\"width\":793,\"height\":354,\"caption\":\"MOAS\"},\"image\":{\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/migrantoffshoreaidstation\",\"https:\\\/\\\/x.com\\\/moas_eu\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/migrant-offshore-aid-station\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCZHcDS7ePIBW66d3KvX2K0Q\",\"https:\\\/\\\/www.instagram.com\\\/moas_eu\\\/?hl=en\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.moas.eu\\\/#\\\/schema\\\/person\\\/be1af883120febb082823c3c74304c69\",\"name\":\"Christina Lejman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g\",\"caption\":\"Christina Lejman\"},\"url\":\"https:\\\/\\\/www.moas.eu\\\/it\\\/author\\\/clejman\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Corridoi umanitari - MOAS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.moas.eu\/it\/corridoi-umanitari\/","og_locale":"it_IT","og_type":"article","og_title":"Corridoi umanitari - MOAS","og_description":"\u201cI corridoi umanitari sono un messaggio all\u2019Europa per ricordarle che costruire muri non \u00e8 la soluzione alla crisi migratoria.\u201d Paolo Gentiloni, Ministro degli Affari Esteri, ... Read more","og_url":"https:\/\/www.moas.eu\/it\/corridoi-umanitari\/","og_site_name":"MOAS","article_publisher":"https:\/\/www.facebook.com\/migrantoffshoreaidstation","article_published_time":"2020-07-14T08:11:11+00:00","article_modified_time":"2022-10-20T09:11:20+00:00","og_image":[{"width":1280,"height":854,"url":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/human-corridors-blog-1.jpg","type":"image\/jpeg"}],"author":"Christina Lejman","twitter_card":"summary_large_image","twitter_creator":"@moas_eu","twitter_site":"@moas_eu","twitter_misc":{"Scritto da":"Christina Lejman","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.moas.eu\/it\/corridoi-umanitari\/#article","isPartOf":{"@id":"https:\/\/www.moas.eu\/it\/corridoi-umanitari\/"},"author":{"name":"Christina Lejman","@id":"https:\/\/www.moas.eu\/#\/schema\/person\/be1af883120febb082823c3c74304c69"},"headline":"Corridoi umanitari","datePublished":"2020-07-14T08:11:11+00:00","dateModified":"2022-10-20T09:11:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.moas.eu\/it\/corridoi-umanitari\/"},"wordCount":853,"commentCount":0,"publisher":{"@id":"https:\/\/www.moas.eu\/#organization"},"image":{"@id":"https:\/\/www.moas.eu\/it\/corridoi-umanitari\/#primaryimage"},"thumbnailUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/human-corridors-blog-1.jpg","articleSection":["Blog","Blog"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.moas.eu\/it\/corridoi-umanitari\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.moas.eu\/it\/corridoi-umanitari\/","url":"https:\/\/www.moas.eu\/it\/corridoi-umanitari\/","name":"Corridoi umanitari - MOAS","isPartOf":{"@id":"https:\/\/www.moas.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.moas.eu\/it\/corridoi-umanitari\/#primaryimage"},"image":{"@id":"https:\/\/www.moas.eu\/it\/corridoi-umanitari\/#primaryimage"},"thumbnailUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/human-corridors-blog-1.jpg","datePublished":"2020-07-14T08:11:11+00:00","dateModified":"2022-10-20T09:11:20+00:00","breadcrumb":{"@id":"https:\/\/www.moas.eu\/it\/corridoi-umanitari\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.moas.eu\/it\/corridoi-umanitari\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.moas.eu\/it\/corridoi-umanitari\/#primaryimage","url":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/human-corridors-blog-1.jpg","contentUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/human-corridors-blog-1.jpg","width":1280,"height":854,"caption":"human corridors blog 1"},{"@type":"BreadcrumbList","@id":"https:\/\/www.moas.eu\/it\/corridoi-umanitari\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.moas.eu\/it\/"},{"@type":"ListItem","position":2,"name":"Corridoi umanitari"}]},{"@type":"WebSite","@id":"https:\/\/www.moas.eu\/#website","url":"https:\/\/www.moas.eu\/","name":"MOAS","description":"MOAS","publisher":{"@id":"https:\/\/www.moas.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.moas.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.moas.eu\/#organization","name":"MOAS","alternateName":"Migrant Offshore Aid Station","url":"https:\/\/www.moas.eu\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.moas.eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/moas-logo-oval.png","contentUrl":"https:\/\/www.moas.eu\/wp-content\/uploads\/2022\/07\/moas-logo-oval.png","width":793,"height":354,"caption":"MOAS"},"image":{"@id":"https:\/\/www.moas.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/migrantoffshoreaidstation","https:\/\/x.com\/moas_eu","https:\/\/www.linkedin.com\/company\/migrant-offshore-aid-station","https:\/\/www.youtube.com\/channel\/UCZHcDS7ePIBW66d3KvX2K0Q","https:\/\/www.instagram.com\/moas_eu\/?hl=en"]},{"@type":"Person","@id":"https:\/\/www.moas.eu\/#\/schema\/person\/be1af883120febb082823c3c74304c69","name":"Christina Lejman","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cdd044668e567142ac9e7c50898a3be21161f2aa3eeeaffd0fe110aa920a7b8a?s=96&d=mm&r=g","caption":"Christina Lejman"},"url":"https:\/\/www.moas.eu\/it\/author\/clejman\/"}]}},"_links":{"self":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/49171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/comments?post=49171"}],"version-history":[{"count":1,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/49171\/revisions"}],"predecessor-version":[{"id":49172,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/posts\/49171\/revisions\/49172"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/media\/44945"}],"wp:attachment":[{"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/media?parent=49171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/categories?post=49171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.moas.eu\/it\/wp-json\/wp\/v2\/tags?post=49171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}